{"id":83781,"date":"2021-12-20T13:56:17","date_gmt":"2021-12-20T17:56:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83781"},"modified":"2021-12-20T13:56:57","modified_gmt":"2021-12-20T17:56:57","slug":"pocas-lluvias-para-este-lunes-mientras-el-oleaje-retorna-a-la-normalidad","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/pocas-lluvias-para-este-lunes-mientras-el-oleaje-retorna-a-la-normalidad\/","title":{"rendered":"Pocas lluvias para este lunes, mientras el oleaje retorna a la normalidad"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"671\" height=\"434\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/clima-para-hoy.jpg\" alt=\"\" class=\"wp-image-83782\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/clima-para-hoy.jpg 671w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/clima-para-hoy-300x194.jpg 300w\" sizes=\"auto, (max-width: 671px) 100vw, 671px\" \/><figcaption>Sol para hoy y poca lluvia<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>OnametSanto Domingo, R.D.<\/strong> La\u00a0Oficina Nacional de Meteorolog\u00eda (Onamet) pronostica pocas lluvias para este lunes, debido a\u00a0un sistema de alta presi\u00f3n que se posiciona sobre el territorio dominicano.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una d\u00e9bil vaguada y los efectos del viento del este ocasionar\u00e1n algunos\u00a0<strong>nublados ocasionales en horas de la ma\u00f1ana con chubascos aislados\u00a0<\/strong>en algunos sectores de la regi\u00f3n norte, la zona fronteriza y la Cordillera Central.\u00a0 Sin embargo,<strong>\u00a0en las dem\u00e1s regiones se prev\u00e9 un clima soleado y de escasas lluvias.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Para el pr\u00f3ximo martes, la incidencia de una masa de aire con escaso contenido de humedad\u00a0 asociada un sistema de alta presi\u00f3n sobre nuestra \u00e1rea,\u00a0<strong>estar\u00e1 provocando condiciones soleadas sobre el pa\u00eds.\u00a0<\/strong>\u00a0No obstante, algunos chubascos d\u00e9biles podr\u00edan ocurrir en horas de la tarde debido a los efectos locales de calentamiento sobre puntos aislados de las regiones nordeste, el litoral costero sur y la Cordillera Central.\u00a0 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>OnametSanto Domingo, R.D. La\u00a0Oficina Nacional de Meteorolog\u00eda (Onamet) pronostica pocas lluvias para este lunes, debido a\u00a0un sistema de alta presi\u00f3n que se posiciona sobre el territorio dominicano.\u00a0 Una d\u00e9bil vaguada y los efectos del viento del este ocasionar\u00e1n algunos\u00a0nublados ocasionales en horas de la ma\u00f1ana con chubascos aislados\u00a0en algunos sectores de la regi\u00f3n norte, la zona fronteriza y la Cordillera Central.\u00a0 Sin embargo,\u00a0en las dem\u00e1s regiones se prev\u00e9 un clima soleado y de escasas lluvias. Para el pr\u00f3ximo martes, la incidencia de una masa de aire con escaso contenido de humedad\u00a0 asociada un sistema de alta presi\u00f3n sobre nuestra \u00e1rea,\u00a0estar\u00e1 provocando condiciones soleadas sobre el pa\u00eds.\u00a0\u00a0No obstante, algunos chubascos d\u00e9biles podr\u00edan ocurrir en horas de la tarde debido a los efectos locales de calentamiento sobre puntos aislados de las regiones nordeste, el litoral costero sur y la Cordillera Central.\u00a0<\/p>\n","protected":false},"author":12,"featured_media":83782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-83781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83781"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83781\/revisions"}],"predecessor-version":[{"id":83784,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83781\/revisions\/83784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83782"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}