{"id":83793,"date":"2021-12-21T13:30:16","date_gmt":"2021-12-21T17:30:16","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83793"},"modified":"2021-12-21T13:30:20","modified_gmt":"2021-12-21T17:30:20","slug":"procuraduria-vincula-a-aracelis-medina-otra-hermana-de-danilo-y-a-su-esposo-en-caso-pulpo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/procuraduria-vincula-a-aracelis-medina-otra-hermana-de-danilo-y-a-su-esposo-en-caso-pulpo\/","title":{"rendered":"Procuradur\u00eda vincula a Aracelis Medina, otra hermana de Danilo, y a su esposo en caso Pulpo"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/202112211713041.jpeg\" alt=\"\" class=\"wp-image-83794\" width=\"235\" height=\"121\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/202112211713041.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/202112211713041-300x155.jpeg 300w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La Procuradur\u00eda General de la Rep\u00fablica se\u00f1ala a otra hermana del expresidente Danilo Medina como parte del esquema de supuesta corrupci\u00f3n administrativa develada con el caso AntiPulpo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de Aracelis Medina S\u00e1nchez, quien durante los a\u00f1os que abarca la investigaci\u00f3n se desempe\u00f1\u00f3 como vicepresidenta del Banco de Reservas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esa entidad financiera fue usada para m\u00e1s del 95% de las operaciones il\u00edcitas del entramado, dice la Procuradur\u00eda en la acusaci\u00f3n formal del caso, depositada el pasado viernes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl tr\u00e1fico de influencia gestado desde las entra\u00f1as del poder como motor impulsor de las acciones delictivas de la organizaci\u00f3n\u201d, indica la acusaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y contin\u00faa: \u201cEn la materializaci\u00f3n de los actos de corrupci\u00f3n objeto de la presente acusaci\u00f3n tuvieron una participaci\u00f3n determinante los investigados&nbsp;<strong>Aracelis Medina S\u00e1nchez<\/strong>, vicepresidenta del Banco de Reservas, entidad utilizada como financiera particular de m\u00e1s del 95% de las operaciones il\u00edcitas del entramado\u201d, indica la acusaci\u00f3n formal depositada. Sin embargo, la se\u00f1ora no figura como imputada en el caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n vincula a Luis de Le\u00f3n, quien presidi\u00f3 la Empresa Distribuidora de Electricidad del Este (EdeEste), cu\u00f1ado del expresidente Danilo Medina (esposo de Magalys Medina S\u00e1nchez, en prisi\u00f3n domiciliaria por el caso).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la acusaci\u00f3n tambi\u00e9n se confirma la investigaci\u00f3n contra Luc\u00eda Medina S\u00e1nchez, otra hermana del exmandatario y quien se desempe\u00f1aba como diputada por San Juan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u2026precandidata a senadora por la misma demarcaci\u00f3n y presidenta de la Fundaci\u00f3n de Mujeres para el Desarrollo de San Juan (Fumudesju), anteriormente Asociaci\u00f3n de Mujeres para el Desarrollo de San Juan de la Maguana, inc. (Asodemusa), una ONG que obtuvo, por distracciones de fondos disfrazados de donaciones, la suma de unos setenta y ocho millones ciento diez mil pesos (RD$78,110,000.00), recursos en su mayor\u00eda utilizados en beneficios personales y financiamiento il\u00edcito de sus diferentes campa\u00f1as electorales\u201d, indica la acusaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Procuradur\u00eda General de la Rep\u00fablica se\u00f1ala a otra hermana del expresidente Danilo Medina como parte del esquema de supuesta corrupci\u00f3n administrativa develada con el caso AntiPulpo. Se trata de Aracelis Medina S\u00e1nchez, quien durante los a\u00f1os que abarca la investigaci\u00f3n se desempe\u00f1\u00f3 como vicepresidenta del Banco de Reservas. Esa entidad financiera fue usada para m\u00e1s del 95% de las operaciones il\u00edcitas del entramado, dice la Procuradur\u00eda en la acusaci\u00f3n formal del caso, depositada el pasado viernes. \u201cEl tr\u00e1fico de influencia gestado desde las entra\u00f1as del poder como motor impulsor de las acciones delictivas de la organizaci\u00f3n\u201d, indica la acusaci\u00f3n. Y contin\u00faa: \u201cEn la materializaci\u00f3n de los actos de corrupci\u00f3n objeto de la presente acusaci\u00f3n tuvieron una participaci\u00f3n determinante los investigados&nbsp;Aracelis Medina S\u00e1nchez, vicepresidenta del Banco de Reservas, entidad utilizada como financiera particular de m\u00e1s del 95% de las operaciones il\u00edcitas del entramado\u201d, indica la acusaci\u00f3n formal depositada. Sin embargo, la se\u00f1ora no figura como imputada en el caso. Tambi\u00e9n vincula a Luis de Le\u00f3n, quien presidi\u00f3 la Empresa Distribuidora de Electricidad del Este (EdeEste), cu\u00f1ado del expresidente Danilo Medina (esposo de Magalys Medina S\u00e1nchez, en prisi\u00f3n domiciliaria por el caso). Con la acusaci\u00f3n tambi\u00e9n se confirma la investigaci\u00f3n contra Luc\u00eda Medina S\u00e1nchez, otra hermana del exmandatario y quien se desempe\u00f1aba como diputada por San Juan. \u201c\u2026precandidata a senadora por la misma demarcaci\u00f3n y presidenta de la Fundaci\u00f3n de Mujeres para el Desarrollo de San Juan (Fumudesju), anteriormente Asociaci\u00f3n de Mujeres para el Desarrollo de San Juan de la Maguana, inc. (Asodemusa), una ONG que obtuvo, por distracciones de fondos disfrazados de donaciones, la suma de unos setenta y ocho millones ciento diez mil pesos (RD$78,110,000.00), recursos en su mayor\u00eda utilizados en beneficios personales y financiamiento il\u00edcito de sus diferentes campa\u00f1as electorales\u201d, indica la acusaci\u00f3n.<\/p>\n","protected":false},"author":9,"featured_media":83794,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-83793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83793"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83793\/revisions"}],"predecessor-version":[{"id":83795,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83793\/revisions\/83795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83794"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}