{"id":83838,"date":"2022-01-19T07:54:50","date_gmt":"2022-01-19T11:54:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83838"},"modified":"2022-01-19T07:54:52","modified_gmt":"2022-01-19T11:54:52","slug":"debaten-como-mitigar-la-inflacion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/debaten-como-mitigar-la-inflacion\/","title":{"rendered":"Debaten c\u00f3mo mitigar la inflaci\u00f3n"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/01\/a-1.jpg\" alt=\"\" class=\"wp-image-83839\" width=\"258\" height=\"133\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/01\/a-1.jpg 331w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/01\/a-1-300x155.jpg 300w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La Vicepresidenta Raquel Pe\u00f1a, encabez\u00f3 ayer una reuni\u00f3n con&nbsp; sectores del empresariado y representantes de supermercados para tratar el tema de la inflaci\u00f3n global por el desabastecimiento que podr\u00eda afectar los productos de importaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHoy hemos estado con los importadores, con los productores, con los comerciantes de los productos b\u00e1sicos, d\u00e1ndole seguimiento a este inicio de a\u00f1o y lo que estamos viendo que es una inflaci\u00f3n importada, ustedes ven lo que ha sucedido en los supermercados de los Estados Unidos por lo que tiene que ver con el reabastecimiento despu\u00e9s de navidades, tambi\u00e9n est\u00e1 el impacto por \u00f3micron y por eso nos reunimos para mantener una vigilancia a esa situaci\u00f3n\u201d, expres\u00f3 el ministro de Industria y Comercio, V\u00edctor Ito Bison\u00f3, quien fue el encargado de dar las conclusiones de la reuni\u00f3n a los miembros de la prensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Garantizar consumo<\/strong><br \/>Bison\u00f3 explic\u00f3 que lo principal es hacerle \u201cfrente a la situaci\u00f3n\u201d para garantizarles el consumo b\u00e1sico a todos los dominicanos a pesar de esa inflaci\u00f3n global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPreocupaci\u00f3n siempre hay, porque siempre hay que poner atenci\u00f3n, ahora lo que hay es ocupaci\u00f3n; nos estamos ocupando para que en cualquier novedad poder nosotros hacerle frente\u201d, a\u00f1adi\u00f3 el funcionario, quien agreg\u00f3 que en ese encuentro no hubo quejas por parte de los empresarios y comerciantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Abastecimiento<\/strong><br \/>Mientras el presidente del Consejo Nacional de la Empresa Privada (Conep), Pedro Brache, manifest\u00f3 que se encuentran trabajando para que en Rep\u00fablica Dominicana siempre haya abastecimiento de los productos b\u00e1sicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNuestra posici\u00f3n es clara, que en Rep\u00fablica Dominicana haya abastecimiento todo el tiempo, lo que no queremos es que falten las cosas y se est\u00e1 haciendo un trabajo muy intenso para que haya abastecimiento y en eso es lo que estamos trabajando\u201d, expres\u00f3 Brache.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reuni\u00f3n tuvo una duraci\u00f3n de alrededor una hora y media y se realiz\u00f3 a puertas cerradas en el Sal\u00f3n Verde del Palacio Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CLAVES<br \/>Factores.<\/strong><br \/>El presidente de la Federaci\u00f3n Dominicana de Comerciantes, Iv\u00e1n Garc\u00eda, indic\u00f3 que el costo del transporte mar\u00edtimo ha incidido notablemente en la inflaci\u00f3n. Tambi\u00e9n ha advertido que la eliminaci\u00f3n del subsidio a los combustibles provocar\u00eda aumento de precios en los productos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Vicepresidenta Raquel Pe\u00f1a, encabez\u00f3 ayer una reuni\u00f3n con&nbsp; sectores del empresariado y representantes de supermercados para tratar el tema de la inflaci\u00f3n global por el desabastecimiento que podr\u00eda afectar los productos de importaci\u00f3n. \u201cHoy hemos estado con los importadores, con los productores, con los comerciantes de los productos b\u00e1sicos, d\u00e1ndole seguimiento a este inicio de a\u00f1o y lo que estamos viendo que es una inflaci\u00f3n importada, ustedes ven lo que ha sucedido en los supermercados de los Estados Unidos por lo que tiene que ver con el reabastecimiento despu\u00e9s de navidades, tambi\u00e9n est\u00e1 el impacto por \u00f3micron y por eso nos reunimos para mantener una vigilancia a esa situaci\u00f3n\u201d, expres\u00f3 el ministro de Industria y Comercio, V\u00edctor Ito Bison\u00f3, quien fue el encargado de dar las conclusiones de la reuni\u00f3n a los miembros de la prensa. Garantizar consumoBison\u00f3 explic\u00f3 que lo principal es hacerle \u201cfrente a la situaci\u00f3n\u201d para garantizarles el consumo b\u00e1sico a todos los dominicanos a pesar de esa inflaci\u00f3n global. \u201cPreocupaci\u00f3n siempre hay, porque siempre hay que poner atenci\u00f3n, ahora lo que hay es ocupaci\u00f3n; nos estamos ocupando para que en cualquier novedad poder nosotros hacerle frente\u201d, a\u00f1adi\u00f3 el funcionario, quien agreg\u00f3 que en ese encuentro no hubo quejas por parte de los empresarios y comerciantes. AbastecimientoMientras el presidente del Consejo Nacional de la Empresa Privada (Conep), Pedro Brache, manifest\u00f3 que se encuentran trabajando para que en Rep\u00fablica Dominicana siempre haya abastecimiento de los productos b\u00e1sicos. \u201cNuestra posici\u00f3n es clara, que en Rep\u00fablica Dominicana haya abastecimiento todo el tiempo, lo que no queremos es que falten las cosas y se est\u00e1 haciendo un trabajo muy intenso para que haya abastecimiento y en eso es lo que estamos trabajando\u201d, expres\u00f3 Brache. La reuni\u00f3n tuvo una duraci\u00f3n de alrededor una hora y media y se realiz\u00f3 a puertas cerradas en el Sal\u00f3n Verde del Palacio Nacional. CLAVESFactores.El presidente de la Federaci\u00f3n Dominicana de Comerciantes, Iv\u00e1n Garc\u00eda, indic\u00f3 que el costo del transporte mar\u00edtimo ha incidido notablemente en la inflaci\u00f3n. Tambi\u00e9n ha advertido que la eliminaci\u00f3n del subsidio a los combustibles provocar\u00eda aumento de precios en los productos.<\/p>\n","protected":false},"author":9,"featured_media":83839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-83838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83838"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83838\/revisions"}],"predecessor-version":[{"id":83840,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83838\/revisions\/83840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83839"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}