{"id":8396,"date":"2014-09-11T16:27:17","date_gmt":"2014-09-11T20:27:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=8396"},"modified":"2014-09-11T13:29:38","modified_gmt":"2014-09-11T17:29:38","slug":"decenas-de-organizaciones-de-puerto-plata-respaldan-marcha-en-contra-privatizacion-servicio-agua-potable","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/decenas-de-organizaciones-de-puerto-plata-respaldan-marcha-en-contra-privatizacion-servicio-agua-potable\/","title":{"rendered":"Decenas de organizaciones de Puerto Plata respaldan marcha en contra privatizaci\u00f3n servicio agua potable"},"content":{"rendered":"<p><span style=\"color: #000000;\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/0_a_contra_coraapp_210_120.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8397 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/0_a_contra_coraapp_210_120.jpg\" alt=\"0_a_contra_coraapp_210_120\" width=\"210\" height=\"120\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/0_a_contra_coraapp_210_120.jpg 210w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/0_a_contra_coraapp_210_120-595x340.jpg 595w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a>PUERTO PLATA.- Centenares de ciudadanos a pie, en motocicletas y veh\u00edculos participaron la ma\u00f1ana de este pasado mi\u00e9rcoles en una tremenda marcha-caravana que fue convocada por el Comit\u00e9 Pro Puerto de Puerto Plata en contra de la privatizaci\u00f3n al servicio de agua potable en esta provincia.<\/span><!--more--><\/p>\n<p style=\"color: #000000;\">\u00a0La movilizaci\u00f3n de protesta parti\u00f3 desde la explanada frontal del estadio de b\u00e9isbol Jos\u00e9 Brise\u00f1o donde se aglomer\u00f3 una gran multitud de ciudadanos desde las 8:00 de la ma\u00f1ana quienes minutos m\u00e1s tardes entonaban consignas en contra de la CORAAPLATA y tomaron la avenida Luis Ginebra donde se desplazaba la marcha de protesta.<\/p>\n<p style=\"color: #000000;\">\nMuchos de los ciudadanos participantes expresaron que no van a permitir que un grupito de pol\u00edticos que tienen incidencia en la privatizaci\u00f3n del servicio de agua potable en Puerto Plata quieren seguir haci\u00e9ndose m\u00e1s ricos pintando como una chuler\u00eda el dudoso proceso de privatizar el \u00e1rea comercial de la Corporaci\u00f3n de Acueductos y Alcantarillados de Puerto Plata (CORAAPPLATA).<\/p>\n<p>En ese mismo tenor, el doctor Juan Payero Brisso quien pertenece al comit\u00e9 provincial de partido Alianza Pa\u00eds, dijo que \u201ccon esta demostraci\u00f3n de fuerza el pueblo de Puerto Plata se mantiene de manera firme en contra de esos negociantes de la pol\u00edtica y de la corruptela, que quieren aumentar sus riquezas a costa de la privatizaci\u00f3n del agua, por lo que toda la ciudadan\u00eda y a los sectores comunitarios est\u00e1n rechazando dicha acci\u00f3n\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.- Centenares de ciudadanos a pie, en motocicletas y veh\u00edculos participaron la ma\u00f1ana de este pasado mi\u00e9rcoles en una tremenda marcha-caravana que fue convocada por el Comit\u00e9 Pro Puerto de Puerto Plata en contra de la privatizaci\u00f3n al servicio de agua potable en esta provincia.<\/p>\n","protected":false},"author":3,"featured_media":8397,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-8396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=8396"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8396\/revisions"}],"predecessor-version":[{"id":8398,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8396\/revisions\/8398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/8397"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=8396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=8396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=8396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}