{"id":84310,"date":"2022-03-07T15:07:38","date_gmt":"2022-03-07T19:07:38","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=84310"},"modified":"2022-03-07T15:07:40","modified_gmt":"2022-03-07T19:07:40","slug":"carbohidratos-como-incluirlos-en-tu-alimentacion-diaria","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/carbohidratos-como-incluirlos-en-tu-alimentacion-diaria\/","title":{"rendered":"Carbohidratos: c\u00f3mo incluirlos en tu alimentaci\u00f3n diaria"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/03\/shutterstock1361138861-d0d1f410-focus-0-0-895-573.jpg\" alt=\"\" class=\"wp-image-84311\" width=\"232\" height=\"148\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/03\/shutterstock1361138861-d0d1f410-focus-0-0-895-573.jpg 895w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/03\/shutterstock1361138861-d0d1f410-focus-0-0-895-573-300x192.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/03\/shutterstock1361138861-d0d1f410-focus-0-0-895-573-768x492.jpg 768w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Un error a\u00fan arraigado en muchas personas es la eliminaci\u00f3n de&nbsp;<strong>carbohidratos<\/strong>&nbsp;en una dieta para perder peso. Esto no es verdad,&nbsp;<strong>no hay que eliminar los&nbsp;carbohidratos.<\/strong>&nbsp;Sus nutrientes constituyen la base de toda&nbsp;<strong>alimentaci\u00f3n<\/strong>&nbsp;equilibrada por lo que lo ideal es incluirlos de forma moderada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los&nbsp;<strong>carbohidratos<\/strong>&nbsp;son la principal fuente de energ\u00eda del cuerpo y deben cubrir entre el 50 y el 60% de las calor\u00edas totales de la dieta. Lo importante es la moderaci\u00f3n. No hay que atender solamente las cantidades, sino el tipo de&nbsp;<strong>alimentos<\/strong>&nbsp;que los acompa\u00f1an y c\u00f3mo se cocinan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por caso, una porci\u00f3n de papas fritas ser\u00e1 mucho m\u00e1s cal\u00f3rica que si la misma porci\u00f3n se prepara al horno o al vapor, sin el agregado del aceite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Es aconsejable elegir las versiones integrales que aportan m\u00e1s fibra y contribuye a acelerar el tr\u00e1nsito intestinal y prevenir la constipaci\u00f3n, generar mayor sensaci\u00f3n de saciedad y regular los niveles de glucosa y colesterol en la sangre. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un error a\u00fan arraigado en muchas personas es la eliminaci\u00f3n de&nbsp;carbohidratos&nbsp;en una dieta para perder peso. Esto no es verdad,&nbsp;no hay que eliminar los&nbsp;carbohidratos.&nbsp;Sus nutrientes constituyen la base de toda&nbsp;alimentaci\u00f3n&nbsp;equilibrada por lo que lo ideal es incluirlos de forma moderada.&nbsp; Los&nbsp;carbohidratos&nbsp;son la principal fuente de energ\u00eda del cuerpo y deben cubrir entre el 50 y el 60% de las calor\u00edas totales de la dieta. Lo importante es la moderaci\u00f3n. No hay que atender solamente las cantidades, sino el tipo de&nbsp;alimentos&nbsp;que los acompa\u00f1an y c\u00f3mo se cocinan. Por caso, una porci\u00f3n de papas fritas ser\u00e1 mucho m\u00e1s cal\u00f3rica que si la misma porci\u00f3n se prepara al horno o al vapor, sin el agregado del aceite. Es aconsejable elegir las versiones integrales que aportan m\u00e1s fibra y contribuye a acelerar el tr\u00e1nsito intestinal y prevenir la constipaci\u00f3n, generar mayor sensaci\u00f3n de saciedad y regular los niveles de glucosa y colesterol en la sangre.<\/p>\n","protected":false},"author":9,"featured_media":84311,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-84310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=84310"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84310\/revisions"}],"predecessor-version":[{"id":84312,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84310\/revisions\/84312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/84311"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=84310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=84310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=84310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}