{"id":84323,"date":"2022-03-09T20:54:22","date_gmt":"2022-03-10T00:54:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=84323"},"modified":"2022-03-09T20:54:25","modified_gmt":"2022-03-10T00:54:25","slug":"fallece-patricia-ascuasiati-gloria-de-la-danza-dominicana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/fallece-patricia-ascuasiati-gloria-de-la-danza-dominicana\/","title":{"rendered":"Fallece Patricia Ascuasiati, gloria de la danza dominicana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"354\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/03\/patricia-ascuasiati.jpg\" alt=\"\" class=\"wp-image-84324\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/03\/patricia-ascuasiati.jpg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/03\/patricia-ascuasiati-300x156.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption> Patricia Ascuasiati. (<strong>FUENTE EXTERNA<\/strong>) <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Falleci\u00f3 este mi\u00e9rcoles 9 de marzo la veterana&nbsp;<strong>bailarina<\/strong>, core\u00f3grafa y actriz dominicana,&nbsp;<strong>Patricia Ascuasiati<\/strong>, gloria del arte nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Franklin Soto, su&nbsp;<strong>exesposo<\/strong>&nbsp;y su hermano Alejandro Ascuasiati confirmaron el deceso a Diario Libre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fallecimiento de la artista se produjo tras varios d\u00edas ingresada en el Hospital General&nbsp;<strong>Plaza de la Salud<\/strong>, donde fue llevada luego de ser arrollada por un veh\u00edculo en un confuso incidente que a\u00fan est\u00e1 en investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El\u00a0<strong>accidente<\/strong>\u00a0ocurri\u00f3 el 15 de febrero y por el\u00a0<strong>ha sido sometida a la justicia su colega<\/strong>, la tambi\u00e9n\u00a0<strong>core\u00f3grafa<\/strong>\u00a0y\u00a0<strong>bailarina<\/strong>\u00a0<strong>Mary Louise Ventura<\/strong>, a quien el pasado mi\u00e9rcoles el Juzgado de Atenci\u00f3n Permanente de Villa Altagracia dict\u00f3 tres meses de prisi\u00f3n preventiva. Esta medida la cumplir\u00e1 en la c\u00e1rcel de Najayo Mujeres y el 7 de junio se le har\u00e1 revisi\u00f3n a su caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Patricia<\/strong>&nbsp;Antonia Ascusiati Dom\u00ednguez fue una&nbsp;<strong>bailarina<\/strong>&nbsp;y&nbsp;actriz&nbsp;dominicana con m\u00e1s de 35 a\u00f1os de carrera art\u00edstica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ascuasiati Dom\u00ednguez acumul\u00f3 una larga trayectoria en la danza y en el teatro dominicano, y en los \u00faltimos a\u00f1os incursion\u00f3 en las producciones cinematogr\u00e1ficas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se destaca su participaci\u00f3n en producciones como la&nbsp;pel\u00edcula&nbsp;La Gunguna&nbsp;(2015),&nbsp;Detective Willy&nbsp;(2015) y&nbsp;Piedra de Sangre&nbsp;(2016).&nbsp;<strong>Ascuasiati<\/strong>&nbsp;tambi\u00e9n produjo y dirigi\u00f3 espect\u00e1culos teatrales y televisivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se le reconoce por su amplio historial en el arte de la Rep\u00fablica Dominicana, con un ejercicio profesional de m\u00e1s de 35 a\u00f1os dedicados a la danza, la coreograf\u00eda y la ense\u00f1anza de ballet, adem\u00e1s de la producci\u00f3n y direcci\u00f3n de espect\u00e1culos de teatro, televisi\u00f3n nacional y como guionista cinematogr\u00e1fica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Patricia<\/strong>&nbsp;fue miembro del&nbsp;Ballet Santo Domingo, dirigido por la maestra&nbsp;Imgard Despradel, y adem\u00e1s dirigi\u00f3 la&nbsp;Escuela Nacional de Danza&nbsp;desde el 2004 hasta el 2008.&nbsp;Fue alumna de la maestra&nbsp;Eladia de Cuello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destacamos algunos de sus reconocimientos m\u00e1s importantes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Core\u00f3grafa residente del Ballet Cl\u00e1sico Nacional (1994-2000)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Participaci\u00f3n en la recopilaci\u00f3n, registro de datos y redacci\u00f3n del libro documental hist\u00f3rico&nbsp; del Ballet Nacional Dominicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Directora de los centros educativos: Escuela Contempor\u00e1nea de Danza (1984-1989),\u00a0<strong>Patricia Ascuasiati<\/strong>\u00a0Escuela de Formaci\u00f3n Art\u00edstica (1994-2005), Escuela Nacional de Danza (2000-2004) y Danza Banreservas (2008 a la actualidad).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.diariolibre.com\/revista\/cultura\/2022\/03\/09\/muere-patricia-ascuasiati-gloria-de-la-danza\/1695980\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Falleci\u00f3 este mi\u00e9rcoles 9 de marzo la veterana&nbsp;bailarina, core\u00f3grafa y actriz dominicana,&nbsp;Patricia Ascuasiati, gloria del arte nacional. Franklin Soto, su&nbsp;exesposo&nbsp;y su hermano Alejandro Ascuasiati confirmaron el deceso a Diario Libre. El fallecimiento de la artista se produjo tras varios d\u00edas ingresada en el Hospital General&nbsp;Plaza de la Salud, donde fue llevada luego de ser arrollada por un veh\u00edculo en un confuso incidente que a\u00fan est\u00e1 en investigaci\u00f3n. El\u00a0accidente\u00a0ocurri\u00f3 el 15 de febrero y por el\u00a0ha sido sometida a la justicia su colega, la tambi\u00e9n\u00a0core\u00f3grafa\u00a0y\u00a0bailarina\u00a0Mary Louise Ventura, a quien el pasado mi\u00e9rcoles el Juzgado de Atenci\u00f3n Permanente de Villa Altagracia dict\u00f3 tres meses de prisi\u00f3n preventiva. Esta medida la cumplir\u00e1 en la c\u00e1rcel de Najayo Mujeres y el 7 de junio se le har\u00e1 revisi\u00f3n a su caso. Patricia&nbsp;Antonia Ascusiati Dom\u00ednguez fue una&nbsp;bailarina&nbsp;y&nbsp;actriz&nbsp;dominicana con m\u00e1s de 35 a\u00f1os de carrera art\u00edstica. Ascuasiati Dom\u00ednguez acumul\u00f3 una larga trayectoria en la danza y en el teatro dominicano, y en los \u00faltimos a\u00f1os incursion\u00f3 en las producciones cinematogr\u00e1ficas. Se destaca su participaci\u00f3n en producciones como la&nbsp;pel\u00edcula&nbsp;La Gunguna&nbsp;(2015),&nbsp;Detective Willy&nbsp;(2015) y&nbsp;Piedra de Sangre&nbsp;(2016).&nbsp;Ascuasiati&nbsp;tambi\u00e9n produjo y dirigi\u00f3 espect\u00e1culos teatrales y televisivos. Se le reconoce por su amplio historial en el arte de la Rep\u00fablica Dominicana, con un ejercicio profesional de m\u00e1s de 35 a\u00f1os dedicados a la danza, la coreograf\u00eda y la ense\u00f1anza de ballet, adem\u00e1s de la producci\u00f3n y direcci\u00f3n de espect\u00e1culos de teatro, televisi\u00f3n nacional y como guionista cinematogr\u00e1fica. Patricia&nbsp;fue miembro del&nbsp;Ballet Santo Domingo, dirigido por la maestra&nbsp;Imgard Despradel, y adem\u00e1s dirigi\u00f3 la&nbsp;Escuela Nacional de Danza&nbsp;desde el 2004 hasta el 2008.&nbsp;Fue alumna de la maestra&nbsp;Eladia de Cuello. Destacamos algunos de sus reconocimientos m\u00e1s importantes: Core\u00f3grafa residente del Ballet Cl\u00e1sico Nacional (1994-2000) Participaci\u00f3n en la recopilaci\u00f3n, registro de datos y redacci\u00f3n del libro documental hist\u00f3rico&nbsp; del Ballet Nacional Dominicano. Directora de los centros educativos: Escuela Contempor\u00e1nea de Danza (1984-1989),\u00a0Patricia Ascuasiati\u00a0Escuela de Formaci\u00f3n Art\u00edstica (1994-2005), Escuela Nacional de Danza (2000-2004) y Danza Banreservas (2008 a la actualidad). FUENTE<\/p>\n","protected":false},"author":12,"featured_media":84324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-84323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=84323"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84323\/revisions"}],"predecessor-version":[{"id":84325,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84323\/revisions\/84325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/84324"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=84323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=84323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=84323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}