{"id":84353,"date":"2022-03-12T19:32:53","date_gmt":"2022-03-12T23:32:53","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=84353"},"modified":"2022-03-12T19:32:55","modified_gmt":"2022-03-12T23:32:55","slug":"el-plato-de-pasta-es-cada-vez-mas-caro-en-italia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-plato-de-pasta-es-cada-vez-mas-caro-en-italia\/","title":{"rendered":"El plato de pasta es cada vez m\u00e1s caro en Italia"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/03\/el-plato-de-pasta-es-cada-vez-mas-caro-en-italia.jpeg\" alt=\"\" class=\"wp-image-84354\" width=\"172\" height=\"114\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/03\/el-plato-de-pasta-es-cada-vez-mas-caro-en-italia.jpeg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/03\/el-plato-de-pasta-es-cada-vez-mas-caro-en-italia-300x200.jpeg 300w\" sizes=\"auto, (max-width: 172px) 100vw, 172px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La pasta o la pizza son las otras banderas de Italia pero disfrutar de estos platos es cada vez m\u00e1s caro a causa del encarecimiento de la energ\u00eda y por un mercado mundial de materias primas agitado, ahora tambi\u00e9n por la guerra en Ucrania.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl precio de la pasta en el supermercado aument\u00f3 por efecto del encarecimiento del trigo duro desde el pasado octubre. Aument\u00f3 la materia prima, la energ\u00eda, el transporte y todo lo que hace falta para que llegue a las estanter\u00edas\u00bb, explica a Efe Andrea Pasini, director del sector de cereal del Consorcio Agr\u00edcola Italiano (CAI).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La palabra \u00abinflaci\u00f3n\u00bb resuena cada vez con m\u00e1s frecuencia en las tiendas, bares y restaurantes italianos. Por ejemplo, de la noche a la ma\u00f1ana el caf\u00e9 \u00abespresso\u00bb pas\u00f3 de los habituales ochenta c\u00e9ntimos en Roma al euro redondo, para sorpresa de los parroquianos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTendremos que subir los precios porque, si no, no sobrevivimos\u00bb, reconoce a Efe con resignaci\u00f3n Mauro, al frente de un ultramarinos en el barrio romano de Prati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde hace d\u00edas, los hornos que suministran pan, pasta, galletas o boller\u00eda a su tienda, la Macelleria Bordiga, vienen avisando de que los precios subir\u00e1n \u00abentre un 25 y un 30 %\u00bb porque la harina est\u00e1 por las nubes, y eso ya est\u00e1 repercutiendo en el bolsillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre este fen\u00f3meno planea especialmente la sombra de la crisis energ\u00e9tica que recorre el continente europeo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Italia, los precios sufrieron en febrero su octava aceleraci\u00f3n consecutiva, aumentando en un 5,7 %, un nivel que no se ve\u00eda desde 1995, pero especialmente se dispararon la vivienda, el agua, la electricidad y el combustible, un 27,3 % interanual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo se encarecieron el transporte (9,0 %), los alimentos (4,9 %) y la restauraci\u00f3n (4,0 %), seg\u00fan el Instituto Nacional de Estad\u00edstica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El vuelo del spaghetti<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La inflaci\u00f3n tambi\u00e9n golpea a la insigne pasta. En la asociaci\u00f3n Unione Italiana Food avisan de que sus fabricantes, repartidos en unas 120 empresas, muchas centenarias y familiares, con m\u00e1s de 10.000 empleados, \u00abatraviesan una crisis sin precedentes\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El precio del trigo duro, usado en este manjar, es estable desde hace \u00abalgunas semanas\u00bb pero acumula un alza del 80 % en el \u00faltimo a\u00f1o a causa de cambios en el clima y las cosechas, la especulaci\u00f3n internacional y la acumulaci\u00f3n de reservas por algunas potencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n afecta la escalada de la energ\u00eda pues los molinos y secadoras requieren mucha electricidad, alega Pasini, as\u00ed como el encarecimiento de los embalajes y del petr\u00f3leo, y en este sentido la crisis rusa marcar\u00e1 los pr\u00f3ximos meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que el \u00abBel Paese\u00bb es especialmente sensible a los vaivenes del mercado internacional porque aunque produce, vende y presume de pasta o pizza, su elaboraci\u00f3n depende en gran parte de los campos de otras latitudes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En concreto, Italia importa el 64 % del trigo blando que usa en su pan o dulces, el 44 % del duro, necesario para la pasta, el 47 % del ma\u00edz y el 73 % de su soja, estos dos \u00faltimos esenciales en la alimentaci\u00f3n animal, explican en el CAI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El peso de la guerra ucraniana<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, la guerra provocada por la invasi\u00f3n de Ucrania por parte de Rusia tampoco ayuda a paliar la situaci\u00f3n, agravada a su vez por las sanciones econ\u00f3micas impuestas por otras potencias como la Uni\u00f3n Europea o Estados Unidos al r\u00e9gimen de Vladimir Putin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rusia es el mayor exportador mundial de trigo y Ucrania el quinto, ambos representan m\u00e1s de un tercio de las exportaciones planetarias de cereal y el primero adem\u00e1s es el principal productor de fertilizantes, seg\u00fan la Organizaci\u00f3n de Naciones Unidas para la Alimentaci\u00f3n y la Agricultura (FAO).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El impacto de este conflicto en la mesa de los italianos var\u00eda en funci\u00f3n del alimento: en lo que respecta al grano duro ser\u00e1 \u00abextremadamente marginal\u00bb porque en 2021 no se import\u00f3 de Ucrania y el que lleg\u00f3 de Rusia represent\u00f3 menos del 3 %.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero la cosa cambia con el trigo harinero, con el que se elabora el pan, los postres, la pizza o los piensos animales y del que Ucrania es uno de los principales productores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEn una econom\u00eda global, la oscilaci\u00f3n de una mercanc\u00eda arrastra a las dem\u00e1s\u00bb, sostiene en un comunicado el secretario de los Pasteros italianos, Luigi Cristiano Laurenza: \u00abNo podemos excluir que el conflicto tenga efectos indirectos tambi\u00e9n en la pasta\u00bb, subraya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cualquier caso, desde el inicio de la guerra, el precio del grano blando ha escalado un 12 % y el del ma\u00edz subi\u00f3 un 14,5 %.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como soluci\u00f3n, Coldiretti, la mayor asociaci\u00f3n de agricultores del pa\u00eds, se dice preparada para cultivar 75 millones de quintales m\u00e1s de ma\u00edz y trigo con el objetivo de aplacar \u00ablas dificultades del aprovisionamiento extranjero causadas por la guerra\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pasta o la pizza son las otras banderas de Italia pero disfrutar de estos platos es cada vez m\u00e1s caro a causa del encarecimiento de la energ\u00eda y por un mercado mundial de materias primas agitado, ahora tambi\u00e9n por la guerra en Ucrania. \u00abEl precio de la pasta en el supermercado aument\u00f3 por efecto del encarecimiento del trigo duro desde el pasado octubre. Aument\u00f3 la materia prima, la energ\u00eda, el transporte y todo lo que hace falta para que llegue a las estanter\u00edas\u00bb, explica a Efe Andrea Pasini, director del sector de cereal del Consorcio Agr\u00edcola Italiano (CAI). La palabra \u00abinflaci\u00f3n\u00bb resuena cada vez con m\u00e1s frecuencia en las tiendas, bares y restaurantes italianos. Por ejemplo, de la noche a la ma\u00f1ana el caf\u00e9 \u00abespresso\u00bb pas\u00f3 de los habituales ochenta c\u00e9ntimos en Roma al euro redondo, para sorpresa de los parroquianos. \u00abTendremos que subir los precios porque, si no, no sobrevivimos\u00bb, reconoce a Efe con resignaci\u00f3n Mauro, al frente de un ultramarinos en el barrio romano de Prati. Desde hace d\u00edas, los hornos que suministran pan, pasta, galletas o boller\u00eda a su tienda, la Macelleria Bordiga, vienen avisando de que los precios subir\u00e1n \u00abentre un 25 y un 30 %\u00bb porque la harina est\u00e1 por las nubes, y eso ya est\u00e1 repercutiendo en el bolsillo. Sobre este fen\u00f3meno planea especialmente la sombra de la crisis energ\u00e9tica que recorre el continente europeo. En Italia, los precios sufrieron en febrero su octava aceleraci\u00f3n consecutiva, aumentando en un 5,7 %, un nivel que no se ve\u00eda desde 1995, pero especialmente se dispararon la vivienda, el agua, la electricidad y el combustible, un 27,3 % interanual. Asimismo se encarecieron el transporte (9,0 %), los alimentos (4,9 %) y la restauraci\u00f3n (4,0 %), seg\u00fan el Instituto Nacional de Estad\u00edstica. El vuelo del spaghetti La inflaci\u00f3n tambi\u00e9n golpea a la insigne pasta. En la asociaci\u00f3n Unione Italiana Food avisan de que sus fabricantes, repartidos en unas 120 empresas, muchas centenarias y familiares, con m\u00e1s de 10.000 empleados, \u00abatraviesan una crisis sin precedentes\u00bb. El precio del trigo duro, usado en este manjar, es estable desde hace \u00abalgunas semanas\u00bb pero acumula un alza del 80 % en el \u00faltimo a\u00f1o a causa de cambios en el clima y las cosechas, la especulaci\u00f3n internacional y la acumulaci\u00f3n de reservas por algunas potencias. Tambi\u00e9n afecta la escalada de la energ\u00eda pues los molinos y secadoras requieren mucha electricidad, alega Pasini, as\u00ed como el encarecimiento de los embalajes y del petr\u00f3leo, y en este sentido la crisis rusa marcar\u00e1 los pr\u00f3ximos meses. Y es que el \u00abBel Paese\u00bb es especialmente sensible a los vaivenes del mercado internacional porque aunque produce, vende y presume de pasta o pizza, su elaboraci\u00f3n depende en gran parte de los campos de otras latitudes. En concreto, Italia importa el 64 % del trigo blando que usa en su pan o dulces, el 44 % del duro, necesario para la pasta, el 47 % del ma\u00edz y el 73 % de su soja, estos dos \u00faltimos esenciales en la alimentaci\u00f3n animal, explican en el CAI. El peso de la guerra ucraniana Por eso, la guerra provocada por la invasi\u00f3n de Ucrania por parte de Rusia tampoco ayuda a paliar la situaci\u00f3n, agravada a su vez por las sanciones econ\u00f3micas impuestas por otras potencias como la Uni\u00f3n Europea o Estados Unidos al r\u00e9gimen de Vladimir Putin. Rusia es el mayor exportador mundial de trigo y Ucrania el quinto, ambos representan m\u00e1s de un tercio de las exportaciones planetarias de cereal y el primero adem\u00e1s es el principal productor de fertilizantes, seg\u00fan la Organizaci\u00f3n de Naciones Unidas para la Alimentaci\u00f3n y la Agricultura (FAO). El impacto de este conflicto en la mesa de los italianos var\u00eda en funci\u00f3n del alimento: en lo que respecta al grano duro ser\u00e1 \u00abextremadamente marginal\u00bb porque en 2021 no se import\u00f3 de Ucrania y el que lleg\u00f3 de Rusia represent\u00f3 menos del 3 %. Pero la cosa cambia con el trigo harinero, con el que se elabora el pan, los postres, la pizza o los piensos animales y del que Ucrania es uno de los principales productores. \u00abEn una econom\u00eda global, la oscilaci\u00f3n de una mercanc\u00eda arrastra a las dem\u00e1s\u00bb, sostiene en un comunicado el secretario de los Pasteros italianos, Luigi Cristiano Laurenza: \u00abNo podemos excluir que el conflicto tenga efectos indirectos tambi\u00e9n en la pasta\u00bb, subraya. En cualquier caso, desde el inicio de la guerra, el precio del grano blando ha escalado un 12 % y el del ma\u00edz subi\u00f3 un 14,5 %. Como soluci\u00f3n, Coldiretti, la mayor asociaci\u00f3n de agricultores del pa\u00eds, se dice preparada para cultivar 75 millones de quintales m\u00e1s de ma\u00edz y trigo con el objetivo de aplacar \u00ablas dificultades del aprovisionamiento extranjero causadas por la guerra\u00bb.<\/p>\n","protected":false},"author":9,"featured_media":84354,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-84353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=84353"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84353\/revisions"}],"predecessor-version":[{"id":84355,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84353\/revisions\/84355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/84354"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=84353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=84353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=84353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}