{"id":84422,"date":"2022-04-02T12:41:37","date_gmt":"2022-04-02T16:41:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=84422"},"modified":"2022-04-02T12:41:40","modified_gmt":"2022-04-02T16:41:40","slug":"santiago-maestros-toman-las-calles-en-reclamo-de-aumento","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/santiago-maestros-toman-las-calles-en-reclamo-de-aumento\/","title":{"rendered":"SANTIAGO: Maestros toman las calles en reclamo de aumento"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/04\/una-multitud-de-gente-en-la-calle-1fbbc52d.jpeg\" alt=\"\" class=\"wp-image-84423\" width=\"201\" height=\"134\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/04\/una-multitud-de-gente-en-la-calle-1fbbc52d.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/04\/una-multitud-de-gente-en-la-calle-1fbbc52d-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/04\/una-multitud-de-gente-en-la-calle-1fbbc52d-768x512.jpeg 768w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTIAGO .- Con bombas lacrim\u00f3genas trat\u00f3 la Polic\u00eda de dispersar este viernes a cientos de profesores aglomerados frente a las oficinas del Ministerio de Educaci\u00f3n, en Santiago, en reclamo de aumento salarial y otras reivindicaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pancartas en manos y vociferando consignas alusivas a sus reclamos, los manifestantes ocuparon un tramo de la avenida Salvador Estrella Sadhal\u00e1 y obstruyeron el paso vehicular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exigen un incremento de un 25 por ciento en sus sueldos,&nbsp;nombramiento de quienes aprobaron el concurso de oposici\u00f3n docente, adecuaci\u00f3n de centros educativos, mejores comidas y contrataci\u00f3n de personal administrativo y de conserjer\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las demandas forman parte del acuerdo con el Ministerio de Educaci\u00f3n que se firm\u00f3 en junio del a\u00f1o pasado, record\u00f3&nbsp;Miguel Jorge, presidente de la Asociaci\u00f3n Dominicana de Profesores (ADP) en Santiago, quien advirti\u00f3 que \u00abseguiremos las protestas, a pesar de la represi\u00f3n de los uniformados\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abUn ministro que no escucha, solo nos deja la lucha. Queremos ser escuchados y que se cumpla lo acordado\u00bb, dijo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTIAGO .- Con bombas lacrim\u00f3genas trat\u00f3 la Polic\u00eda de dispersar este viernes a cientos de profesores aglomerados frente a las oficinas del Ministerio de Educaci\u00f3n, en Santiago, en reclamo de aumento salarial y otras reivindicaciones. Pancartas en manos y vociferando consignas alusivas a sus reclamos, los manifestantes ocuparon un tramo de la avenida Salvador Estrella Sadhal\u00e1 y obstruyeron el paso vehicular. Exigen un incremento de un 25 por ciento en sus sueldos,&nbsp;nombramiento de quienes aprobaron el concurso de oposici\u00f3n docente, adecuaci\u00f3n de centros educativos, mejores comidas y contrataci\u00f3n de personal administrativo y de conserjer\u00eda. Las demandas forman parte del acuerdo con el Ministerio de Educaci\u00f3n que se firm\u00f3 en junio del a\u00f1o pasado, record\u00f3&nbsp;Miguel Jorge, presidente de la Asociaci\u00f3n Dominicana de Profesores (ADP) en Santiago, quien advirti\u00f3 que \u00abseguiremos las protestas, a pesar de la represi\u00f3n de los uniformados\u00bb. \u00abUn ministro que no escucha, solo nos deja la lucha. Queremos ser escuchados y que se cumpla lo acordado\u00bb, dijo.<\/p>\n","protected":false},"author":9,"featured_media":84423,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-84422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=84422"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84422\/revisions"}],"predecessor-version":[{"id":84424,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84422\/revisions\/84424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/84423"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=84422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=84422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=84422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}