{"id":84662,"date":"2022-05-05T09:17:00","date_gmt":"2022-05-05T13:17:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=84662"},"modified":"2022-05-05T09:17:01","modified_gmt":"2022-05-05T13:17:01","slug":"pais-no-ha-reportado-casos-de-la-hepatitis-infantil-que-vigila-oms","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/pais-no-ha-reportado-casos-de-la-hepatitis-infantil-que-vigila-oms\/","title":{"rendered":"Pa\u00eds no ha reportado casos de la hepatitis infantil que vigila OMS"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/05\/salu.jpg\" alt=\"\" class=\"wp-image-84663\" width=\"212\" height=\"109\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/05\/salu.jpg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/05\/salu-300x155.jpg 300w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque los casos de la nueva hepatitis infantil aguda que observa la Organizaci\u00f3n Mundial de la Salud (OMS) siguen expandi\u00e9ndose a diferentes naciones, las autoridades sanitarias dominicanas aseguran que en el pa\u00eds a\u00fan no se ha notificado ning\u00fan caso sospechoso de la misma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, el ministro de Salud P\u00fablica, Daniel Rivera, asegur\u00f3 que mantiene contacto diario con el organismo internacional y una vigilancia activa a nivel nacional para detectar a tiempo cualquier paciente con s\u00edntomas sospechosos. Exhort\u00f3 a la poblaci\u00f3n adoptar como medidas preventivas la higiene, el lavado de manos y el consumo de agua potable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, llam\u00f3 a la poblaci\u00f3n a seguir aplic\u00e1ndose la vacuna contra el COVID-19 y pidi\u00f3 a los padres llevar a inmunizar a sus ni\u00f1os contra el sarampi\u00f3n, la rub\u00e9ola y el polio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario inform\u00f3 que en la jornada de vacunaci\u00f3n contra esas tres enfermedades se han aplicado 247,363 dosis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precis\u00f3 que por ahora no hay lotes de vacunas contra el Covid-19 vencidas o por vencerse, pero que es importante que la poblaci\u00f3n complete sus esquemas de vacunaci\u00f3n. Se\u00f1al\u00f3 que aquellos que tienen m\u00e1s de 50 a\u00f1os, pueden colocarse la cuarta dosis de vacuna, cuatro meses de haberse puesto la tercera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;a su vez, el infect\u00f3logo Clemente Terrero, director del Hospital Infantil Robert Reid Cabral, dijo que tienen cinco pacientes ingresados por dengue, pero est\u00e1n dentro de los par\u00e1metros esperados para esta \u00e9poca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos est\u00e1n estables y no se ha registrado ninguna muerte, dijo. el centro de referencia nacional no ha recibido ning\u00fan caso sospechoso de hepatitis aguda de origen desconocido, pero que se mantiene una estricta observaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En torno al dengue, dijo que actualmente hay cinco pacientes ingresados, lo cual se encuentra dentro de los par\u00e1metros esperados para esta \u00e9poca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque los casos de la nueva hepatitis infantil aguda que observa la Organizaci\u00f3n Mundial de la Salud (OMS) siguen expandi\u00e9ndose a diferentes naciones, las autoridades sanitarias dominicanas aseguran que en el pa\u00eds a\u00fan no se ha notificado ning\u00fan caso sospechoso de la misma. No obstante, el ministro de Salud P\u00fablica, Daniel Rivera, asegur\u00f3 que mantiene contacto diario con el organismo internacional y una vigilancia activa a nivel nacional para detectar a tiempo cualquier paciente con s\u00edntomas sospechosos. Exhort\u00f3 a la poblaci\u00f3n adoptar como medidas preventivas la higiene, el lavado de manos y el consumo de agua potable. Asimismo, llam\u00f3 a la poblaci\u00f3n a seguir aplic\u00e1ndose la vacuna contra el COVID-19 y pidi\u00f3 a los padres llevar a inmunizar a sus ni\u00f1os contra el sarampi\u00f3n, la rub\u00e9ola y el polio. El funcionario inform\u00f3 que en la jornada de vacunaci\u00f3n contra esas tres enfermedades se han aplicado 247,363 dosis. Precis\u00f3 que por ahora no hay lotes de vacunas contra el Covid-19 vencidas o por vencerse, pero que es importante que la poblaci\u00f3n complete sus esquemas de vacunaci\u00f3n. Se\u00f1al\u00f3 que aquellos que tienen m\u00e1s de 50 a\u00f1os, pueden colocarse la cuarta dosis de vacuna, cuatro meses de haberse puesto la tercera. &nbsp;a su vez, el infect\u00f3logo Clemente Terrero, director del Hospital Infantil Robert Reid Cabral, dijo que tienen cinco pacientes ingresados por dengue, pero est\u00e1n dentro de los par\u00e1metros esperados para esta \u00e9poca. Todos est\u00e1n estables y no se ha registrado ninguna muerte, dijo. el centro de referencia nacional no ha recibido ning\u00fan caso sospechoso de hepatitis aguda de origen desconocido, pero que se mantiene una estricta observaci\u00f3n. En torno al dengue, dijo que actualmente hay cinco pacientes ingresados, lo cual se encuentra dentro de los par\u00e1metros esperados para esta \u00e9poca.<\/p>\n","protected":false},"author":9,"featured_media":84663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-84662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=84662"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84662\/revisions"}],"predecessor-version":[{"id":84664,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84662\/revisions\/84664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/84663"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=84662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=84662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=84662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}