{"id":84725,"date":"2022-05-24T20:15:21","date_gmt":"2022-05-25T00:15:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=84725"},"modified":"2022-05-25T20:20:47","modified_gmt":"2022-05-26T00:20:47","slug":"aeropuerto-de-puerto-plata-reinicia-operaciones-con-la-llegada-de-seis-vuelos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aeropuerto-de-puerto-plata-reinicia-operaciones-con-la-llegada-de-seis-vuelos\/","title":{"rendered":"Aeropuerto de Puerto Plata reinicia operaciones con la llegada de seis vuelos"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"530\" height=\"360\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/05\/aeropuerto-gregorio-luper\u00f3n-1-3973463b-focus-0-0-895-573.jpg\" alt=\"\" data-id=\"84726\" data-full-url=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/05\/aeropuerto-gregorio-luper\u00f3n-1-3973463b-focus-0-0-895-573.jpg\" data-link=\"http:\/\/sosuaonline.net\/inicio\/?attachment_id=84726\" class=\"wp-image-84726\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/05\/aeropuerto-gregorio-luper\u00f3n-1-3973463b-focus-0-0-895-573.jpg 530w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/05\/aeropuerto-gregorio-luper\u00f3n-1-3973463b-focus-0-0-895-573-300x204.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/05\/aeropuerto-gregorio-luper\u00f3n-1-3973463b-focus-0-0-895-573-75x52.jpg 75w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa&nbsp;<strong>Aeropuertos Dominicanos<\/strong>&nbsp;Siglo XXI (<strong>Aerodom<\/strong>) restableci\u00f3 este viernes el tr\u00e1fico a\u00e9reo en el&nbsp;<strong>Aeropuerto Internacional Gregorio Luper\u00f3n&nbsp;<\/strong>(AIGL) de&nbsp;<strong>Puerto Plata<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las operaciones en dicha terminal estuvieron cerradas durante 10 d\u00edas debido a los trabajos de remodelaci\u00f3n de la pista de aterrizaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primero de los seis vuelos programados para el reinicio del tr\u00e1fico a\u00e9reo en el AIGL fue el 627 de JetBlue. El mismo aterriz\u00f3 a las 12:28 p.m. procedente del Aeropuerto John F. Kennedy de Nueva York.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, aterrizaron los vuelos United Airlines 1078, desde Newark; WestJet 2506, desde Toronto; American Airlines 935, desde Miami; Condor 2144, desde Frankfurt; y Air Transat 944, desde Toronto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNos llena de alegr\u00eda reanudar nuestras operaciones en el Aeropuerto Internacional Gregorio Luper\u00f3n, luego de haber realizado una reparaci\u00f3n y remodelaci\u00f3n mayor en la pista como parte de nuestro programa de mantenimiento\u201d, expres\u00f3 Carlos Rodol\u00ed Conde, director del aeropuerto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que la intervenci\u00f3n permitir\u00e1 elevar la seguridad operacional al mejorar las condiciones de rodadura, as\u00ed como maximizar su vida \u00fatil.<strong>TE PUEDE INTERESAR<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sobre la reparaci\u00f3n de la terminal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los trabajos realizados, que implicaron una inversi\u00f3n superior a los US$4.5 millones, consistieron en la demolici\u00f3n de las losas de hormig\u00f3n existentes que deb\u00edan ser reemplazadas, construcci\u00f3n de nuevas losas y la adecuaci\u00f3n de la \u00abRESA\u00bb de la cabecera 26.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ellos, se extiende la vida \u00fatil de la pista, mejoran las condiciones operativas de las aeronaves, y se corrige la nivelaci\u00f3n de losas en el tramo central de la pista, dijo&nbsp;<strong>Aerodom<\/strong>.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa&nbsp;Aeropuertos Dominicanos&nbsp;Siglo XXI (Aerodom) restableci\u00f3 este viernes el tr\u00e1fico a\u00e9reo en el&nbsp;Aeropuerto Internacional Gregorio Luper\u00f3n&nbsp;(AIGL) de&nbsp;Puerto Plata. Las operaciones en dicha terminal estuvieron cerradas durante 10 d\u00edas debido a los trabajos de remodelaci\u00f3n de la pista de aterrizaje. El primero de los seis vuelos programados para el reinicio del tr\u00e1fico a\u00e9reo en el AIGL fue el 627 de JetBlue. El mismo aterriz\u00f3 a las 12:28 p.m. procedente del Aeropuerto John F. Kennedy de Nueva York. Posteriormente, aterrizaron los vuelos United Airlines 1078, desde Newark; WestJet 2506, desde Toronto; American Airlines 935, desde Miami; Condor 2144, desde Frankfurt; y Air Transat 944, desde Toronto. \u201cNos llena de alegr\u00eda reanudar nuestras operaciones en el Aeropuerto Internacional Gregorio Luper\u00f3n, luego de haber realizado una reparaci\u00f3n y remodelaci\u00f3n mayor en la pista como parte de nuestro programa de mantenimiento\u201d, expres\u00f3 Carlos Rodol\u00ed Conde, director del aeropuerto. Explic\u00f3 que la intervenci\u00f3n permitir\u00e1 elevar la seguridad operacional al mejorar las condiciones de rodadura, as\u00ed como maximizar su vida \u00fatil.TE PUEDE INTERESAR Sobre la reparaci\u00f3n de la terminal Los trabajos realizados, que implicaron una inversi\u00f3n superior a los US$4.5 millones, consistieron en la demolici\u00f3n de las losas de hormig\u00f3n existentes que deb\u00edan ser reemplazadas, construcci\u00f3n de nuevas losas y la adecuaci\u00f3n de la \u00abRESA\u00bb de la cabecera 26. Con ellos, se extiende la vida \u00fatil de la pista, mejoran las condiciones operativas de las aeronaves, y se corrige la nivelaci\u00f3n de losas en el tramo central de la pista, dijo&nbsp;Aerodom.&nbsp;<\/p>\n","protected":false},"author":12,"featured_media":84726,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,3],"tags":[],"class_list":["post-84725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=84725"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84725\/revisions"}],"predecessor-version":[{"id":84727,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84725\/revisions\/84727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/84726"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=84725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=84725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=84725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}