{"id":84873,"date":"2022-06-17T07:59:04","date_gmt":"2022-06-17T11:59:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=84873"},"modified":"2022-06-17T07:59:05","modified_gmt":"2022-06-17T11:59:05","slug":"pn-desmantela-banda-robaba-motocicletas-en-sosua-y-cabarete","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/pn-desmantela-banda-robaba-motocicletas-en-sosua-y-cabarete\/","title":{"rendered":"PN desmantela banda robaba motocicletas en Sos\u00faa y Cabarete"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/06\/PN-DESMANTELA-BANDA-DELINCUENCIAL-ROBABA-MOTOCICLETAS-EN-SOSUA-Y-CABARETE.jpg\" alt=\"\" class=\"wp-image-84874\" width=\"234\" height=\"105\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/06\/PN-DESMANTELA-BANDA-DELINCUENCIAL-ROBABA-MOTOCICLETAS-EN-SOSUA-Y-CABARETE.jpg 555w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/06\/PN-DESMANTELA-BANDA-DELINCUENCIAL-ROBABA-MOTOCICLETAS-EN-SOSUA-Y-CABARETE-300x135.jpg 300w\" sizes=\"auto, (max-width: 234px) 100vw, 234px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PUERTO PLATA.-<\/strong>&nbsp;La Polic\u00eda Nacional inform\u00f3 la detenci\u00f3n de un hombre que dirig\u00eda una peligrosa banda de asaltantes que despojaban a ciudadanos de motocicletas en sectores de Sos\u00faa y Cabarete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El detenido es&nbsp;F\u00e9lix Junior Baret Montero, quien ser\u00e1 sometido a la justicia en las pr\u00f3ximas horas ya que en compa\u00f1\u00eda de unos tales \u201cSadam\u201d y \u201cKensy\u201d que est\u00e1n pr\u00f3fugos, realizaron varios asaltos en el distrito municipal de Cabarete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el parte policial, los tres antisociales&nbsp;con cuchillos en mano interceptaron al nacional haitiano Francisco Donacley al cual despojaron de la motocicleta Honda, modelo C50 de color Verde, un celular marca ZTE y la suma de 200 d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los bandoleros dejaron abandonada en el sector Bombita de Cabarete la motocicleta marca Benyi, CG-150 de color rojo donde comet\u00edan sus fechor\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n robaron la motocicleta Yamaha TC110 Crypton de color negro, propiedad de la nacional ucraniana Karina Dede, recuperada en unos matorrales de la urbanizaci\u00f3n La Mulata II del municipio de Sos\u00faa,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se supo que dichos malhechores atracaron a&nbsp;filo de machete a la se\u00f1ora Raquel Vargas,&nbsp;despoj\u00e1ndola de su cartera que conten\u00eda en su interior documentos personales, tarjetas de cr\u00e9dito, dos tel\u00e9fonos celulares y la suma de 19 mil pesos en efectivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.-&nbsp;La Polic\u00eda Nacional inform\u00f3 la detenci\u00f3n de un hombre que dirig\u00eda una peligrosa banda de asaltantes que despojaban a ciudadanos de motocicletas en sectores de Sos\u00faa y Cabarete. El detenido es&nbsp;F\u00e9lix Junior Baret Montero, quien ser\u00e1 sometido a la justicia en las pr\u00f3ximas horas ya que en compa\u00f1\u00eda de unos tales \u201cSadam\u201d y \u201cKensy\u201d que est\u00e1n pr\u00f3fugos, realizaron varios asaltos en el distrito municipal de Cabarete. Seg\u00fan el parte policial, los tres antisociales&nbsp;con cuchillos en mano interceptaron al nacional haitiano Francisco Donacley al cual despojaron de la motocicleta Honda, modelo C50 de color Verde, un celular marca ZTE y la suma de 200 d\u00f3lares. Los bandoleros dejaron abandonada en el sector Bombita de Cabarete la motocicleta marca Benyi, CG-150 de color rojo donde comet\u00edan sus fechor\u00edas. Tambi\u00e9n robaron la motocicleta Yamaha TC110 Crypton de color negro, propiedad de la nacional ucraniana Karina Dede, recuperada en unos matorrales de la urbanizaci\u00f3n La Mulata II del municipio de Sos\u00faa, Se supo que dichos malhechores atracaron a&nbsp;filo de machete a la se\u00f1ora Raquel Vargas,&nbsp;despoj\u00e1ndola de su cartera que conten\u00eda en su interior documentos personales, tarjetas de cr\u00e9dito, dos tel\u00e9fonos celulares y la suma de 19 mil pesos en efectivo.<\/p>\n","protected":false},"author":9,"featured_media":84874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-84873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=84873"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84873\/revisions"}],"predecessor-version":[{"id":84875,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84873\/revisions\/84875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/84874"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=84873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=84873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=84873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}