{"id":84883,"date":"2022-06-17T11:25:25","date_gmt":"2022-06-17T15:25:25","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=84883"},"modified":"2022-06-17T11:25:26","modified_gmt":"2022-06-17T15:25:26","slug":"salud-publica-inabie-y-la-fao-trabajaran-juntos-para-mejorar-la-alimentacion-escolar","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/salud-publica-inabie-y-la-fao-trabajaran-juntos-para-mejorar-la-alimentacion-escolar\/","title":{"rendered":"Salud P\u00fablica, INABIE y la FAO trabajar\u00e1n juntos para mejorar la alimentaci\u00f3n escolar"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/06\/escolar.jpg\" alt=\"\" class=\"wp-image-84884\" width=\"241\" height=\"135\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/06\/escolar.jpg 688w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/06\/escolar-300x169.jpg 300w\" sizes=\"auto, (max-width: 241px) 100vw, 241px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">La cooperaci\u00f3n de estas instituciones busca mejorar la calidad de los productos que se suplen en los plantes escolares, con miras a mitigar enfermedades cr\u00f3nicas desde este segmento poblacional.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SANTO DOMINGO.<\/strong>&#8211; El Ministerio de Salud P\u00fablica y Asistencia Social (MISPAS) se reuni\u00f3 con representantes del Instituto Nacional de Bienestar Estudiantil (INABIE) y expertos en nutrici\u00f3n de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura (FAO) a fin de identificar acciones puntuales que garanticen la calidad e inocuidad de los alimentos que se suplen en los centros educativos p\u00fablicos a trav\u00e9s del programa PAE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Esta acci\u00f3n forma parte del proyecto FAO-INABIE en Rep\u00fablica Dominicana, denominado \u201cDesaf\u00edos y oportunidades de Alimentaci\u00f3n Escolar-PAE y la iniciativa \u201cEntorno Escolar Saludable\u201d, que incluye estrategias innovadoras para el fortalecimiento del Programa de Alimentaci\u00f3n Escolar (PAE).<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPretendemos mantener el acompa\u00f1amiento a INABIE porque queremos hacer cambios en los patrones alimenticios del sector estudiantil y as\u00ed mitigar enfermedades cr\u00f3nicas, (sobrepeso infantil y de salud mental), manifest\u00f3 el doctor Daniel Rivera al asegurar que pondr\u00e1n el esfuerzo necesario para mejorar la nutrici\u00f3n a trav\u00e9s del PAE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cooperaci\u00f3n de estas instituciones busca mejorar la calidad de los productos que se suplen en los plantes escolares, con miras a mitigar enfermedades cr\u00f3nicas desde este segmento poblacional. SANTO DOMINGO.&#8211; El Ministerio de Salud P\u00fablica y Asistencia Social (MISPAS) se reuni\u00f3 con representantes del Instituto Nacional de Bienestar Estudiantil (INABIE) y expertos en nutrici\u00f3n de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura (FAO) a fin de identificar acciones puntuales que garanticen la calidad e inocuidad de los alimentos que se suplen en los centros educativos p\u00fablicos a trav\u00e9s del programa PAE. Esta acci\u00f3n forma parte del proyecto FAO-INABIE en Rep\u00fablica Dominicana, denominado \u201cDesaf\u00edos y oportunidades de Alimentaci\u00f3n Escolar-PAE y la iniciativa \u201cEntorno Escolar Saludable\u201d, que incluye estrategias innovadoras para el fortalecimiento del Programa de Alimentaci\u00f3n Escolar (PAE). \u201cPretendemos mantener el acompa\u00f1amiento a INABIE porque queremos hacer cambios en los patrones alimenticios del sector estudiantil y as\u00ed mitigar enfermedades cr\u00f3nicas, (sobrepeso infantil y de salud mental), manifest\u00f3 el doctor Daniel Rivera al asegurar que pondr\u00e1n el esfuerzo necesario para mejorar la nutrici\u00f3n a trav\u00e9s del PAE.<\/p>\n","protected":false},"author":9,"featured_media":84884,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-84883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=84883"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84883\/revisions"}],"predecessor-version":[{"id":84885,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84883\/revisions\/84885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/84884"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=84883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=84883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=84883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}