{"id":84977,"date":"2022-06-26T07:05:17","date_gmt":"2022-06-26T11:05:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=84977"},"modified":"2022-06-26T07:05:18","modified_gmt":"2022-06-26T11:05:18","slug":"gobierno-realiza-jornadas-sociales-en-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/gobierno-realiza-jornadas-sociales-en-puerto-plata\/","title":{"rendered":"Gobierno realiza jornadas sociales en Puerto Plata"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/06\/gobierno-realiza-jornadas-sociales-en-puerto-plata.jpeg\" alt=\"\" class=\"wp-image-84978\" width=\"245\" height=\"126\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/06\/gobierno-realiza-jornadas-sociales-en-puerto-plata.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/06\/gobierno-realiza-jornadas-sociales-en-puerto-plata-300x155.jpeg 300w\" sizes=\"auto, (max-width: 245px) 100vw, 245px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la Rep\u00fablica Luis Abinader encabez\u00f3 una serie de jornadas sociales en esta ciudad como parte del recorrido realizado este s\u00e1bado, dentro de las cuales est\u00e1 la afiliaci\u00f3n al Servicio Nacional de Salud (Senasa).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad fue encabezada por el ministro Jos\u00e9 Ignacio Paliza, el doctor Santiago Hazim director general de Senasa, Luis Faringthon gerente regional de Senasa, Jhonny Tavarez director provincial de Salud, Jiseida Mercado representante de la DIDA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ministro Administrativo de la Presidencia, Jos\u00e9 Ignacio Paliza, explic\u00f3 que el presidente por un asunto de tiempo no pudo estar presente en esa actividad, dijo que este evento representa una gran importancia para el gobierno del presidente Luis Abinader, de garantizar la cobertura universal a los dominicanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mismo resalt\u00f3 que m\u00e1s de dos millones de dominicanos han sido incorporados dentro de la gesti\u00f3n del presidente Luis Abinader, con la garant\u00eda de que no quedar\u00e1 una persona que no tenga acceso a la afiliaci\u00f3n al Senasa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Santiago Hazim dijo que desde que llegaron al gobierno han llevado el n\u00famero de afiliados a 7 millones de personas, convirti\u00e9ndose en el principal proveedor de ese servicio y en el caso de Puerto Plata esto se refleja en un aumento de m\u00e1s de 120 mil afiliados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hazim anunci\u00f3 que la cobertura m\u00e1xima que actualmente es de un mill\u00f3n de pesos ser\u00e1 incrementado a 2 millones de pesos para que ning\u00fan ciudadano tenga que buscar la ayuda de funcionarios o legisladores para resolver un problema de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Previamente el Presidente hab\u00eda encabezado el acto de entrega de tarjetas del programa Sup\u00e9rate a miembros de la Asociaci\u00f3n de Pescadores de Puerto Plata a 300 miembros de la entidad en un acto efectuado en el Polideportivo de esta ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de este evento el mandatario particip\u00f3 en la jornada de inclusi\u00f3n social \u201cPrimero T\u00fa\u201d, en la escuela Concepci\u00f3n G\u00f3mez Matos, del sector de Padre Las Casas, ejecutada por el Programa de Proyectos Estrat\u00e9gicos y Especiales de la Presidencia (Propeep), La Gobernaci\u00f3n Civil, la Alcald\u00eda de San Felipe de Puerto Plata y Dominicana Digna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa incluy\u00f3 los servicios de oftalmolog\u00eda, odontolog\u00eda, medicina general, de cardiolog\u00eda, an\u00e1lisis para la detecci\u00f3n del c\u00e1ncer de mama, pr\u00f3stata, medicina en general y vac\u00fanate RD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se registraron j\u00f3venes para su ingreso al programa de primer empleo y optar por becas para estudiar carreras t\u00e9cnicas en las escuelas vocacionales de las FF. AA. y la Polic\u00eda Nacional, Infotep y el ITLA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Edgar Lantigua<\/strong><strong>Puerto Plata, RD<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Rep\u00fablica Luis Abinader encabez\u00f3 una serie de jornadas sociales en esta ciudad como parte del recorrido realizado este s\u00e1bado, dentro de las cuales est\u00e1 la afiliaci\u00f3n al Servicio Nacional de Salud (Senasa). La actividad fue encabezada por el ministro Jos\u00e9 Ignacio Paliza, el doctor Santiago Hazim director general de Senasa, Luis Faringthon gerente regional de Senasa, Jhonny Tavarez director provincial de Salud, Jiseida Mercado representante de la DIDA. El ministro Administrativo de la Presidencia, Jos\u00e9 Ignacio Paliza, explic\u00f3 que el presidente por un asunto de tiempo no pudo estar presente en esa actividad, dijo que este evento representa una gran importancia para el gobierno del presidente Luis Abinader, de garantizar la cobertura universal a los dominicanos. El mismo resalt\u00f3 que m\u00e1s de dos millones de dominicanos han sido incorporados dentro de la gesti\u00f3n del presidente Luis Abinader, con la garant\u00eda de que no quedar\u00e1 una persona que no tenga acceso a la afiliaci\u00f3n al Senasa. Por su parte, Santiago Hazim dijo que desde que llegaron al gobierno han llevado el n\u00famero de afiliados a 7 millones de personas, convirti\u00e9ndose en el principal proveedor de ese servicio y en el caso de Puerto Plata esto se refleja en un aumento de m\u00e1s de 120 mil afiliados. Hazim anunci\u00f3 que la cobertura m\u00e1xima que actualmente es de un mill\u00f3n de pesos ser\u00e1 incrementado a 2 millones de pesos para que ning\u00fan ciudadano tenga que buscar la ayuda de funcionarios o legisladores para resolver un problema de salud. Previamente el Presidente hab\u00eda encabezado el acto de entrega de tarjetas del programa Sup\u00e9rate a miembros de la Asociaci\u00f3n de Pescadores de Puerto Plata a 300 miembros de la entidad en un acto efectuado en el Polideportivo de esta ciudad. Luego de este evento el mandatario particip\u00f3 en la jornada de inclusi\u00f3n social \u201cPrimero T\u00fa\u201d, en la escuela Concepci\u00f3n G\u00f3mez Matos, del sector de Padre Las Casas, ejecutada por el Programa de Proyectos Estrat\u00e9gicos y Especiales de la Presidencia (Propeep), La Gobernaci\u00f3n Civil, la Alcald\u00eda de San Felipe de Puerto Plata y Dominicana Digna. El programa incluy\u00f3 los servicios de oftalmolog\u00eda, odontolog\u00eda, medicina general, de cardiolog\u00eda, an\u00e1lisis para la detecci\u00f3n del c\u00e1ncer de mama, pr\u00f3stata, medicina en general y vac\u00fanate RD. Adem\u00e1s, se registraron j\u00f3venes para su ingreso al programa de primer empleo y optar por becas para estudiar carreras t\u00e9cnicas en las escuelas vocacionales de las FF. AA. y la Polic\u00eda Nacional, Infotep y el ITLA. Edgar LantiguaPuerto Plata, RD<\/p>\n","protected":false},"author":9,"featured_media":84978,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-84977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=84977"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84977\/revisions"}],"predecessor-version":[{"id":84979,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/84977\/revisions\/84979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/84978"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=84977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=84977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=84977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}