{"id":8501,"date":"2014-09-15T18:39:05","date_gmt":"2014-09-15T22:39:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=8501"},"modified":"2014-09-15T18:39:05","modified_gmt":"2014-09-15T22:39:05","slug":"comandante-base-aerea-pp-destaca-labor-de-la-prensa-y-asegura-sera-guardian-de-esta-region","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/comandante-base-aerea-pp-destaca-labor-de-la-prensa-y-asegura-sera-guardian-de-esta-region\/","title":{"rendered":"Comandante Base A\u00e9rea PP destaca labor de la prensa y asegura ser\u00e1 guardi\u00e1n de esta regi\u00f3n"},"content":{"rendered":"<p><span style=\"color: #000000;\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/0_a_general_bapp_ll_210_120.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8502 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/0_a_general_bapp_ll_210_120.jpg\" alt=\"0_a_general_bapp_ll_210_120\" width=\"210\" height=\"120\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/0_a_general_bapp_ll_210_120.jpg 210w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/0_a_general_bapp_ll_210_120-595x340.jpg 595w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a>SOSUA.- El comandante de la Base A\u00e9rea de Puerto Plata; general de brigada piloto Richard V\u00e1squez Jim\u00e9nez, asegur\u00f3 que \u201clos representantes de los diferentes medios de comunicaci\u00f3n juegan un papel fundamental en la sociedad dominicana, ya que median entre los acontecimientos que a diario se producen entre los ciudadanos y las esferas pol\u00edtica, econ\u00f3mica, social y hasta en la militar\u201d.<\/span><!--more--><\/p>\n<p style=\"color: #000000;\">\n<p style=\"color: #000000;\">\nEl alto oficial quien fue designado comandante de esta jurisdicci\u00f3n militar que tiene su sede en la comunidad Sabaneta de Cangrejos de Puerto Plata, manifest\u00f3 que \u201clos periodistas y comunicadores en general son los intermediarios capaces de comprender, analizar y poner en contenido las ocurrencias que suceden como parte del proceso transparente que contribuye a la formaci\u00f3n de la ciudadan\u00eda en estos momentos que vivimos en democracia y en plena libertad de expresi\u00f3n, lo cual es un derecho inalienable de los pueblos\u201d.<\/p>\n<p>\u201cEstoy convencido de que ustedes como periodistas y representantes de los medios de comunicaci\u00f3n, juegan un papel importante, no solo como medio de transmisi\u00f3n de nuestros mensajes y noticias hacia el p\u00fablico, sino tambi\u00e9n como verdaderos protagonistas que pueden contribuir a crear una cultura de integraci\u00f3n para la b\u00fasqueda de soluciones de esas problem\u00e1ticas, lo que define una mejor calidad de la informaci\u00f3n\u201d, expres\u00f3.<\/p>\n<p>El general V\u00e1squez Jim\u00e9nez tambi\u00e9n agradeci\u00f3 su designaci\u00f3n al frente de esta instalaci\u00f3n militar mediante el decreto n\u00famero 302-14 del presidente de la Rep\u00fablica; licenciado Danilo Medina S\u00e1nchez, por lo cual aprovech\u00f3 la oportunidad para difundir los objetivos y acciones hacia donde dirigir\u00e1 los esfuerzos de su gesti\u00f3n estar\u00e1n orientados en desarrollar programas de planificaci\u00f3n fundamentados en la medici\u00f3n del desempe\u00f1o de los miembros de la Fuerza A\u00e9rea de la Republica Domicana (FARD) en las diferentes \u00e1reas del servicio y en las obligaciones y misiones profesionales que le sean asignadas.<\/p>\n<p>De igual manera, el comandante de la Base A\u00e9rea de Puerto Plata dijo que se compromete \u201ca ser un fiel guardi\u00e1n de la regi\u00f3n, presto siempre para garantizar la seguridad, soberan\u00eda, integridad territorial, seguridad p\u00fablica, bienestar de la poblaci\u00f3n, mantenimiento del orden p\u00fablico, la paz social, as\u00ed como apoyar los acontecimientos educativos, de salud, sociales, culturales y deportivos desarrollados en esta Regi\u00f3n Norte de la Rep\u00fablica Dominicana\u201d.<\/p>\n<p>En ese mismo tenor, asegur\u00f3 que realizar\u00e1 interacci\u00f3n con los diferentes sectores de la vida social de la regi\u00f3n, ya que esos esfuerzos estar\u00e1n fundamentados en un proceso de integraci\u00f3n comunitario que despierten mayores niveles de participaci\u00f3n de nuestras comunidades en la b\u00fasqueda de las soluciones para enfrentar los riesgos, vulnerabilidades y desaf\u00edos que nos amenacen o nos afecten.<\/p>\n<p>El comandante de la Base A\u00e9rea de Puerto Plata, asegur\u00f3 que \u201cfrente a las tendencias de las amenazas a la seguridad ciudadana que definen al siglo XXI, debemos ser capaces de construir una sociedad cimentada en la libertad de expresi\u00f3n, el pleno derecho a la informaci\u00f3n y la credibilidad de los medios, as\u00ed como el compromiso de estos con los mejores intereses nacionales y regionales\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SOSUA.- El comandante de la Base A\u00e9rea de Puerto Plata; general de brigada piloto Richard V\u00e1squez Jim\u00e9nez, asegur\u00f3 que \u201clos representantes de los diferentes medios de comunicaci\u00f3n juegan un papel fundamental en la sociedad dominicana, ya que median entre los acontecimientos que a diario se producen entre los ciudadanos y las esferas pol\u00edtica, econ\u00f3mica, social y hasta en la militar\u201d.<\/p>\n","protected":false},"author":3,"featured_media":8502,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-8501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=8501"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8501\/revisions"}],"predecessor-version":[{"id":8503,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8501\/revisions\/8503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/8502"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=8501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=8501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=8501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}