{"id":85140,"date":"2022-07-06T07:25:44","date_gmt":"2022-07-06T11:25:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=85140"},"modified":"2022-07-06T07:25:46","modified_gmt":"2022-07-06T11:25:46","slug":"premios-billboard-latinos-se-celebraran-el-29-de-septiembre","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/premios-billboard-latinos-se-celebraran-el-29-de-septiembre\/","title":{"rendered":"Premios Billboard latinos se celebrar\u00e1n el 29 de septiembre"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/espe.jpg\" alt=\"\" class=\"wp-image-85141\" width=\"219\" height=\"144\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/espe.jpg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/espe-300x199.jpg 300w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los premios Billboard de la M\u00fasica Latina se celebrar\u00e1n de forma presencial el pr\u00f3ximo 29 de septiembre en el Watsco Center de Coral Gables, en el sur de Florida (EE.UU.), seg\u00fan anunci\u00f3 este martes la cadena hispana Telemundo, uno de los organizadores del evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gala, que contar\u00e1 con actuaciones en vivo, volver\u00e1 as\u00ed al mismo escenario del a\u00f1o pasado, edici\u00f3n en la que el puertorrique\u00f1o Bad Bunny se alz\u00f3 como el triunfador de la noche al recibir diez galardones, entre ellos el de artista del a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como es habitual, una hora antes del arranque de la ceremonia, tendr\u00e1 lugar la popular alfombra roja en los exteriores de este recinto ubicado en el suroeste del condado Miami-Dade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Premios Billboard de la M\u00fasica Latina reconocen \u00ablos \u00e1lbumes, canciones e int\u00e9rpretes m\u00e1s populares en la m\u00fasica latina, seg\u00fan los resultados de ventas reales, streaming, transmisiones radiales, y redes sociales que proveen informaci\u00f3n a las listas semanales de Billboard durante un periodo de un a\u00f1o\u00bb, explic\u00f3 Telemundo en un comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gala coincidir\u00e1 con la Semana de la M\u00fasica Latina de Billboard, que como el a\u00f1o pasado tambi\u00e9n volver\u00e1 a realizarse en Miami, entre el 26 de septiembre y el 1 de octubre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se celebrar\u00e1 \u00abla m\u00fasica, la cultura y el entretenimiento latino (&#8230;) con presentaciones exclusivas, conversaciones \u00fanicas, talleres, presentaciones, eventos y experiencias exclusivas para fans\u00bb, ahond\u00f3 la cadena, que organiza este evento junto a la firma MBS Special Events.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El a\u00f1o pasado, en la ceremonia de estos premios que concede la revista especializada se rindi\u00f3 tributo al mexicano Juan Gabriel mientras que el grupo de rock Man\u00e1 y el reguetonero Daddy Yankee recibieron premios especiales en reconocimiento a su trayectoria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los premios Billboard de la M\u00fasica Latina se celebrar\u00e1n de forma presencial el pr\u00f3ximo 29 de septiembre en el Watsco Center de Coral Gables, en el sur de Florida (EE.UU.), seg\u00fan anunci\u00f3 este martes la cadena hispana Telemundo, uno de los organizadores del evento. La gala, que contar\u00e1 con actuaciones en vivo, volver\u00e1 as\u00ed al mismo escenario del a\u00f1o pasado, edici\u00f3n en la que el puertorrique\u00f1o Bad Bunny se alz\u00f3 como el triunfador de la noche al recibir diez galardones, entre ellos el de artista del a\u00f1o. Como es habitual, una hora antes del arranque de la ceremonia, tendr\u00e1 lugar la popular alfombra roja en los exteriores de este recinto ubicado en el suroeste del condado Miami-Dade. Los Premios Billboard de la M\u00fasica Latina reconocen \u00ablos \u00e1lbumes, canciones e int\u00e9rpretes m\u00e1s populares en la m\u00fasica latina, seg\u00fan los resultados de ventas reales, streaming, transmisiones radiales, y redes sociales que proveen informaci\u00f3n a las listas semanales de Billboard durante un periodo de un a\u00f1o\u00bb, explic\u00f3 Telemundo en un comunicado. La gala coincidir\u00e1 con la Semana de la M\u00fasica Latina de Billboard, que como el a\u00f1o pasado tambi\u00e9n volver\u00e1 a realizarse en Miami, entre el 26 de septiembre y el 1 de octubre. Se celebrar\u00e1 \u00abla m\u00fasica, la cultura y el entretenimiento latino (&#8230;) con presentaciones exclusivas, conversaciones \u00fanicas, talleres, presentaciones, eventos y experiencias exclusivas para fans\u00bb, ahond\u00f3 la cadena, que organiza este evento junto a la firma MBS Special Events. El a\u00f1o pasado, en la ceremonia de estos premios que concede la revista especializada se rindi\u00f3 tributo al mexicano Juan Gabriel mientras que el grupo de rock Man\u00e1 y el reguetonero Daddy Yankee recibieron premios especiales en reconocimiento a su trayectoria.<\/p>\n","protected":false},"author":9,"featured_media":85141,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-85140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=85140"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85140\/revisions"}],"predecessor-version":[{"id":85142,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85140\/revisions\/85142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/85141"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=85140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=85140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=85140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}