{"id":85255,"date":"2022-07-19T07:10:35","date_gmt":"2022-07-19T11:10:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=85255"},"modified":"2022-07-19T07:10:36","modified_gmt":"2022-07-19T11:10:36","slug":"teleferico-de-puerto-plata-acoge-concierto-jazz-en-la-montana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/teleferico-de-puerto-plata-acoge-concierto-jazz-en-la-montana\/","title":{"rendered":"Telef\u00e9rico de Puerto Plata acoge concierto Jazz en la Monta\u00f1a"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/Dominicana-Jazz-teleferico-de-Puerto-Plata-1.jpg\" alt=\"\" class=\"wp-image-85256\" width=\"197\" height=\"117\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/Dominicana-Jazz-teleferico-de-Puerto-Plata-1.jpg 374w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/Dominicana-Jazz-teleferico-de-Puerto-Plata-1-300x179.jpg 300w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">PUERTO PLATA.- Las instalaciones del telef\u00e9rico dominicano de Puerto Plata, provincia hom\u00f3nima, acogi\u00f3 el concierto Jazz en la Monta\u00f1a, iniciativa del pianista y director Oscar Micheli, con la producci\u00f3n de Gregorio P\u00e9rez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es la primera vez en sus 47 a\u00f1os de vida que el Telef\u00e9rico es sede de una actividad cultural de esta envergadura en horario nocturno y para la ocasi\u00f3n debieron subir hasta la cima de la elevaci\u00f3n Isabel de Torres, a un nutrido p\u00fablico amante de la buena m\u00fasica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El concierto estuvo a cargo de reconocidos artistas dominicanos, quienes le rindieron homenaje a los compositores puertoplate\u00f1os Juan Lockward, Rafael Solano y Luis Senior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, la Novia del Atl\u00e1ntico disfrut\u00f3 de la cantante oriunda de Santiago, Sabrina Estepan, quien interpret\u00f3 temas como En d\u00f3nde Est\u00e1s y B\u00e9same t\u00fa, de Senior, Guitarra Bohemia y Puerto Plata de Juan Lockward, y Soy tu enamorada, del maestro Solano, para cerrar con la m\u00edtica canci\u00f3n Por Amor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento, el administrador del Telef\u00e9rico, Atahualpa Paulino, agradeci\u00f3 la confianza del presidente, Luis Abinader, del ministro de Turismo, David Collado, y de los miembros del patronato para con esa instituci\u00f3n, as\u00ed como del personal t\u00e9cnico y de socorro que durante la velada dieron servicio para garantizar todo funcionara sin inconvenientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Participaron en el esperado concierto, la gobernadora de la provincia, Claritza Rochtte, y los presidentes de las asociaciones de hoteles de Playa Dorada, C\u00e9sar Jos\u00e9 de los Santos, y de Sos\u00faa y Cabarete, Humberto Pichardo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, la directora ejecutiva del Cl\u00faster Tur\u00edstico, Ambra Attus, el presidente del Grupo Rescue, Jos\u00e9 Natalio Redondo y la encargada de negocios tur\u00edsticos de Banreservas, Alidelfi Rollfo, entre otras personalidades del territorio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.- Las instalaciones del telef\u00e9rico dominicano de Puerto Plata, provincia hom\u00f3nima, acogi\u00f3 el concierto Jazz en la Monta\u00f1a, iniciativa del pianista y director Oscar Micheli, con la producci\u00f3n de Gregorio P\u00e9rez. Es la primera vez en sus 47 a\u00f1os de vida que el Telef\u00e9rico es sede de una actividad cultural de esta envergadura en horario nocturno y para la ocasi\u00f3n debieron subir hasta la cima de la elevaci\u00f3n Isabel de Torres, a un nutrido p\u00fablico amante de la buena m\u00fasica. El concierto estuvo a cargo de reconocidos artistas dominicanos, quienes le rindieron homenaje a los compositores puertoplate\u00f1os Juan Lockward, Rafael Solano y Luis Senior. Asimismo, la Novia del Atl\u00e1ntico disfrut\u00f3 de la cantante oriunda de Santiago, Sabrina Estepan, quien interpret\u00f3 temas como En d\u00f3nde Est\u00e1s y B\u00e9same t\u00fa, de Senior, Guitarra Bohemia y Puerto Plata de Juan Lockward, y Soy tu enamorada, del maestro Solano, para cerrar con la m\u00edtica canci\u00f3n Por Amor. En el evento, el administrador del Telef\u00e9rico, Atahualpa Paulino, agradeci\u00f3 la confianza del presidente, Luis Abinader, del ministro de Turismo, David Collado, y de los miembros del patronato para con esa instituci\u00f3n, as\u00ed como del personal t\u00e9cnico y de socorro que durante la velada dieron servicio para garantizar todo funcionara sin inconvenientes. Participaron en el esperado concierto, la gobernadora de la provincia, Claritza Rochtte, y los presidentes de las asociaciones de hoteles de Playa Dorada, C\u00e9sar Jos\u00e9 de los Santos, y de Sos\u00faa y Cabarete, Humberto Pichardo. Tambi\u00e9n, la directora ejecutiva del Cl\u00faster Tur\u00edstico, Ambra Attus, el presidente del Grupo Rescue, Jos\u00e9 Natalio Redondo y la encargada de negocios tur\u00edsticos de Banreservas, Alidelfi Rollfo, entre otras personalidades del territorio.<\/p>\n","protected":false},"author":9,"featured_media":85256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-85255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=85255"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85255\/revisions"}],"predecessor-version":[{"id":85257,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85255\/revisions\/85257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/85256"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=85255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=85255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=85255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}