{"id":85261,"date":"2022-07-19T18:59:50","date_gmt":"2022-07-19T22:59:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=85261"},"modified":"2022-07-19T18:59:52","modified_gmt":"2022-07-19T22:59:52","slug":"leon-que-escapo-de-villa-en-puerto-plata-es-trasladado-al-zoologico-nacional","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/leon-que-escapo-de-villa-en-puerto-plata-es-trasladado-al-zoologico-nacional\/","title":{"rendered":"Le\u00f3n que escap\u00f3 de villa en Puerto Plata es trasladado al Zool\u00f3gico Nacional"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/leon.jpg\" alt=\"\" class=\"wp-image-85262\" width=\"258\" height=\"134\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/leon.jpg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/leon-300x155.jpg 300w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Un le\u00f3n que se\u00a0<strong>escap\u00f3 de su jaula<\/strong>en un zoocriadero de Puerto Plata fue incautado y trasladado al Parque Zool\u00f3gico Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicha operaci\u00f3n fue realizada por un equipo de t\u00e9cnicos, de la Direcci\u00f3n de Biodiversidad junto a M\u00e9dicos Veterinario y Cuidadores del Parque Zool\u00f3gico Nacional (ZooDom), se procedi\u00f3 al&nbsp;<strong>rescate del felino el cual se escap\u00f3 de las instalaciones del Zoocriadero, Hacienda Altamira, ubicado en Altamira, Cupey, Puerto Plata.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>La situaci\u00f3n ser\u00e1 investigada ya que hubo un descuido que ocasion\u00f3 el escape<\/strong>, en estas instalaciones en que albergan estos animales y a los cuales este ministerio siempre se le ha dado seguimiento, como confinamiento registrado\u201d, dijo el Ministerio de Medio Ambiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Desde la ma\u00f1ana de este martes circulaba en redes sociales un video del felino fuera de su jaula.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poco despu\u00e9s del escape, miembros de los organismos de socorro y unidades policiales se mantuvieron en el \u00e1rea en espera de una comisi\u00f3n del Zool\u00f3gico Nacional y el Ministerio de Medio Ambiente.&nbsp;<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un le\u00f3n que se\u00a0escap\u00f3 de su jaulaen un zoocriadero de Puerto Plata fue incautado y trasladado al Parque Zool\u00f3gico Nacional. Dicha operaci\u00f3n fue realizada por un equipo de t\u00e9cnicos, de la Direcci\u00f3n de Biodiversidad junto a M\u00e9dicos Veterinario y Cuidadores del Parque Zool\u00f3gico Nacional (ZooDom), se procedi\u00f3 al&nbsp;rescate del felino el cual se escap\u00f3 de las instalaciones del Zoocriadero, Hacienda Altamira, ubicado en Altamira, Cupey, Puerto Plata.&nbsp; \u201cLa situaci\u00f3n ser\u00e1 investigada ya que hubo un descuido que ocasion\u00f3 el escape, en estas instalaciones en que albergan estos animales y a los cuales este ministerio siempre se le ha dado seguimiento, como confinamiento registrado\u201d, dijo el Ministerio de Medio Ambiente. Desde la ma\u00f1ana de este martes circulaba en redes sociales un video del felino fuera de su jaula. Poco despu\u00e9s del escape, miembros de los organismos de socorro y unidades policiales se mantuvieron en el \u00e1rea en espera de una comisi\u00f3n del Zool\u00f3gico Nacional y el Ministerio de Medio Ambiente.&nbsp;<\/p>\n","protected":false},"author":9,"featured_media":85262,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-85261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=85261"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85261\/revisions"}],"predecessor-version":[{"id":85263,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85261\/revisions\/85263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/85262"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=85261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=85261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=85261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}