{"id":85318,"date":"2022-07-24T08:48:02","date_gmt":"2022-07-24T12:48:02","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=85318"},"modified":"2022-07-24T08:48:04","modified_gmt":"2022-07-24T12:48:04","slug":"clientes-veran-en-factura-de-agosto-acreditacion-ordenada-por-superintendencia-de-electricidad","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/clientes-veran-en-factura-de-agosto-acreditacion-ordenada-por-superintendencia-de-electricidad\/","title":{"rendered":"Clientes ver\u00e1n en factura de agosto acreditaci\u00f3n ordenada por Superintendencia de Electricidad"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/shutterstock2083858597-17695157-focus-0.16-0.05-895-573.jpg\" alt=\"\" class=\"wp-image-85319\" width=\"218\" height=\"139\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/shutterstock2083858597-17695157-focus-0.16-0.05-895-573.jpg 895w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/shutterstock2083858597-17695157-focus-0.16-0.05-895-573-300x192.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/07\/shutterstock2083858597-17695157-focus-0.16-0.05-895-573-768x492.jpg 768w\" sizes=\"auto, (max-width: 218px) 100vw, 218px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> Los clientes de las Empresas Distribuidoras de Electricidad (EDE) deber\u00e1n ver en el monto de su pr\u00f3xima factura la decisi\u00f3n ordenada por la\u00a0<strong>Superintendencia de Electricidad<\/strong>\u00a0(SIE) de refacturar lo cobrado en julio, para acreditar o debitar, seg\u00fan corresponda en cada caso, luego de que la instituci\u00f3n revirtiera los ajustes tarifarios que hab\u00eda anunciado para el actual trimestre en el marco del Pacto El\u00e9ctrico. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a la resoluci\u00f3n SIE-068-2022-TF, la Superintendencia instruye a Edesur, Edeeste y Edenorte a refacturar a las tarifas de transici\u00f3n aplicables para el trimestre abril-junio de este 2022, las facturas emitidas en julio con las tarifas de transici\u00f3n aplicadas y dejadas sin efecto, a fines de acreditar o debitar, seg\u00fan corresponda, en la siguiente facturaci\u00f3n, la diferencia entre los precios de las tarifas de transici\u00f3n aplicadas en la resoluci\u00f3n que dispuso un incremento de 9 % a los clientes residenciales y los nuevos dispuestos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la decisi\u00f3n de la Superintendencia, para este trimestre julio-septiembre, los primeros 200 kWh que consuman los clientes residenciales de Edesur se los facturar\u00e1n a 6.05 pesos, de Edenorte 5.97 pesos y de 6.17 pesos a los de Edeeste, a diferencia de los 6.59, 6.51 y 6.73 pesos, respectivamente, que se hab\u00edan pautado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La medida se produjo dos d\u00edas despu\u00e9s de que el presidente Luis Abinader anunciara la suspensi\u00f3n de los pr\u00f3ximos ajustes trimestrales de la\u00a0<strong>tarifa el\u00e9ctrica<\/strong>\u00a0a los usuarios regulados de las EDE, que se han venido aplicando desde noviembre del a\u00f1o pasado como parte de los acuerdos arribados en el Pacto El\u00e9ctrico -que tambi\u00e9n se revisar\u00e1-, que consensuaron los partidos pol\u00edticos, empresarios y representantes de la sociedad civil. El objetivo de los ajustes tarifarios es demontar gradualmente el subsidio energ\u00e9tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de emitida la Resoluci\u00f3n No. SIE-061-2022-TF, esta Superintendencia ha verificado que las condiciones extraordinarias actuales de la situaci\u00f3n mundial, ha generado un incremento desmesurado de los precios de los combustibles, insumos indispensables para la generaci\u00f3n t\u00e9rmica de nuestra matriz energ\u00e9tica, los cuales impactan el costo de generaci\u00f3n de electricidad; el proceso de abastecimiento de las Empresas de Distribuci\u00f3n El\u00e9ctrica y el c\u00e1lculo tarifario\u201d, se\u00f1al\u00f3 la SIE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas circunstancias extraordinarias en las cuales se encuentra el mundo -agreg\u00f3-, que afectan econ\u00f3micamente tanto a nivel internacional como local, son muy distintas a las que exist\u00edan cuando se firm\u00f3 el Pacto El\u00e9ctrico. Por un imperativo social y moral, el Gobierno se ve en la necesidad de pausar el desmonte gradual del subsidio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los clientes de las Empresas Distribuidoras de Electricidad (EDE) deber\u00e1n ver en el monto de su pr\u00f3xima factura la decisi\u00f3n ordenada por la\u00a0Superintendencia de Electricidad\u00a0(SIE) de refacturar lo cobrado en julio, para acreditar o debitar, seg\u00fan corresponda en cada caso, luego de que la instituci\u00f3n revirtiera los ajustes tarifarios que hab\u00eda anunciado para el actual trimestre en el marco del Pacto El\u00e9ctrico. De acuerdo a la resoluci\u00f3n SIE-068-2022-TF, la Superintendencia instruye a Edesur, Edeeste y Edenorte a refacturar a las tarifas de transici\u00f3n aplicables para el trimestre abril-junio de este 2022, las facturas emitidas en julio con las tarifas de transici\u00f3n aplicadas y dejadas sin efecto, a fines de acreditar o debitar, seg\u00fan corresponda, en la siguiente facturaci\u00f3n, la diferencia entre los precios de las tarifas de transici\u00f3n aplicadas en la resoluci\u00f3n que dispuso un incremento de 9 % a los clientes residenciales y los nuevos dispuestos.&nbsp; Con la decisi\u00f3n de la Superintendencia, para este trimestre julio-septiembre, los primeros 200 kWh que consuman los clientes residenciales de Edesur se los facturar\u00e1n a 6.05 pesos, de Edenorte 5.97 pesos y de 6.17 pesos a los de Edeeste, a diferencia de los 6.59, 6.51 y 6.73 pesos, respectivamente, que se hab\u00edan pautado. La medida se produjo dos d\u00edas despu\u00e9s de que el presidente Luis Abinader anunciara la suspensi\u00f3n de los pr\u00f3ximos ajustes trimestrales de la\u00a0tarifa el\u00e9ctrica\u00a0a los usuarios regulados de las EDE, que se han venido aplicando desde noviembre del a\u00f1o pasado como parte de los acuerdos arribados en el Pacto El\u00e9ctrico -que tambi\u00e9n se revisar\u00e1-, que consensuaron los partidos pol\u00edticos, empresarios y representantes de la sociedad civil. El objetivo de los ajustes tarifarios es demontar gradualmente el subsidio energ\u00e9tico. Luego de emitida la Resoluci\u00f3n No. SIE-061-2022-TF, esta Superintendencia ha verificado que las condiciones extraordinarias actuales de la situaci\u00f3n mundial, ha generado un incremento desmesurado de los precios de los combustibles, insumos indispensables para la generaci\u00f3n t\u00e9rmica de nuestra matriz energ\u00e9tica, los cuales impactan el costo de generaci\u00f3n de electricidad; el proceso de abastecimiento de las Empresas de Distribuci\u00f3n El\u00e9ctrica y el c\u00e1lculo tarifario\u201d, se\u00f1al\u00f3 la SIE. \u201cLas circunstancias extraordinarias en las cuales se encuentra el mundo -agreg\u00f3-, que afectan econ\u00f3micamente tanto a nivel internacional como local, son muy distintas a las que exist\u00edan cuando se firm\u00f3 el Pacto El\u00e9ctrico. Por un imperativo social y moral, el Gobierno se ve en la necesidad de pausar el desmonte gradual del subsidio.<\/p>\n","protected":false},"author":9,"featured_media":85319,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-85318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=85318"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85318\/revisions"}],"predecessor-version":[{"id":85320,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85318\/revisions\/85320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/85319"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=85318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=85318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=85318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}