{"id":8546,"date":"2014-09-16T18:22:39","date_gmt":"2014-09-16T22:22:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=8546"},"modified":"2014-09-16T18:22:39","modified_gmt":"2014-09-16T22:22:39","slug":"caso-armando-casciati-sosua-y-la-nueva-forma-de-la-inquisicion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/caso-armando-casciati-sosua-y-la-nueva-forma-de-la-inquisicion\/","title":{"rendered":"Caso Armando Casciati: Sos\u00faa y la nueva forma de la Inquisici\u00f3n"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/armando-casciati2014.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8547 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/armando-casciati2014.jpg\" alt=\"armando casciati2014\" width=\"376\" height=\"367\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/armando-casciati2014.jpg 700w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/armando-casciati2014-300x293.jpg 300w\" sizes=\"auto, (max-width: 376px) 100vw, 376px\" \/><\/a>OPINI\u00d3N: Lic. Edgar Lantigua<br \/>\nPara nadie es un secreto que la proliferaci\u00f3n de la prostituci\u00f3n en Sos\u00faa afecta la imagen de ese destino, provoca la queja constante de sus ciudadanos y el reclamo del sector tur\u00edstico organizado para que se busque soluci\u00f3n a este problema.<!--more--><\/p>\n<p>El gran drama de la Rep\u00fablica Dominicana es que, cuando un problema se prolonga en el tiempo, pedimos la soluci\u00f3n, \u201cno importa c\u00f3mo\u201d. El drama de la prostituci\u00f3n en Sos\u00faa que creci\u00f3 durante a\u00f1os de manera alarmante, ante la mirada indiferente de todas las autoridades, hoy se pretende resolver con mecanismos de dudosa legitimidad.<\/p>\n<p>Estamos plenamente \u00a0de acuerdo que la prostituci\u00f3n tiene que sacarse del centro tur\u00edstico de Sos\u00faa, para que ese destino recupere su espacio como destino tur\u00edstico de familia.<\/p>\n<p>Todo parece indicar que la soluci\u00f3n identificada por el procurador general de la Rep\u00fablica, es una brecha legal que tiene la ley de migraci\u00f3n que establece lo siguiente:<br \/>\n\u201cCAPITULO 111: DE LOS PROCEDIMIENTOS DE INMIGRACION Y PERMANENCIA<\/p>\n<p>SECCION I: DE LA NO ADMISION<\/p>\n<p>Art. 15.-<\/p>\n<p>4. Lucrarse con la prostituci\u00f3n, el tr\u00e1fico ilegal de personas o de sus \u00f3rganos, el tr\u00e1fico ilegal de drogas o ser adicto a la misma o fomentar su USO.\u201d<\/p>\n<p>En la pr\u00e1ctica lo que se hace es que bajo este argumento se le retira la residencia que tenga la persona y se procede a su deportaci\u00f3n.<\/p>\n<p>Desde luego esto tiene de entrada el problema de que es una decisi\u00f3n m\u00e1s bien administrativa, el procurador determina que este se lucra de la prostituci\u00f3n, que se dedica al proxenetismo, a la trata de\u00a0 blancas y se procede a retirarle la residencia, anular su documento migratorio y deportarlo, no se requiere un sometimiento judicial, ni la decisi\u00f3n de un tribunal de justicia, basta con que as\u00ed lo determine el procurador.<\/p>\n<p>Nadie duda de la seriedad del procurador general, pero decisiones de este tipo que afectan la vida de personas que tienen a\u00f1os residiendo en el pa\u00eds, en algunos casos con millonarias inversiones en la zona deber\u00edan estar sujetas a un procedimiento legal, deber\u00edan ser tomadas por un tribunal de justicia y no por un funcionario, por muy serio que este sea.<\/p>\n<p>Ni que decir que de esta manera se afecta a los extranjeros acusados de proxenetismo y no as\u00ed a los dominicanos que puedan ser acusados de lo mismo. Estos no pueden ser deportados.<\/p>\n<p>Lo otro es que se hace selectivamente en este caso en Sos\u00faa, Cabarete y tal vez en Boca Chica, no he escuchado ninguna deportaci\u00f3n de extranjeros o sometimiento de dominicanos por proxenetismo y trata de blancas, en Santiago, por ejemplo, de donde es oriundo el procurador, y seg\u00fan dicen algunos, yo no lo puedo afirmar, porque no he estado all\u00ed, lugares como Pasi\u00f3n, Ilusi\u00f3n, en las afueras de la ciudad, Twenty Two sobre Colinas Mall y otros, sobreabundan de mujeres que se dedican al viejo oficio.<\/p>\n<p>Ni que decir de la prostituci\u00f3n callejera alrededor de la Plaza Valerio, del Monumento a los H\u00e9roes de la Restauraci\u00f3n, de la avenida Caama\u00f1o en Puerto Plata o el Centro de los H\u00e9roes en la capital.<\/p>\n<p>Cuando se han planteado soluciones al tema de Sos\u00faa la mayor\u00eda de las personas entiende que lo que debe hacerse es establecer una zona de tolerancia, ante este argumento se dice que eso ser\u00eda ilegal y que las autoridades no pueden favorecer este tipo de soluci\u00f3n.<\/p>\n<p>El procurador general de la Rep\u00fablica que ha ocupado esa posici\u00f3n del 2004 al 2006, y ahora lleva dos a\u00f1os en el cargo, que fue fiscal del Distrito Nacional del 97 al 2000 y que fue senador del 2006 al 2010, es decir ha estado del lado de hacer cumplir la ley y del lado de redactar la ley, ha tenido tiempo de buscar una soluci\u00f3n, verdaderamente sensata, incluso si esta hubiera implicado someter la aprobaci\u00f3n de una ley que regule esas pr\u00e1cticas en el pa\u00eds.<\/p>\n<p>Se prefiere sin embargo la propuesta quijotesca de pretender eliminar lo que no ha podido eliminar ni la religi\u00f3n, ni el comunismo, solo el m\u00e1s extremo fundamentalismo religioso ha podido contener, en algunos lugares del mundo, la prostituci\u00f3n. Pretender con medidas de franca inquisici\u00f3n como la deportaci\u00f3n de extranjeros resolver el problema es no solo ut\u00f3pico sino adem\u00e1s risible.<\/p>\n<p>Sos\u00faa requiere una soluci\u00f3n racional del tema de la prostituci\u00f3n que no parece ser otro que establecer un \u00e1rea, una zona en donde eso se d\u00e9, lejos del ambiente tur\u00edstico familiar. Para eso es necesaria la participaci\u00f3n de todos los sectores en identificar soluciones.<\/p>\n<p>El caso m\u00e1s reciente, el del empresario italiano Armando Casciati es bastante ilustrativo de los riesgos del proceder decidido por el licenciado Dom\u00ednguez Brito, algunos dicen que con el asentimiento del mismo presidente Danilo Medina.<\/p>\n<p>De entrada, su deportaci\u00f3n bajo el argumento de proxenetismo entra en contradicci\u00f3n con la excepci\u00f3n establecida por esa misma ley 285-04, que expresa claramente:<\/p>\n<p>\u201cArt\u00edculo.- 123 Podr\u00e1 no ordenarse la deportaci\u00f3n o expulsi\u00f3n del extranjero prevista en los art\u00edculos anteriores, de la presente ley, en los casos siguientes:<\/p>\n<p>B) Cuando tuviere una residencia legal, pac\u00edfica y continua en el pa\u00eds superior a los 10 a\u00f1os , a partir de su ingreso legal correspondiente.\u201d<\/p>\n<p>Casciati tiene m\u00e1s de catorce a\u00f1os residiendo en el pa\u00eds.<\/p>\n<p>Las inversiones principales de Armando Casciati en Sos\u00faa, son el hotel Sos\u00faa Bay, el Sos\u00faa Bay Convention Center, el canal de televisi\u00f3n Costa Norte Network y otras inversiones inmobiliarias que hoy en d\u00eda son improductivas por la merma en el turismo de Sos\u00faa.<\/p>\n<p>No bastaba, si el problema era el manejo de sus centros nocturnos Merengue Bar, D\u00b4Clase y otros propiedad del empresario, el cierre de estos previa comprobaci\u00f3n de la comisi\u00f3n de il\u00edcitos contemplados en el c\u00f3digo penal dominicano.<\/p>\n<p>\u00bfQu\u00e9 acciones, tomar\u00e1 la procuradur\u00eda y el grupo de empresarios y autoridades tur\u00edsticas que promueven esta cruzada inquisitoria, contra los due\u00f1os de negocios de similar jaez, que son dominicanos y que no pueden ser deportados?<\/p>\n<p>\u00bfEs este el mensaje que le damos a inversionistas internacionales que vienen al pa\u00eds e invierten 20, 30 0 40 millones de d\u00f3lares, en negocios que luego no tienen el retorno esperado?<\/p>\n<p>\u00bfFortalecen estas acciones el clima de inversi\u00f3n en el pa\u00eds?<\/p>\n<p>La Rep\u00fablica Dominicana ha estrenado hace poco un Tribunal Constitucional, en muchos lugares llamado de: \u201cGarant\u00edas Constitucionales\u201d, este tipo de acciones garantizan el debido proceso, de que tanto habla el Ministerio P\u00fablico? No se han violentado en la misma derechos fundamentales de este empresario extranjero con cuantiosas inversiones en el pa\u00eds y con m\u00e1s de 10 a\u00f1os \u201cresidiendo de manera legal y pac\u00edfica\u201d en el pa\u00eds?<\/p>\n<p>Obs\u00e9rvese que no estamos haciendo juicios de valor sobre las acusaciones de que ha sido objeto Casciati en el pasado, sencillamente porque no ha sido condenado por un tribunal por ninguna de ellas.<\/p>\n<p>Cualquiera puede sentirse tentado a pensar que esto forme parte de un plan para que, deportado del pa\u00eds, \u00e9ste se vea forzado a vender las cuantiosas inversiones que tiene a precios de \u201cvaca muerta\u201d.<\/p>\n<p>La inquisici\u00f3n moderna iniciada por el procurador a instancias de empresarios y autoridades de turismo de la zona, dista mucho de ser la soluci\u00f3n al problema de\u00a0 Sos\u00faa.<\/p>\n<p>Cualquier actuaci\u00f3n sensata y racional en esa direcci\u00f3n contar\u00eda con nuestro respaldo, acciones draconianas, unilaterales y a todas luces selectivas como estas no.<\/p>\n<p>Ojal\u00e1 se reflexionara sobre el tema independientemente de si Armando Casciati nos cae bien o no.<\/p>\n<p>&nbsp;<\/p>\n<p>Por: Lic. Edgar Lantigua<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OPINI\u00d3N: Lic. Edgar Lantigua Para nadie es un secreto que la proliferaci\u00f3n de la prostituci\u00f3n en Sos\u00faa afecta la imagen de ese destino, provoca la queja constante de sus ciudadanos y el reclamo del sector tur\u00edstico organizado para que se busque soluci\u00f3n a este problema.<\/p>\n","protected":false},"author":3,"featured_media":8547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-8546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=8546"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8546\/revisions"}],"predecessor-version":[{"id":8548,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8546\/revisions\/8548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/8547"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=8546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=8546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=8546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}