{"id":85598,"date":"2022-08-10T13:34:01","date_gmt":"2022-08-10T17:34:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=85598"},"modified":"2022-08-10T13:34:05","modified_gmt":"2022-08-10T17:34:05","slug":"identifican-los-cuerpos-de-dos-jovenes-hallados-calcinados-cerca-de-un-cementerio-en-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/identifican-los-cuerpos-de-dos-jovenes-hallados-calcinados-cerca-de-un-cementerio-en-puerto-plata\/","title":{"rendered":"Identifican los cuerpos de dos j\u00f3venes hallados calcinados cerca de un cementerio en Puerto Plata"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/08\/san.jpg\" alt=\"\" class=\"wp-image-85599\" width=\"214\" height=\"141\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/08\/san.jpg 384w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/08\/san-300x198.jpg 300w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los cuerpos de dos j\u00f3venes fueron encontrados calcinados en las cercan\u00edas del cementerio de la comunidad de Marmolejos, del municipio de Los Hidalgos, Puerto Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las v\u00edctimas fueron identificadas como<strong>&nbsp;Estefan Rafael Dom\u00ednguez Hidalgo&nbsp;<\/strong>de 29 a\u00f1os, y&nbsp;<strong>Olenny De Jes\u00fas Luna Disla<\/strong>, de 23 a\u00f1os, quienes presuntamente eran empleados de bancas de loter\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus cuerpos fueron impactados de bala y luego quemados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El caso es investigado por efectivos de la Direcci\u00f3n Central de Investigaciones Criminales, DICRIM de la Polic\u00eda Nacional quienes a\u00fan no han ofrecido detalles del hecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan versiones que circulan en el municipio de Los Hidalgos, los cuerpos fueron incendiados cerca del cementerio y del rio de la comunidad de Marmolejos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cuerpos de dos j\u00f3venes fueron encontrados calcinados en las cercan\u00edas del cementerio de la comunidad de Marmolejos, del municipio de Los Hidalgos, Puerto Plata. Las v\u00edctimas fueron identificadas como&nbsp;Estefan Rafael Dom\u00ednguez Hidalgo&nbsp;de 29 a\u00f1os, y&nbsp;Olenny De Jes\u00fas Luna Disla, de 23 a\u00f1os, quienes presuntamente eran empleados de bancas de loter\u00eda. Sus cuerpos fueron impactados de bala y luego quemados. El caso es investigado por efectivos de la Direcci\u00f3n Central de Investigaciones Criminales, DICRIM de la Polic\u00eda Nacional quienes a\u00fan no han ofrecido detalles del hecho. Seg\u00fan versiones que circulan en el municipio de Los Hidalgos, los cuerpos fueron incendiados cerca del cementerio y del rio de la comunidad de Marmolejos.<\/p>\n","protected":false},"author":9,"featured_media":85599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-85598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=85598"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85598\/revisions"}],"predecessor-version":[{"id":85600,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85598\/revisions\/85600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/85599"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=85598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=85598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=85598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}