{"id":85670,"date":"2022-08-20T07:35:42","date_gmt":"2022-08-20T11:35:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=85670"},"modified":"2022-08-20T07:35:43","modified_gmt":"2022-08-20T11:35:43","slug":"p-plata-dictan-20-anos-prision-a-dos-mataron-hombre-para-robarle","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/p-plata-dictan-20-anos-prision-a-dos-mataron-hombre-para-robarle\/","title":{"rendered":"P. PLATA: Dictan 20 a\u00f1os prisi\u00f3n a dos mataron hombre para robarle"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/08\/Untitled-30.jpg\" alt=\"\" class=\"wp-image-85671\" width=\"192\" height=\"120\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/08\/Untitled-30.jpg 772w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/08\/Untitled-30-300x187.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/08\/Untitled-30-768x479.jpg 768w\" sizes=\"auto, (max-width: 192px) 100vw, 192px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">PUERTO PLATA, Rep\u00fablica Dominicana.-&nbsp;El Tribunal Colegiado de esta jurisdicci\u00f3n conden\u00f3 a 20 a\u00f1os de prisi\u00f3n a dos hombres que asesinaron a otro para robarle en el distrito municipal Cabarete, de Sos\u00faa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Odeny Alberto Tavares Toribio (Patr\u00f3n Vaper) y Jonathan Antonio Mart\u00ednez Castillo (Kinito) fueron enviados al Centro de Correcci\u00f3n y Rehabilitaci\u00f3n San Felipe, de esta ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La acusaci\u00f3n instrumentada por el fiscalizador Leury Ure\u00f1a indica que el 28 de agosto de 2020, mientras Marcel Demeusy y Anthony Dicroce se encontraban en la playa Encuentro, organiz\u00e1ndose para salir a pescar, fueron interceptados por los hoy condenados, quienes les robaron, los golpearon y provocaron la muerte de Dicrose.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de las pruebas documentales, audiovisuales y testimoniales, la representante del Ministerio P\u00fablico Ana Mariela Hern\u00e1ndez demostr\u00f3 la culpabilidad de los procesados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA, Rep\u00fablica Dominicana.-&nbsp;El Tribunal Colegiado de esta jurisdicci\u00f3n conden\u00f3 a 20 a\u00f1os de prisi\u00f3n a dos hombres que asesinaron a otro para robarle en el distrito municipal Cabarete, de Sos\u00faa. Odeny Alberto Tavares Toribio (Patr\u00f3n Vaper) y Jonathan Antonio Mart\u00ednez Castillo (Kinito) fueron enviados al Centro de Correcci\u00f3n y Rehabilitaci\u00f3n San Felipe, de esta ciudad. La acusaci\u00f3n instrumentada por el fiscalizador Leury Ure\u00f1a indica que el 28 de agosto de 2020, mientras Marcel Demeusy y Anthony Dicroce se encontraban en la playa Encuentro, organiz\u00e1ndose para salir a pescar, fueron interceptados por los hoy condenados, quienes les robaron, los golpearon y provocaron la muerte de Dicrose. A trav\u00e9s de las pruebas documentales, audiovisuales y testimoniales, la representante del Ministerio P\u00fablico Ana Mariela Hern\u00e1ndez demostr\u00f3 la culpabilidad de los procesados.<\/p>\n","protected":false},"author":9,"featured_media":85671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-85670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=85670"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85670\/revisions"}],"predecessor-version":[{"id":85672,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/85670\/revisions\/85672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/85671"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=85670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=85670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=85670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}