{"id":86459,"date":"2022-10-24T08:07:56","date_gmt":"2022-10-24T12:07:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86459"},"modified":"2022-10-24T08:07:58","modified_gmt":"2022-10-24T12:07:58","slug":"el-dengue-ha-matado-a-37-personas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-dengue-ha-matado-a-37-personas\/","title":{"rendered":"El dengue ha matado a 37 personas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"171\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/10\/den.jpg\" alt=\"\" class=\"wp-image-86460\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/10\/den.jpg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/10\/den-300x155.jpg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Tres nuevas muertes por dengue entraron al sistema de vigilancia epidemiol\u00f3gica, con lo que suman 37 las defunciones&nbsp; provocadas por esta enfermedad en el pa\u00eds hasta el primero de este mes, con m\u00e1s de 6,600 infectados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras, las autoridades sanitarias instruyeron a las direcciones provinciales a redoblar medidas preventivas contra dengue, malaria, leptospirosis y c\u00f3lera, priorizando los lugares donde hay mayor incidencia, sobre todo del dengue, con operativos de fumigaci\u00f3n, limpieza de espacios y eliminaci\u00f3n de artefactos que puedan convertirse en criaderos del mosquito transmisor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los registros epidemiol\u00f3gicos hasta el primero de&nbsp; octubre recogen un incremento de los casos de dengue que superan en 242% los notificados el a\u00f1o pasado a la misma fecha. En la \u00faltima semana se captaron 482 casos probables de dengue, de los cuales el 56% son pacientes procedentes de Santiago, Santo Domingo, Duarte, S\u00e1nchez Ram\u00edrez, La Vega y San Juan.&nbsp; Indica que durante las \u00faltimas cuatro semanas se registraron 1,737 casos de dengue, para un acumulado de 6,601 incluyendo 37 fallecimientos que a\u00fan no han sido auditados por el Comit\u00e9 Interinstitucional de Auditor\u00eda Cl\u00ednica.&nbsp; A nivel nacional circula el tipo DEN-2, mientras el DEN-1 se detect\u00f3 en la provincia Duarte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Covid-19 y malaria<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En torno al Covid-19, el pa\u00eds contin\u00faa notificando baja incidencia, registrando ayer 35 nuevos casos, captados en 1,573 muestras analizadas y nueve pacientes hospitalizados. Los casos activos suman 244 y la positividad diaria se coloc\u00f3 en 3.44% y la acumulada de las \u00faltimas cuatro semanas en 1.66%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tres nuevas muertes por dengue entraron al sistema de vigilancia epidemiol\u00f3gica, con lo que suman 37 las defunciones&nbsp; provocadas por esta enfermedad en el pa\u00eds hasta el primero de este mes, con m\u00e1s de 6,600 infectados. Mientras, las autoridades sanitarias instruyeron a las direcciones provinciales a redoblar medidas preventivas contra dengue, malaria, leptospirosis y c\u00f3lera, priorizando los lugares donde hay mayor incidencia, sobre todo del dengue, con operativos de fumigaci\u00f3n, limpieza de espacios y eliminaci\u00f3n de artefactos que puedan convertirse en criaderos del mosquito transmisor. Los registros epidemiol\u00f3gicos hasta el primero de&nbsp; octubre recogen un incremento de los casos de dengue que superan en 242% los notificados el a\u00f1o pasado a la misma fecha. En la \u00faltima semana se captaron 482 casos probables de dengue, de los cuales el 56% son pacientes procedentes de Santiago, Santo Domingo, Duarte, S\u00e1nchez Ram\u00edrez, La Vega y San Juan.&nbsp; Indica que durante las \u00faltimas cuatro semanas se registraron 1,737 casos de dengue, para un acumulado de 6,601 incluyendo 37 fallecimientos que a\u00fan no han sido auditados por el Comit\u00e9 Interinstitucional de Auditor\u00eda Cl\u00ednica.&nbsp; A nivel nacional circula el tipo DEN-2, mientras el DEN-1 se detect\u00f3 en la provincia Duarte. Covid-19 y malaria En torno al Covid-19, el pa\u00eds contin\u00faa notificando baja incidencia, registrando ayer 35 nuevos casos, captados en 1,573 muestras analizadas y nueve pacientes hospitalizados. Los casos activos suman 244 y la positividad diaria se coloc\u00f3 en 3.44% y la acumulada de las \u00faltimas cuatro semanas en 1.66%.<\/p>\n","protected":false},"author":9,"featured_media":86460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-86459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86459"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86459\/revisions"}],"predecessor-version":[{"id":86461,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86459\/revisions\/86461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86460"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}