{"id":86727,"date":"2022-11-07T15:43:05","date_gmt":"2022-11-07T19:43:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86727"},"modified":"2022-11-07T15:43:10","modified_gmt":"2022-11-07T19:43:10","slug":"embajada-de-japon-entrega-4-nuevas-aulas-escuela-padre-arturo-de-monte-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/embajada-de-japon-entrega-4-nuevas-aulas-escuela-padre-arturo-de-monte-plata\/","title":{"rendered":"Embajada de Jap\u00f3n entrega 4 nuevas aulas escuela Padre Arturo de Monte Plata"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/embajada-de-japon-entrega-4-nuevas-aulas-escuela-padre-arturo-de-monte-plata.jpeg\" alt=\"\" class=\"wp-image-86728\" width=\"241\" height=\"124\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/embajada-de-japon-entrega-4-nuevas-aulas-escuela-padre-arturo-de-monte-plata.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/embajada-de-japon-entrega-4-nuevas-aulas-escuela-padre-arturo-de-monte-plata-300x155.jpeg 300w\" sizes=\"auto, (max-width: 241px) 100vw, 241px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El embajador de Jap\u00f3n en Rep\u00fablica Dominicana, Takagi Masahiro, encabez\u00f3 el acto de entrega de cuatro nuevas aulas, que se suman a las acciones de colaboraci\u00f3n que esa naci\u00f3n ha hecho durante varias d\u00e9cadas a la escuela Padre Arturo de esta localidad de Monte Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Takagi Masahiro dijo que esta vez la inversi\u00f3n para la obra supera los 91,000 d\u00f3lares, a fin de mejorar las condiciones en las que reciben docencia 1,400 alumnos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diplom\u00e1tico record\u00f3 que es la tercera vez que visita esta escuela, con el prop\u00f3sito de aportar a la educaci\u00f3n. Estuvo en 1998, luego del paso del hurac\u00e1n George, tambi\u00e9n en el 2014 y&nbsp; ahora en 2022, siempre haciendo \u00e9nfasis en&nbsp; elogiar el nivel y la calidad de la ense\u00f1anza que se imparte en este centro educativo. Asimismo, reiterando su disposici\u00f3n de continuar colaborando con el mismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resalt\u00f3 que dicha colaboraci\u00f3n est\u00e1 contenida en el marco del programa de cooperaci\u00f3n econ\u00f3mica no reembolsable o donaci\u00f3n del pueblo japon\u00e9s para la Rep\u00fablica Dominicana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que la directora de la escuela, Teresa Pag\u00e1n agradeci\u00f3 profundamente el gesto de la embajada japon\u00e9s, asegurando que,&nbsp;<strong>\u00b4\u00b4de no ser por su colaboraci\u00f3n incondicional, hoy cientos de ni\u00f1os estuvieran en las calles por falta de cupo escolar\u00b4<\/strong>\u00b4, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pag\u00e1n aprovech\u00f3 para recordar a las autoridades de Educaci\u00f3n que el plantel&nbsp; a\u00fan necesita de tres aulas, tambi\u00e9n carece de docentes y personal de apoyo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el corte de la cinta, el embajador Masahiro estuvo acompa\u00f1ado de la directora, Teresa Pag\u00e1n; el senador Lenin Valdez; la gobernadora Rafaela Javier; la alcaldesa Altagracia Herrera, el viceministro de Educaci\u00f3n, Oscar Camargo; el director regional de Educaci\u00f3n, Buenaventura de la Cruz; la directora del Distrito Escolar 17-02, Natividad Custodio; el sacerdote C\u00e9sar Peralta; el presidente de la Asociaci\u00f3n de Padres y Amigos de la Escuela, Captulo Espinosa, profesores y otras personalidades vinculadas al quehacer educativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El embajador de Jap\u00f3n en Rep\u00fablica Dominicana, Takagi Masahiro, encabez\u00f3 el acto de entrega de cuatro nuevas aulas, que se suman a las acciones de colaboraci\u00f3n que esa naci\u00f3n ha hecho durante varias d\u00e9cadas a la escuela Padre Arturo de esta localidad de Monte Plata. &nbsp;Takagi Masahiro dijo que esta vez la inversi\u00f3n para la obra supera los 91,000 d\u00f3lares, a fin de mejorar las condiciones en las que reciben docencia 1,400 alumnos. El diplom\u00e1tico record\u00f3 que es la tercera vez que visita esta escuela, con el prop\u00f3sito de aportar a la educaci\u00f3n. Estuvo en 1998, luego del paso del hurac\u00e1n George, tambi\u00e9n en el 2014 y&nbsp; ahora en 2022, siempre haciendo \u00e9nfasis en&nbsp; elogiar el nivel y la calidad de la ense\u00f1anza que se imparte en este centro educativo. Asimismo, reiterando su disposici\u00f3n de continuar colaborando con el mismo. Resalt\u00f3 que dicha colaboraci\u00f3n est\u00e1 contenida en el marco del programa de cooperaci\u00f3n econ\u00f3mica no reembolsable o donaci\u00f3n del pueblo japon\u00e9s para la Rep\u00fablica Dominicana.&nbsp; Mientras que la directora de la escuela, Teresa Pag\u00e1n agradeci\u00f3 profundamente el gesto de la embajada japon\u00e9s, asegurando que,&nbsp;\u00b4\u00b4de no ser por su colaboraci\u00f3n incondicional, hoy cientos de ni\u00f1os estuvieran en las calles por falta de cupo escolar\u00b4\u00b4, dijo. Pag\u00e1n aprovech\u00f3 para recordar a las autoridades de Educaci\u00f3n que el plantel&nbsp; a\u00fan necesita de tres aulas, tambi\u00e9n carece de docentes y personal de apoyo. Durante el corte de la cinta, el embajador Masahiro estuvo acompa\u00f1ado de la directora, Teresa Pag\u00e1n; el senador Lenin Valdez; la gobernadora Rafaela Javier; la alcaldesa Altagracia Herrera, el viceministro de Educaci\u00f3n, Oscar Camargo; el director regional de Educaci\u00f3n, Buenaventura de la Cruz; la directora del Distrito Escolar 17-02, Natividad Custodio; el sacerdote C\u00e9sar Peralta; el presidente de la Asociaci\u00f3n de Padres y Amigos de la Escuela, Captulo Espinosa, profesores y otras personalidades vinculadas al quehacer educativo.<\/p>\n","protected":false},"author":9,"featured_media":86728,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-86727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86727"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86727\/revisions"}],"predecessor-version":[{"id":86729,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86727\/revisions\/86729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86728"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}