{"id":86733,"date":"2022-11-07T15:48:33","date_gmt":"2022-11-07T19:48:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86733"},"modified":"2022-11-07T15:48:34","modified_gmt":"2022-11-07T19:48:34","slug":"esta-es-la-directora-confirmada-para-venom-3","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/esta-es-la-directora-confirmada-para-venom-3\/","title":{"rendered":"Esta es la directora confirmada para \u00abVenom 3"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"895\" height=\"573\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/venom-3-c865952a-focus-0-0-895-573.jpg\" alt=\"\" class=\"wp-image-86734\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/venom-3-c865952a-focus-0-0-895-573.jpg 895w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/venom-3-c865952a-focus-0-0-895-573-300x192.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/venom-3-c865952a-focus-0-0-895-573-768x492.jpg 768w\" sizes=\"auto, (max-width: 895px) 100vw, 895px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab<strong>Venom 3<\/strong>\u00bb ser\u00e1 la tercera entrada de Venom en lo que es el Universo de Personajes de Spider-Man que Sony est\u00e1 desarrollando y que tiene v\u00ednculos con el Universo Cinematogr\u00e1fico de&nbsp;<strong>Marvel<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con Tom Hardy a la cabeza, encarnando a Eddie Brock, ahora se conoci\u00f3 que la pel\u00edcula ya encontr\u00f3 a su directora. Y se trata de Kelly Marcel, que ya trabaj\u00f3 en la franquicia Venom.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marcel coescribi\u00f3 Venom, escribi\u00f3 el gui\u00f3n de \u00abVenom: Let There Be Carnage\u00bb y ahora estar\u00e1 tras la silla de la directora, seg\u00fan inform\u00f3 Deadline.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marcel tambi\u00e9n trabaj\u00f3 como guionista adaptando Fifty Shades of Grey en 2015 y tambi\u00e9n coescribi\u00f3 Saving Mr. Banks en 2013.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 la primera mujer y ahora la tercera tras la silla de la direcci\u00f3n de la franquicia Venom, luego de que Ruben Fleischer dirigiera la cinta original y que Andy Serkis dirigiera la segunda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed las cosas, ser\u00e1 la primera vez que Kelly Marcel tenga a cargo la direcci\u00f3n de una pel\u00edcula.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y t\u00fa, \u00bfhas visto la franquicia Venom?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abVenom 3\u00bb ser\u00e1 la tercera entrada de Venom en lo que es el Universo de Personajes de Spider-Man que Sony est\u00e1 desarrollando y que tiene v\u00ednculos con el Universo Cinematogr\u00e1fico de&nbsp;Marvel. Con Tom Hardy a la cabeza, encarnando a Eddie Brock, ahora se conoci\u00f3 que la pel\u00edcula ya encontr\u00f3 a su directora. Y se trata de Kelly Marcel, que ya trabaj\u00f3 en la franquicia Venom. Marcel coescribi\u00f3 Venom, escribi\u00f3 el gui\u00f3n de \u00abVenom: Let There Be Carnage\u00bb y ahora estar\u00e1 tras la silla de la directora, seg\u00fan inform\u00f3 Deadline. Marcel tambi\u00e9n trabaj\u00f3 como guionista adaptando Fifty Shades of Grey en 2015 y tambi\u00e9n coescribi\u00f3 Saving Mr. Banks en 2013.&nbsp; Ser\u00e1 la primera mujer y ahora la tercera tras la silla de la direcci\u00f3n de la franquicia Venom, luego de que Ruben Fleischer dirigiera la cinta original y que Andy Serkis dirigiera la segunda. As\u00ed las cosas, ser\u00e1 la primera vez que Kelly Marcel tenga a cargo la direcci\u00f3n de una pel\u00edcula.&nbsp; Y t\u00fa, \u00bfhas visto la franquicia Venom?<\/p>\n","protected":false},"author":9,"featured_media":86734,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[387],"tags":[],"class_list":["post-86733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86733"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86733\/revisions"}],"predecessor-version":[{"id":86735,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86733\/revisions\/86735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86734"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}