{"id":86736,"date":"2022-11-07T15:51:52","date_gmt":"2022-11-07T19:51:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86736"},"modified":"2022-11-07T15:51:54","modified_gmt":"2022-11-07T19:51:54","slug":"el-cohete-sls-de-la-nasa-regresa-a-la-plataforma-de-lanzamiento","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-cohete-sls-de-la-nasa-regresa-a-la-plataforma-de-lanzamiento\/","title":{"rendered":"El cohete SLS de la NASA regresa a la plataforma de lanzamiento"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"895\" height=\"573\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/cohete-03a85a20-focus-0-0.4-895-573.jpg\" alt=\"\" class=\"wp-image-86737\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/cohete-03a85a20-focus-0-0.4-895-573.jpg 895w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/cohete-03a85a20-focus-0-0.4-895-573-300x192.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/cohete-03a85a20-focus-0-0.4-895-573-768x492.jpg 768w\" sizes=\"auto, (max-width: 895px) 100vw, 895px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;<strong>cohete SLS<\/strong>&nbsp;regres\u00f3 este viernes a su plataforma de&nbsp;<strong>lanzamiento<\/strong>&nbsp;en el estado de Florida para un nuevo intento de despegue a la Luna dentro de diez d\u00edas, retomando el demorado comienzo de Artemis, el nuevo programa insignia de la agencia espacial estadounidense (<strong>NASA<\/strong>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de dos aplazamientos por problemas t\u00e9cnicos, el cohete debi\u00f3 ser devuelto a hangar a fines de septiembre para protegerlo del paso del hurac\u00e1n Ian.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El viaje de casi 1,6 km desde el hangar hasta la plataforma de&nbsp;<strong>lanzamiento<\/strong>&nbsp;del Centro Espacial Kennedy en Florida (sureste) tom\u00f3 cerca de nueve horas y el cohete de 98 metros de altura debi\u00f3 ser transportado muy lentamente sobre una gigantesca plataforma rodante para evitar vibraciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>NASA<\/strong>&nbsp;hab\u00eda anunciado a mediados de octubre una nueva ventana de&nbsp;<strong>lanzamiento<\/strong>, con una duraci\u00f3n de 69 minutos, el 14 de noviembre a las 00H07 locales (04H07 GMT), con fechas de respaldo los d\u00edas 16 a las 01H04 y 19 a las 01H45 locales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNos sentimos c\u00f3modos con la idea de lanzar en la noche\u00bb, afirm\u00f3 Jim Free, administrador asociado de la&nbsp;<strong>NASA<\/strong>, en conferencia de prensa el jueves, y agreg\u00f3 que los datos necesarios para analizar el desempe\u00f1o de este nuevo veh\u00edculo se recopilar\u00e1n mediante radares y c\u00e1maras infrarrojas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si el&nbsp;<strong>lanzamiento<\/strong>&nbsp;tiene \u00e9xito, la misi\u00f3n durar\u00e1 poco m\u00e1s de 25 d\u00edas, con un aterrizaje en el Oc\u00e9ano Pac\u00edfico previsto para el 9 de diciembre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Planes ambiciosos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La misi\u00f3n Artemis 1 busca probar al&nbsp;<strong>cohete SLS<\/strong>&nbsp;(Sistema de&nbsp;<strong>Lanzamiento<\/strong>&nbsp;Espacial) y a la c\u00e1psula Orion, adosada a la parte superior del cohete, sea segura para transportar astronautas en el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La c\u00e1psula ser\u00e1 propulsada 64.000 km m\u00e1s all\u00e1 de la Luna, aventur\u00e1ndose m\u00e1s lejos que cualquier otra nave espacial tripulada lanzada anteriormente anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su regreso a la atm\u00f3sfera terrestre, deber\u00e1 soportar una velocidad de 40.000 km\/h y una temperatura equivalente a la mitad de la que se registra en la superficie del Sol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una misi\u00f3n exitosa ser\u00e1 un gran alivio para la&nbsp;<strong>NASA<\/strong>, tras a\u00f1os de retrasos y sobrecostos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pr\u00f3xima misi\u00f3n, Artemis 2, prevista para 2024, transportar\u00e1 astronautas pero no alunizar\u00e1. Ese honor ser\u00e1 reservado para la tripulaci\u00f3n de Artemis 3, a ser lanzada no antes de 2025. Despu\u00e9s, la&nbsp;<strong>NASA<\/strong>&nbsp;espera realizar aproximadamente una misi\u00f3n al a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El plan de la agencia estadounidense es construir una estaci\u00f3n espacial en la \u00f3rbita lunar, llamada Gateway, y una base en la superficie de la Luna, para probar all\u00ed las tecnolog\u00edas necesarias que permitan enviar a los primeros humanos a Marte: nuevos trajes, un veh\u00edculo para desplazarse o un posible uso del agua lunar, entre otros objetivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La misi\u00f3n Artemis lleva el nombre de la hermana gemela del dios griego Apollo, que dio nombre a las primeras misiones lunares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A diferencia de aquellas misiones que enviaron solo hombres blancos a la Luna entre 1969 y 1972, el programa Artemis ver\u00e1 a la primera persona negra y a la primera mujer pisar la superficie lunar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;cohete SLS&nbsp;regres\u00f3 este viernes a su plataforma de&nbsp;lanzamiento&nbsp;en el estado de Florida para un nuevo intento de despegue a la Luna dentro de diez d\u00edas, retomando el demorado comienzo de Artemis, el nuevo programa insignia de la agencia espacial estadounidense (NASA). Despu\u00e9s de dos aplazamientos por problemas t\u00e9cnicos, el cohete debi\u00f3 ser devuelto a hangar a fines de septiembre para protegerlo del paso del hurac\u00e1n Ian. El viaje de casi 1,6 km desde el hangar hasta la plataforma de&nbsp;lanzamiento&nbsp;del Centro Espacial Kennedy en Florida (sureste) tom\u00f3 cerca de nueve horas y el cohete de 98 metros de altura debi\u00f3 ser transportado muy lentamente sobre una gigantesca plataforma rodante para evitar vibraciones. La&nbsp;NASA&nbsp;hab\u00eda anunciado a mediados de octubre una nueva ventana de&nbsp;lanzamiento, con una duraci\u00f3n de 69 minutos, el 14 de noviembre a las 00H07 locales (04H07 GMT), con fechas de respaldo los d\u00edas 16 a las 01H04 y 19 a las 01H45 locales. \u00abNos sentimos c\u00f3modos con la idea de lanzar en la noche\u00bb, afirm\u00f3 Jim Free, administrador asociado de la&nbsp;NASA, en conferencia de prensa el jueves, y agreg\u00f3 que los datos necesarios para analizar el desempe\u00f1o de este nuevo veh\u00edculo se recopilar\u00e1n mediante radares y c\u00e1maras infrarrojas. Si el&nbsp;lanzamiento&nbsp;tiene \u00e9xito, la misi\u00f3n durar\u00e1 poco m\u00e1s de 25 d\u00edas, con un aterrizaje en el Oc\u00e9ano Pac\u00edfico previsto para el 9 de diciembre. Planes ambiciosos La misi\u00f3n Artemis 1 busca probar al&nbsp;cohete SLS&nbsp;(Sistema de&nbsp;Lanzamiento&nbsp;Espacial) y a la c\u00e1psula Orion, adosada a la parte superior del cohete, sea segura para transportar astronautas en el futuro. La c\u00e1psula ser\u00e1 propulsada 64.000 km m\u00e1s all\u00e1 de la Luna, aventur\u00e1ndose m\u00e1s lejos que cualquier otra nave espacial tripulada lanzada anteriormente anterior. En su regreso a la atm\u00f3sfera terrestre, deber\u00e1 soportar una velocidad de 40.000 km\/h y una temperatura equivalente a la mitad de la que se registra en la superficie del Sol. Una misi\u00f3n exitosa ser\u00e1 un gran alivio para la&nbsp;NASA, tras a\u00f1os de retrasos y sobrecostos. La pr\u00f3xima misi\u00f3n, Artemis 2, prevista para 2024, transportar\u00e1 astronautas pero no alunizar\u00e1. Ese honor ser\u00e1 reservado para la tripulaci\u00f3n de Artemis 3, a ser lanzada no antes de 2025. Despu\u00e9s, la&nbsp;NASA&nbsp;espera realizar aproximadamente una misi\u00f3n al a\u00f1o. El plan de la agencia estadounidense es construir una estaci\u00f3n espacial en la \u00f3rbita lunar, llamada Gateway, y una base en la superficie de la Luna, para probar all\u00ed las tecnolog\u00edas necesarias que permitan enviar a los primeros humanos a Marte: nuevos trajes, un veh\u00edculo para desplazarse o un posible uso del agua lunar, entre otros objetivos. La misi\u00f3n Artemis lleva el nombre de la hermana gemela del dios griego Apollo, que dio nombre a las primeras misiones lunares. A diferencia de aquellas misiones que enviaron solo hombres blancos a la Luna entre 1969 y 1972, el programa Artemis ver\u00e1 a la primera persona negra y a la primera mujer pisar la superficie lunar.<\/p>\n","protected":false},"author":9,"featured_media":86737,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-86736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86736"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86736\/revisions"}],"predecessor-version":[{"id":86738,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86736\/revisions\/86738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86737"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}