{"id":86742,"date":"2022-11-08T07:17:50","date_gmt":"2022-11-08T11:17:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86742"},"modified":"2022-11-08T07:17:51","modified_gmt":"2022-11-08T11:17:51","slug":"eeuu-ofrece-recompensa-por-pandilleros-haitianos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/eeuu-ofrece-recompensa-por-pandilleros-haitianos\/","title":{"rendered":"EEUU ofrece recompensa por pandilleros haitianos"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/eeuu-acusa-a-pandilleros-haitianos-por-secuestros.jpeg\" alt=\"\" class=\"wp-image-86743\" width=\"250\" height=\"129\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/eeuu-acusa-a-pandilleros-haitianos-por-secuestros.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/eeuu-acusa-a-pandilleros-haitianos-por-secuestros-300x155.jpeg 300w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos anunci\u00f3 el lunes la acusaci\u00f3n de siete pandilleros en Hait\u00ed, inculpados de haber secuestrado a ciudadanos estadounidenses, y ofreci\u00f3 una recompensa de tres millones de d\u00f3lares por informaci\u00f3n sobre tres de ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos decididos a trabajar con nuestros socios internacionales para poner fin a estos secuestros extorsionadores\u201d peligrosos para los estadounidenses y el pueblo haitiano, declar\u00f3 el ministro de Justicia, Merrick Garland, en un comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La medida apunta a tres hombres acusados de haber participado en la captura de un grupo de misioneros cristianos y sus familias cerca de Puerto Pr\u00edncipe, el 16 de octubre de 2021.&nbsp; Se trata de Lanmo Sanjou y Jermaine Stephenson, miembros de la pandilla 400 Mawozo, as\u00ed como Vitel\u2019homme Innocent, miembro de la pandilla Kraze Barye. Washington cree que todav\u00eda est\u00e1n en Hait\u00ed y el Departamento de Estado ofreci\u00f3 hasta tres millones de d\u00f3lares en recompensas (un mill\u00f3n cada uno) por informaci\u00f3n que conduzca a su arresto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese caso, tres rehenes fueron liberados tras varias semanas de detenci\u00f3n y los dem\u00e1s lograron huir alrededor del 16 de diciembre. Uno de sus supuestos guardias ya ha sido detenido y extraditado a Estados Unidos, as\u00ed como el presunto autor intelectual de la operaci\u00f3n. Adem\u00e1s, Estados Unidos ha procesado y est\u00e1 buscando a otros cuatro l\u00edderes de pandillas haitianas. Se les acusa de haber participado en los secuestros, entre enero de 2021 y julio de 2022, de cinco ciudadanos estadounidenses, quienes fueron tomados como rehenes durante varios d\u00edas hasta que sus familiares pagaron el rescate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante el deterioro de la situaci\u00f3n de seguridad en Hait\u00ed, que complica la lucha contra una epidemia de c\u00f3lera, la comunidad internacional ha descartado por el momento el env\u00edo de una fuerza de mantenimiento de la paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sepa m\u00e1s<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otras sanciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Consejo de Seguridad de la ONU ha adoptado sanciones contra las bandas criminales que operan en el pa\u00eds (prohibici\u00f3n de viajar, congelaci\u00f3n de activos, embargo de armas selectivo).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otras sanciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Washington tambi\u00e9n impuso el viernes sanciones contra el presidente del Senado, Joseph Lambert, y uno de sus antecesores, Youri Latortue, acusados de haber \u201ccontribuido activamente\u201d al tr\u00e1fico de drogas en tr\u00e1nsito por la isla caribe\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos anunci\u00f3 el lunes la acusaci\u00f3n de siete pandilleros en Hait\u00ed, inculpados de haber secuestrado a ciudadanos estadounidenses, y ofreci\u00f3 una recompensa de tres millones de d\u00f3lares por informaci\u00f3n sobre tres de ellos. \u201cEstamos decididos a trabajar con nuestros socios internacionales para poner fin a estos secuestros extorsionadores\u201d peligrosos para los estadounidenses y el pueblo haitiano, declar\u00f3 el ministro de Justicia, Merrick Garland, en un comunicado. La medida apunta a tres hombres acusados de haber participado en la captura de un grupo de misioneros cristianos y sus familias cerca de Puerto Pr\u00edncipe, el 16 de octubre de 2021.&nbsp; Se trata de Lanmo Sanjou y Jermaine Stephenson, miembros de la pandilla 400 Mawozo, as\u00ed como Vitel\u2019homme Innocent, miembro de la pandilla Kraze Barye. Washington cree que todav\u00eda est\u00e1n en Hait\u00ed y el Departamento de Estado ofreci\u00f3 hasta tres millones de d\u00f3lares en recompensas (un mill\u00f3n cada uno) por informaci\u00f3n que conduzca a su arresto. En ese caso, tres rehenes fueron liberados tras varias semanas de detenci\u00f3n y los dem\u00e1s lograron huir alrededor del 16 de diciembre. Uno de sus supuestos guardias ya ha sido detenido y extraditado a Estados Unidos, as\u00ed como el presunto autor intelectual de la operaci\u00f3n. Adem\u00e1s, Estados Unidos ha procesado y est\u00e1 buscando a otros cuatro l\u00edderes de pandillas haitianas. Se les acusa de haber participado en los secuestros, entre enero de 2021 y julio de 2022, de cinco ciudadanos estadounidenses, quienes fueron tomados como rehenes durante varios d\u00edas hasta que sus familiares pagaron el rescate. Ante el deterioro de la situaci\u00f3n de seguridad en Hait\u00ed, que complica la lucha contra una epidemia de c\u00f3lera, la comunidad internacional ha descartado por el momento el env\u00edo de una fuerza de mantenimiento de la paz. Sepa m\u00e1s Otras sanciones. El Consejo de Seguridad de la ONU ha adoptado sanciones contra las bandas criminales que operan en el pa\u00eds (prohibici\u00f3n de viajar, congelaci\u00f3n de activos, embargo de armas selectivo). Otras sanciones. Washington tambi\u00e9n impuso el viernes sanciones contra el presidente del Senado, Joseph Lambert, y uno de sus antecesores, Youri Latortue, acusados de haber \u201ccontribuido activamente\u201d al tr\u00e1fico de drogas en tr\u00e1nsito por la isla caribe\u00f1a.<\/p>\n","protected":false},"author":9,"featured_media":86743,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-86742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86742"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86742\/revisions"}],"predecessor-version":[{"id":86744,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86742\/revisions\/86744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86743"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}