{"id":86749,"date":"2022-11-08T07:22:32","date_gmt":"2022-11-08T11:22:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86749"},"modified":"2022-11-08T07:22:34","modified_gmt":"2022-11-08T11:22:34","slug":"compromiso-ciudadano-su-importancia-en-la-educacion-superior","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/compromiso-ciudadano-su-importancia-en-la-educacion-superior\/","title":{"rendered":"Compromiso ciudadano, su importancia en la educaci\u00f3n superior"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/eds.jpg\" alt=\"\" class=\"wp-image-86750\" width=\"254\" height=\"169\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa educaci\u00f3n es el arma m\u00e1s poderosa para cambiar el mundo\u201d, Nelson Mandela. El futuro de las sociedades depende de las acciones que se realizan hoy y, una de las maneras m\u00e1s poderosas de garantizar un mejor ma\u00f1ana para todos y todas es a trav\u00e9s de la educaci\u00f3n.&nbsp;<strong>Formar la conciencia colectiva es parte de una educaci\u00f3n integral,<\/strong>&nbsp;y especialmente en el caso de las universidades, parte de su rol en la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nelia Ram\u00edrez, docente universitaria, explica que el perfil de egreso de las instituciones de educaci\u00f3n superior \u201ccontempla que en su proceso formativo el estudiante no solo debe aprender los contenidos de una carrera profesional, tambi\u00e9n debe saber qu\u00e9 hacer con lo aprendido y transferir ese conocimiento hacia la mejora de sus espacios de interacci\u00f3n colectiva\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el fin de visibilizar todas las acciones que lleva a cabo la universidad para que tanto sus estudiantes como sus egresados y docentes vivan estos valores, se cre\u00f3 la Jornada de Compromiso Ciudadano de la universidad Unibe, actividad sello del \u00e1rea de Ciencias Sociales.<br \/><br \/>El prop\u00f3sito es involucrar a los estudiantes, desde el sal\u00f3n de clases, en proyectos educativos orientados al desarrollo de competencias ciudadanas en la pr\u00e1ctica de la responsabilidad social. \u201cEllos son los protagonistas. Deben hacer el levantamiento de comunidades con las que podamos vincularnos en proyectos de acci\u00f3n social, no para regalar, no para resolver una situaci\u00f3n de un d\u00eda&#8230; el compromiso ciudadano va m\u00e1s all\u00e1 que todo esto\u201d, manifiesta la acad\u00e9mica.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La integraci\u00f3n es la clave<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La catedr\u00e1tica destaca la importancia de integrar en los programas acad\u00e9micos actividades y acciones educativas que contribuyan a desarrollar en los estudiantes destrezas y actitudes encaminadas al ejercicio de una ciudadan\u00eda cr\u00edtica de su realidad y comprometida con el desarrollo sostenido de la comunidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manifiesta que Unibe, por ejemplo, tiene el compromiso de que sus egresados posean don de gente, valores sociales como la \u00e9tica, la integridad y amor por el trabajo en procura de la mejor\u00eda de su pa\u00eds y el mundo\u201d.<br \/><br \/>Desde su fundaci\u00f3n, la instituci\u00f3n de educaci\u00f3n superior asumi\u00f3 el compromiso de formar l\u00edderes solidarios y comprometidos. Lo lleva a cabo a trav\u00e9s de acciones formativas y de extensi\u00f3n, vinculando a sus estudiantes con comunidades vulnerables para sensibilizarlos ante sus realidades y desaf\u00edos, as\u00ed como a trav\u00e9s de proyectos de investigaci\u00f3n-acci\u00f3n que ofrezcan soluciones a las problem\u00e1ticas socioecon\u00f3micas de su entorno. El objetivo es desarrollar en ellos el compromiso social, la b\u00fasqueda del fortalecimiento de la democracia, conciencia ciudadana colectiva y el pensamiento l\u00f3gico, creativo y cr\u00edtico.<br \/><br \/>Los j\u00f3venes se involucran con entusiasmo y de verdad se comprometen. Muchos se mantienen en contacto con las comunidades o las instituciones con las que trabajan, apoy\u00e1ndolas incluso despu\u00e9s de terminar los proyectos en clase. Otros han llegado hasta a crear sus propias organizaciones ben\u00e9ficas, fundaciones, bibliotecas y espacios recreativos.<br \/><br \/>El resultado, de acuerdo a Nelia Ram\u00edrez, es que los profesionales que viven experiencias de este tipo en la universidad son \u201ccapaces de generar y liderar cambios, y poseen los valores \u00e9ticos necesarios para contribuir al desarrollo de la sociedad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La jornada cumple 10 a\u00f1os<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o, La Jornada de Compromiso Ciudadano de Unibe celebr\u00f3 su primera d\u00e9cada de impacto a la comunidad universitaria y la sociedad dominicana con proyectos ideados desde sus aulas. Durante la edici\u00f3n 2022, realizada el dos y tres de noviembre, se reconoci\u00f3 con el premio \u2018Quintiliano J\u00e1quez al liderazgo comprometido\u2019 al periodista Huchi Lora, a la estudiante Nayzeth Jade Alejo Castillo y a la egresada Helena Chapman.&nbsp;<br \/><br \/>Se instaur\u00f3 el reconocimiento \u201cRub\u00e9n Dar\u00edo G\u00f3mez al servicio comunitario\u201d en honor a la memoria de Rub\u00e9n Dar\u00edo G\u00f3mez, quien fuera coordinador de Servicio Comunitario de la universidad. Los reconocidos en esta categor\u00eda fueron la docente Laura S\u00e1nchez Vincitore y la colaboradora Leonor \u00c1lvarez Gil. Tambi\u00e9n, se entregaron certificados de reconocimiento a estudiantes que presentaron sus proyectos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa educaci\u00f3n es el arma m\u00e1s poderosa para cambiar el mundo\u201d, Nelson Mandela. El futuro de las sociedades depende de las acciones que se realizan hoy y, una de las maneras m\u00e1s poderosas de garantizar un mejor ma\u00f1ana para todos y todas es a trav\u00e9s de la educaci\u00f3n.&nbsp;Formar la conciencia colectiva es parte de una educaci\u00f3n integral,&nbsp;y especialmente en el caso de las universidades, parte de su rol en la sociedad. Nelia Ram\u00edrez, docente universitaria, explica que el perfil de egreso de las instituciones de educaci\u00f3n superior \u201ccontempla que en su proceso formativo el estudiante no solo debe aprender los contenidos de una carrera profesional, tambi\u00e9n debe saber qu\u00e9 hacer con lo aprendido y transferir ese conocimiento hacia la mejora de sus espacios de interacci\u00f3n colectiva\u201d. Con el fin de visibilizar todas las acciones que lleva a cabo la universidad para que tanto sus estudiantes como sus egresados y docentes vivan estos valores, se cre\u00f3 la Jornada de Compromiso Ciudadano de la universidad Unibe, actividad sello del \u00e1rea de Ciencias Sociales. El prop\u00f3sito es involucrar a los estudiantes, desde el sal\u00f3n de clases, en proyectos educativos orientados al desarrollo de competencias ciudadanas en la pr\u00e1ctica de la responsabilidad social. \u201cEllos son los protagonistas. Deben hacer el levantamiento de comunidades con las que podamos vincularnos en proyectos de acci\u00f3n social, no para regalar, no para resolver una situaci\u00f3n de un d\u00eda&#8230; el compromiso ciudadano va m\u00e1s all\u00e1 que todo esto\u201d, manifiesta la acad\u00e9mica.&nbsp;&nbsp; La integraci\u00f3n es la clave La catedr\u00e1tica destaca la importancia de integrar en los programas acad\u00e9micos actividades y acciones educativas que contribuyan a desarrollar en los estudiantes destrezas y actitudes encaminadas al ejercicio de una ciudadan\u00eda cr\u00edtica de su realidad y comprometida con el desarrollo sostenido de la comunidad.&nbsp; Manifiesta que Unibe, por ejemplo, tiene el compromiso de que sus egresados posean don de gente, valores sociales como la \u00e9tica, la integridad y amor por el trabajo en procura de la mejor\u00eda de su pa\u00eds y el mundo\u201d. Desde su fundaci\u00f3n, la instituci\u00f3n de educaci\u00f3n superior asumi\u00f3 el compromiso de formar l\u00edderes solidarios y comprometidos. Lo lleva a cabo a trav\u00e9s de acciones formativas y de extensi\u00f3n, vinculando a sus estudiantes con comunidades vulnerables para sensibilizarlos ante sus realidades y desaf\u00edos, as\u00ed como a trav\u00e9s de proyectos de investigaci\u00f3n-acci\u00f3n que ofrezcan soluciones a las problem\u00e1ticas socioecon\u00f3micas de su entorno. El objetivo es desarrollar en ellos el compromiso social, la b\u00fasqueda del fortalecimiento de la democracia, conciencia ciudadana colectiva y el pensamiento l\u00f3gico, creativo y cr\u00edtico. Los j\u00f3venes se involucran con entusiasmo y de verdad se comprometen. Muchos se mantienen en contacto con las comunidades o las instituciones con las que trabajan, apoy\u00e1ndolas incluso despu\u00e9s de terminar los proyectos en clase. Otros han llegado hasta a crear sus propias organizaciones ben\u00e9ficas, fundaciones, bibliotecas y espacios recreativos. El resultado, de acuerdo a Nelia Ram\u00edrez, es que los profesionales que viven experiencias de este tipo en la universidad son \u201ccapaces de generar y liderar cambios, y poseen los valores \u00e9ticos necesarios para contribuir al desarrollo de la sociedad\u201d. La jornada cumple 10 a\u00f1os Este a\u00f1o, La Jornada de Compromiso Ciudadano de Unibe celebr\u00f3 su primera d\u00e9cada de impacto a la comunidad universitaria y la sociedad dominicana con proyectos ideados desde sus aulas. Durante la edici\u00f3n 2022, realizada el dos y tres de noviembre, se reconoci\u00f3 con el premio \u2018Quintiliano J\u00e1quez al liderazgo comprometido\u2019 al periodista Huchi Lora, a la estudiante Nayzeth Jade Alejo Castillo y a la egresada Helena Chapman.&nbsp; Se instaur\u00f3 el reconocimiento \u201cRub\u00e9n Dar\u00edo G\u00f3mez al servicio comunitario\u201d en honor a la memoria de Rub\u00e9n Dar\u00edo G\u00f3mez, quien fuera coordinador de Servicio Comunitario de la universidad. Los reconocidos en esta categor\u00eda fueron la docente Laura S\u00e1nchez Vincitore y la colaboradora Leonor \u00c1lvarez Gil. Tambi\u00e9n, se entregaron certificados de reconocimiento a estudiantes que presentaron sus proyectos.<\/p>\n","protected":false},"author":9,"featured_media":86750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-86749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86749"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86749\/revisions"}],"predecessor-version":[{"id":86751,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86749\/revisions\/86751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86750"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}