{"id":86752,"date":"2022-11-08T07:29:05","date_gmt":"2022-11-08T11:29:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86752"},"modified":"2022-11-08T07:29:07","modified_gmt":"2022-11-08T11:29:07","slug":"matan-a-cuatro-durante-el-fin-de-semana-en-santiago-fin-de-semana-violento","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/matan-a-cuatro-durante-el-fin-de-semana-en-santiago-fin-de-semana-violento\/","title":{"rendered":"Matan a cuatro durante el fin de semana en Santiago Fin de semana violento"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se registraron cuatro muertos a tiros, en hechos separados en distintos sectores de Santiago, por lo que la violencia sigue arropando el Cibao.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas muertes violentas sucedieron sin que hasta el memento las autoridades den respuesta de cada uno de estos casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">David Familia, de 23 a\u00f1os, fue uno de las cuatros personas que cayeron abatidas durante en las \u00faltimas horas aqu\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Familia muri\u00f3 luego de que varios hombres, a\u00fan no identificados por las autoridades, le tiroteron momento cuando la v\u00edctima llegaba a su casa, ubicada en la calle 8 esquina 43, en el sector San Antonio de Cienfuegos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Felipe Familia, abuelo del fallecido, dijo que su nieto hab\u00eda viajado desde Saman\u00e1 a Santiago para comprar una camioneta, ya que \u00e9l se dedicaba a la compra y venta de metales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que cuando asesinaron a su pariente, tambi\u00e9n se llevaron el dinero que \u00e9l ten\u00eda para comprar el veh\u00edculo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">David Familia hab\u00eda tenido problemas con sus asesinos, por problemas que ocurrieron&nbsp; hace 5 a\u00f1os, por una bofetada, que \u00e9l le hab\u00eda dado a uno de ellos, seg\u00fan confirm\u00f3 su abuela, Milagro Valenzuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Justamente, naci\u00f3 el hijo de Familia, el mismo d\u00eda que varios hombres le dieron muerte, dijo su abuela Valenzuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explico que el cuerpo de su pariente se encuentra en el Instituto Nacional de Ciencias Forense&nbsp; (Inacif ), y luego ser\u00e1 trasladado a la comunidad de Walterio en la provincia Monte Cristi, donde es el padre del joven fallecido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dos en Villa Gonz\u00e1lez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la lista de fallecidos tambi\u00e9n se sumaron dos hombres que murieron durante un incidente registrado el domingo, en el sector La Yuca, en un centro de diversi\u00f3n, en Villa Gonz\u00e1lez, provincia Santiago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades policiales identificaron a las v\u00edctimas como Joseph Diligente, haitiano, y el dominicano Jos\u00e9 Juli\u00e1n Fern\u00e1ndez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El informe policial indica que sobre estos casos la uniformada est\u00e1 investigando las circunstancias en que se produjeron los hechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Policial<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra muerte.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/matan-a-cuatro-durante-el-fin-de-semana-en-santiago-fin-de-semana-violento-en.jpeg\" alt=\"\" class=\"wp-image-86753\" width=\"261\" height=\"134\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/matan-a-cuatro-durante-el-fin-de-semana-en-santiago-fin-de-semana-violento-en.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/matan-a-cuatro-durante-el-fin-de-semana-en-santiago-fin-de-semana-violento-en-300x155.jpeg 300w\" sizes=\"auto, (max-width: 261px) 100vw, 261px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El capit\u00e1n Fernando P\u00e9rez Valerio, vocero de la Direcci\u00f3n Regional Cibao Central de la Polic\u00eda Nacional, tambi\u00e9n inform\u00f3 que muri\u00f3 en un enfrentamiento a tiro con agentes policiales \u201cMaiky Ure\u00f1a Tav\u00e1rez\u201d,&nbsp; en la carretera Jamao al Norte, San V\u00edctor, en Espaillat, despu\u00e9s de este dar muerte a una personas y herir a dos. El hoy occiso fue identificado como Yan Carlos Ceballo Cruz, alias Yan, de 38 a\u00f1os; los heridos son Aneudy Ceballo de Jes\u00fas, alias El Cojo, de 39 a\u00f1os, y Francisco Alberto Rodr\u00edguez Dom\u00ednguez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se registraron cuatro muertos a tiros, en hechos separados en distintos sectores de Santiago, por lo que la violencia sigue arropando el Cibao. Estas muertes violentas sucedieron sin que hasta el memento las autoridades den respuesta de cada uno de estos casos. David Familia, de 23 a\u00f1os, fue uno de las cuatros personas que cayeron abatidas durante en las \u00faltimas horas aqu\u00ed. Familia muri\u00f3 luego de que varios hombres, a\u00fan no identificados por las autoridades, le tiroteron momento cuando la v\u00edctima llegaba a su casa, ubicada en la calle 8 esquina 43, en el sector San Antonio de Cienfuegos. Felipe Familia, abuelo del fallecido, dijo que su nieto hab\u00eda viajado desde Saman\u00e1 a Santiago para comprar una camioneta, ya que \u00e9l se dedicaba a la compra y venta de metales. Dijo que cuando asesinaron a su pariente, tambi\u00e9n se llevaron el dinero que \u00e9l ten\u00eda para comprar el veh\u00edculo. David Familia hab\u00eda tenido problemas con sus asesinos, por problemas que ocurrieron&nbsp; hace 5 a\u00f1os, por una bofetada, que \u00e9l le hab\u00eda dado a uno de ellos, seg\u00fan confirm\u00f3 su abuela, Milagro Valenzuela. Justamente, naci\u00f3 el hijo de Familia, el mismo d\u00eda que varios hombres le dieron muerte, dijo su abuela Valenzuela. Explico que el cuerpo de su pariente se encuentra en el Instituto Nacional de Ciencias Forense&nbsp; (Inacif ), y luego ser\u00e1 trasladado a la comunidad de Walterio en la provincia Monte Cristi, donde es el padre del joven fallecido. Dos en Villa Gonz\u00e1lez A la lista de fallecidos tambi\u00e9n se sumaron dos hombres que murieron durante un incidente registrado el domingo, en el sector La Yuca, en un centro de diversi\u00f3n, en Villa Gonz\u00e1lez, provincia Santiago. Las autoridades policiales identificaron a las v\u00edctimas como Joseph Diligente, haitiano, y el dominicano Jos\u00e9 Juli\u00e1n Fern\u00e1ndez. El informe policial indica que sobre estos casos la uniformada est\u00e1 investigando las circunstancias en que se produjeron los hechos. Policial Otra muerte. El capit\u00e1n Fernando P\u00e9rez Valerio, vocero de la Direcci\u00f3n Regional Cibao Central de la Polic\u00eda Nacional, tambi\u00e9n inform\u00f3 que muri\u00f3 en un enfrentamiento a tiro con agentes policiales \u201cMaiky Ure\u00f1a Tav\u00e1rez\u201d,&nbsp; en la carretera Jamao al Norte, San V\u00edctor, en Espaillat, despu\u00e9s de este dar muerte a una personas y herir a dos. El hoy occiso fue identificado como Yan Carlos Ceballo Cruz, alias Yan, de 38 a\u00f1os; los heridos son Aneudy Ceballo de Jes\u00fas, alias El Cojo, de 39 a\u00f1os, y Francisco Alberto Rodr\u00edguez Dom\u00ednguez.<\/p>\n","protected":false},"author":9,"featured_media":86753,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-86752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86752"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86752\/revisions"}],"predecessor-version":[{"id":86754,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86752\/revisions\/86754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86753"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}