{"id":86806,"date":"2022-11-13T20:18:23","date_gmt":"2022-11-14T00:18:23","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86806"},"modified":"2022-11-13T20:18:25","modified_gmt":"2022-11-14T00:18:25","slug":"nieta-de-biden-sera-la-protegonista-de-la-boda-numero-19-en-la-casa-blanca","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nieta-de-biden-sera-la-protegonista-de-la-boda-numero-19-en-la-casa-blanca\/","title":{"rendered":"Nieta de Biden ser\u00e1 la protegonista de la boda n\u00famero 19 en la Casa Blanca"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/preview-79174a26-focus-0-0-895-573.jpg\" alt=\"\" class=\"wp-image-86807\" width=\"213\" height=\"146\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/preview-79174a26-focus-0-0-895-573.jpg 512w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/preview-79174a26-focus-0-0-895-573-300x206.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/preview-79174a26-focus-0-0-895-573-75x52.jpg 75w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En unos d\u00edas se escuchar\u00e1 nuevamente la marcha nupcial en la&nbsp;<strong>Casa Blanca<\/strong>, cuando Naomi Biden, nieta del presidente Joe Biden, se case con Peter Neal en el Jard\u00edn Sur el s\u00e1bado, en lo que ser\u00e1 la&nbsp;<strong>boda<\/strong>&nbsp;n\u00famero 19 en la historia de la mansi\u00f3n presidencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ser\u00e1 la primera boda donde la novia es nieta del actual presidente y la primera en ese jard\u00edn, de acuerdo con la Asociaci\u00f3n Hist\u00f3rica de la Casa Blanca.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un amigo en com\u00fan present\u00f3 a la pareja hace unos cuatro a\u00f1os en la ciudad de Nueva York, y la&nbsp;<strong>Casa Blanca<\/strong>&nbsp;dijo que est\u00e1n juntos desde entonces. Ella, de 28 a\u00f1os, es abogada; su padre es Hunter Biden. Neal, de 25 a\u00f1os, se gradu\u00f3 recientemente de la facultad de Derecho de la Universidad de Pensilvania. La pareja vive en Washington.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nueve de las 18 bodas documentadas en la Casa Blanca fueron para la hija de un presidente, m\u00e1s recientemente la hija de Richard Nixon, Tricia, en 1971, y la hija de Lyndon B. Johnson, Lynda, en 1967.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero all\u00ed tambi\u00e9n se han casado sobrinas, una sobrina nieta, un hijo y hermanos de primeras damas. Un presidente, Grover Cleveland, tambi\u00e9n se cas\u00f3 all\u00ed, estando en el cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La primera dama Jill Biden dijo que est\u00e1 emocionada de ver a su nieta \u201cplaneando su boda, tomando sus decisiones, convirti\u00e9ndose en ella misma\u2026 es tan hermosa\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAs\u00ed que no puedo esperar hasta que todos ustedes la vean como novia\u201d, dijo la primera dama durante una aparici\u00f3n reciente en el programa de entrevistas de la cantante Kelly Clarkson.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stewart McLaurin, presidente de la asociaci\u00f3n hist\u00f3rica, dijo que las ocasiones especiales en la&nbsp;<strong>Casa Blanca<\/strong>&nbsp;no se olvidan f\u00e1cilmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi tuvieras el privilegio de celebrar un d\u00eda festivo all\u00ed o una ocasi\u00f3n especial en tu vida, como una&nbsp;<strong>boda<\/strong>, es una ocasi\u00f3n muy memorable\u201d, indic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En junio de 1971, unos 400 invitados vieron c\u00f3mo Nixon acompa\u00f1\u00f3 a su hija Tricia por los escalones del P\u00f3rtico Sur para entreg\u00e1rsela a Edward Cox, y la pareja intercambi\u00f3 votos en una glorieta instalada en el Rosedal, en la primera ceremonia de boda celebrada all\u00ed.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero no solo se han casado aqu\u00ed familiares del mandatario en turno. En octubre de 2013, el fot\u00f3grafo oficial de la&nbsp;<strong>Casa Blanca<\/strong>&nbsp;de Barack Obama, Pete Souza, y Patti Lease se casaron en una ceremonia privada en el Rosedal despu\u00e9s de 17 a\u00f1os como pareja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En unos d\u00edas se escuchar\u00e1 nuevamente la marcha nupcial en la&nbsp;Casa Blanca, cuando Naomi Biden, nieta del presidente Joe Biden, se case con Peter Neal en el Jard\u00edn Sur el s\u00e1bado, en lo que ser\u00e1 la&nbsp;boda&nbsp;n\u00famero 19 en la historia de la mansi\u00f3n presidencial. Ser\u00e1 la primera boda donde la novia es nieta del actual presidente y la primera en ese jard\u00edn, de acuerdo con la Asociaci\u00f3n Hist\u00f3rica de la Casa Blanca. Un amigo en com\u00fan present\u00f3 a la pareja hace unos cuatro a\u00f1os en la ciudad de Nueva York, y la&nbsp;Casa Blanca&nbsp;dijo que est\u00e1n juntos desde entonces. Ella, de 28 a\u00f1os, es abogada; su padre es Hunter Biden. Neal, de 25 a\u00f1os, se gradu\u00f3 recientemente de la facultad de Derecho de la Universidad de Pensilvania. La pareja vive en Washington. Nueve de las 18 bodas documentadas en la Casa Blanca fueron para la hija de un presidente, m\u00e1s recientemente la hija de Richard Nixon, Tricia, en 1971, y la hija de Lyndon B. Johnson, Lynda, en 1967. Pero all\u00ed tambi\u00e9n se han casado sobrinas, una sobrina nieta, un hijo y hermanos de primeras damas. Un presidente, Grover Cleveland, tambi\u00e9n se cas\u00f3 all\u00ed, estando en el cargo. La primera dama Jill Biden dijo que est\u00e1 emocionada de ver a su nieta \u201cplaneando su boda, tomando sus decisiones, convirti\u00e9ndose en ella misma\u2026 es tan hermosa\u201d. \u201cAs\u00ed que no puedo esperar hasta que todos ustedes la vean como novia\u201d, dijo la primera dama durante una aparici\u00f3n reciente en el programa de entrevistas de la cantante Kelly Clarkson. Stewart McLaurin, presidente de la asociaci\u00f3n hist\u00f3rica, dijo que las ocasiones especiales en la&nbsp;Casa Blanca&nbsp;no se olvidan f\u00e1cilmente. \u201cSi tuvieras el privilegio de celebrar un d\u00eda festivo all\u00ed o una ocasi\u00f3n especial en tu vida, como una&nbsp;boda, es una ocasi\u00f3n muy memorable\u201d, indic\u00f3. En junio de 1971, unos 400 invitados vieron c\u00f3mo Nixon acompa\u00f1\u00f3 a su hija Tricia por los escalones del P\u00f3rtico Sur para entreg\u00e1rsela a Edward Cox, y la pareja intercambi\u00f3 votos en una glorieta instalada en el Rosedal, en la primera ceremonia de boda celebrada all\u00ed. Pero no solo se han casado aqu\u00ed familiares del mandatario en turno. En octubre de 2013, el fot\u00f3grafo oficial de la&nbsp;Casa Blanca&nbsp;de Barack Obama, Pete Souza, y Patti Lease se casaron en una ceremonia privada en el Rosedal despu\u00e9s de 17 a\u00f1os como pareja.<\/p>\n","protected":false},"author":9,"featured_media":86807,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-86806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86806"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86806\/revisions"}],"predecessor-version":[{"id":86808,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86806\/revisions\/86808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86807"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}