{"id":86830,"date":"2022-11-15T07:27:43","date_gmt":"2022-11-15T11:27:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86830"},"modified":"2022-11-15T07:27:50","modified_gmt":"2022-11-15T11:27:50","slug":"dan-plazo-de-15-dias-para-la-acusacion-por-asesinato-jorge-mera","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dan-plazo-de-15-dias-para-la-acusacion-por-asesinato-jorge-mera\/","title":{"rendered":"Dan plazo de 15 d\u00edas para la acusaci\u00f3n por asesinato Jorge Mera"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/acu.jpg\" alt=\"\" class=\"wp-image-86831\" width=\"229\" height=\"116\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/acu.jpg 332w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/acu-300x152.jpg 300w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La jueza del Sexto Juzgado de la Instrucci\u00f3n del Distrito Nacional otorg\u00f3 15 d\u00edas al ministerio p\u00fablico para que presente acusaci\u00f3n formal en contra de Fausto Miguel Cruz, acusado del asesinato del ministro de Medio Ambiente, Orlando Jorge Mera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La magistrada Yanibet Rivas, dispuso que la intimaci\u00f3n de la presentaci\u00f3n de la acusaci\u00f3n comience a correr a partir de la notificaci\u00f3n del tribunal, cuyos 15 d\u00edas ser\u00e1n h\u00e1biles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tribunal tom\u00f3 la decisi\u00f3n, luego de haberle otorgado en septiembre pasado, dos meses al ministerio p\u00fablico para que presentara acto conclusivo cuya fecha l\u00edmite era el 9 de noviembre. Cruz de la Mota fue detenido por la muerte de su amigo de infancia, ocurrida el 6 de junio en las oficinas de Medio Ambiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El expediente<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el expediente del \u00f3rgano acusador, Fausto Miguel Cruz, apodado \u201cCarandai\u201d, planific\u00f3 el asesinato del ministro, porque este se opon\u00eda a otorgarle unos permisos para exportar 5,000 toneladas de bater\u00edas usadas a trav\u00e9s de la empresa Aurum Gavia, S.A. Supuestamente, el imputado estaba frustrado porque \u201chizo campa\u00f1a pol\u00edtica para el Partido Revolucionario Moderno (PRM) y no le resolvieron\u201d.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jueza del Sexto Juzgado de la Instrucci\u00f3n del Distrito Nacional otorg\u00f3 15 d\u00edas al ministerio p\u00fablico para que presente acusaci\u00f3n formal en contra de Fausto Miguel Cruz, acusado del asesinato del ministro de Medio Ambiente, Orlando Jorge Mera. La magistrada Yanibet Rivas, dispuso que la intimaci\u00f3n de la presentaci\u00f3n de la acusaci\u00f3n comience a correr a partir de la notificaci\u00f3n del tribunal, cuyos 15 d\u00edas ser\u00e1n h\u00e1biles. El tribunal tom\u00f3 la decisi\u00f3n, luego de haberle otorgado en septiembre pasado, dos meses al ministerio p\u00fablico para que presentara acto conclusivo cuya fecha l\u00edmite era el 9 de noviembre. Cruz de la Mota fue detenido por la muerte de su amigo de infancia, ocurrida el 6 de junio en las oficinas de Medio Ambiente. El expediente De acuerdo con el expediente del \u00f3rgano acusador, Fausto Miguel Cruz, apodado \u201cCarandai\u201d, planific\u00f3 el asesinato del ministro, porque este se opon\u00eda a otorgarle unos permisos para exportar 5,000 toneladas de bater\u00edas usadas a trav\u00e9s de la empresa Aurum Gavia, S.A. Supuestamente, el imputado estaba frustrado porque \u201chizo campa\u00f1a pol\u00edtica para el Partido Revolucionario Moderno (PRM) y no le resolvieron\u201d.&nbsp;<\/p>\n","protected":false},"author":9,"featured_media":86831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-86830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86830"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86830\/revisions"}],"predecessor-version":[{"id":86832,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86830\/revisions\/86832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86831"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}