{"id":86836,"date":"2022-11-15T07:31:02","date_gmt":"2022-11-15T11:31:02","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86836"},"modified":"2022-11-15T07:31:08","modified_gmt":"2022-11-15T11:31:08","slug":"atacan-a-tiros-a-un-convoy-de-la-embajada-de-estados-unidos-en-haiti","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/atacan-a-tiros-a-un-convoy-de-la-embajada-de-estados-unidos-en-haiti\/","title":{"rendered":"Atacan a tiros a un convoy de la Embajada de Estados Unidos en Hait\u00ed"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/atacan-a-tiros-a-un-convoy-de-la-embajada-de-estados-unidos-en-haiti.jpeg\" alt=\"\" class=\"wp-image-86837\" width=\"214\" height=\"142\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/atacan-a-tiros-a-un-convoy-de-la-embajada-de-estados-unidos-en-haiti.jpeg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/atacan-a-tiros-a-un-convoy-de-la-embajada-de-estados-unidos-en-haiti-300x200.jpeg 300w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Un conductor haitiano result\u00f3 herido tras un ataque a tiros que desconocidos perpetraron este lunes contra un grupo de veh\u00edculos de la Embajada de Estados Unidos en la capital haitiana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La embajada emiti\u00f3 un breve comunicado en el que dijo tambi\u00e9n que fueron tiroteados unidades de la Polic\u00eda Nacional de Hait\u00ed (PNH).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n asegur\u00f3 que las heridas del ch\u00f3fer no representan peligro para su vida, adem\u00e1s de que los miembros de la embajada no sufrieron da\u00f1os f\u00edsicos ni tampoco los agentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El convoy fue atacado en la zona de Croix-des-Bouquets, situada en la entrada norte de la capital, donde opera el grupo armado 400 Mawozo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 16 de octubre de 2021, esa banda secuestr\u00f3 a 16 misioneros cristianos estadounidenses y un misionero canadiense y pidi\u00f3 un rescate por ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los misioneros fueron secuestrados despu\u00e9s de visitar un orfanato en el pueblo de Ganthier, una barriada en las afueras de Puerto Pr\u00edncipe, y entre ellos hab\u00eda cinco ni\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la liberaci\u00f3n de varios de ellos, el grupo -que pertenec\u00eda a la congregaci\u00f3n religiosa Christian Aid Ministries- fue puesto en libertad por completo el 16 de diciembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos lanz\u00f3 el lunes pasado una recompensa de hasta un mill\u00f3n de d\u00f3lares por informaci\u00f3n que lleve a detener a tres haitianos sospechosos de secuestrar a los misioneros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los sospechosos son tres ciudadanos haitianos, Lanm\u00f2 Sanjou, tambi\u00e9n conocido como Joseph Wilson; Jermaine Stephenson, conocido como Gaspiyay, y Vitel&#8217;Homme Innocent, l\u00edderes de dos bandas de secuestradores y acusados de participar en el crimen organizado transnacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un conductor haitiano result\u00f3 herido tras un ataque a tiros que desconocidos perpetraron este lunes contra un grupo de veh\u00edculos de la Embajada de Estados Unidos en la capital haitiana. La embajada emiti\u00f3 un breve comunicado en el que dijo tambi\u00e9n que fueron tiroteados unidades de la Polic\u00eda Nacional de Hait\u00ed (PNH). La informaci\u00f3n asegur\u00f3 que las heridas del ch\u00f3fer no representan peligro para su vida, adem\u00e1s de que los miembros de la embajada no sufrieron da\u00f1os f\u00edsicos ni tampoco los agentes. El convoy fue atacado en la zona de Croix-des-Bouquets, situada en la entrada norte de la capital, donde opera el grupo armado 400 Mawozo. El 16 de octubre de 2021, esa banda secuestr\u00f3 a 16 misioneros cristianos estadounidenses y un misionero canadiense y pidi\u00f3 un rescate por ellos. Los misioneros fueron secuestrados despu\u00e9s de visitar un orfanato en el pueblo de Ganthier, una barriada en las afueras de Puerto Pr\u00edncipe, y entre ellos hab\u00eda cinco ni\u00f1os. Tras la liberaci\u00f3n de varios de ellos, el grupo -que pertenec\u00eda a la congregaci\u00f3n religiosa Christian Aid Ministries- fue puesto en libertad por completo el 16 de diciembre. Estados Unidos lanz\u00f3 el lunes pasado una recompensa de hasta un mill\u00f3n de d\u00f3lares por informaci\u00f3n que lleve a detener a tres haitianos sospechosos de secuestrar a los misioneros. Los sospechosos son tres ciudadanos haitianos, Lanm\u00f2 Sanjou, tambi\u00e9n conocido como Joseph Wilson; Jermaine Stephenson, conocido como Gaspiyay, y Vitel&#8217;Homme Innocent, l\u00edderes de dos bandas de secuestradores y acusados de participar en el crimen organizado transnacional.<\/p>\n","protected":false},"author":9,"featured_media":86837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-86836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86836"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86836\/revisions"}],"predecessor-version":[{"id":86838,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86836\/revisions\/86838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86837"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}