{"id":86914,"date":"2022-11-19T07:01:00","date_gmt":"2022-11-19T11:01:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86914"},"modified":"2022-11-19T07:01:02","modified_gmt":"2022-11-19T11:01:02","slug":"twitter-corre-riesgo-de-colapso-con-salida-de-ingenieros","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/twitter-corre-riesgo-de-colapso-con-salida-de-ingenieros\/","title":{"rendered":"Twitter corre riesgo de colapso con salida de ingenieros"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"453\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/t.jpg\" alt=\"\" class=\"wp-image-86915\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/t.jpg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/t-300x200.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El explosivo estilo gerencial de Elon Musk en Twitter ha mermado las filas de los ingenieros de software que mantienen en funcionamiento la plataforma, a tal grado que expertos del sector y los programadores que han sido despedidos o han renunciado esta semana creen que Twitter podr\u00eda irse estropeando y colapsar pronto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Musk puso fin a una discusi\u00f3n muy p\u00fablica con casi dos docenas de programadores fundamentales para la estabilidad de la plataforma al ordenar su despido esta semana. Cientos de ingenieros y otros trabajadores renunciaron despu\u00e9s de que Musk les exigiera que se comprometieran a trabajar de forma \u201cextremadamente dura\u201d o que renunciaran con una indemnizaci\u00f3n por despido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las nuevas salidas significan que la plataforma est\u00e1 perdiendo trabajadores justo cuando se prepara para la Copa del Mundo en Qatar, que se inaugura el domingo. Es uno de los eventos m\u00e1s concurridos de Twitter, cuando oleadas de tuits estresan fuertemente sus sistemas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cS\u00ed parece que va a reventar Twitter\u201d, coment\u00f3 Robert Graham, un veterano empresario de la ciberseguridad. \u201cNo veo c\u00f3mo no se apagar\u00e1n las luces en cualquier momento\u201d, aunque muchas de las recientes salidas de Twitter auguraban una muerte m\u00e1s gradual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cientos de empleados se\u00f1alaron que se marchaban antes de la fecha l\u00edmite del jueves, y publicaron mensajes de despedida, un emoji de saludo y otros s\u00edmbolos familiares en el tabl\u00f3n de mensajes interno de la compa\u00f1\u00eda en Slack, seg\u00fan los empleados que a\u00fan tienen acceso. Decenas de ellos tambi\u00e9n han anunciado su partida p\u00fablicamente en Twitter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta semana, algunos se enfadaron tanto por la imprudencia percibida de Musk que tomaron Twitter para insultarlo. \u201cB\u00e9same el trasero, Elon\u201d, dijo una ingeniera, a\u00f1adiendo marcas de l\u00e1piz labial. Hab\u00eda sido despedida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La direcci\u00f3n de Twitter envi\u00f3 un correo electr\u00f3nico sin firmar despu\u00e9s de la fecha l\u00edmite del jueves en el que inform\u00f3 que sus oficinas estar\u00edan cerradas y que el acceso con tarjeta de identificaci\u00f3n de los empleados estar\u00eda deshabilitado hasta el lunes. No se dio ninguna raz\u00f3n, seg\u00fan dos empleados que recibieron el correo electr\u00f3nico, uno que acept\u00f3 la indemnizaci\u00f3n y otro que sigue en n\u00f3mina. Ambos hablaron bajo condici\u00f3n de anonimato por temor a represalias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con un escuadr\u00f3n de programadores de Tesla a su lado mientras desvalijaba un espacio de trabajo que sol\u00eda ser agradable, Musk no parec\u00eda alarmado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos mejores se quedan, as\u00ed que no estoy superpreocupado\u201d, tuite\u00f3 el tambi\u00e9n director general de Tesla y SpaceX el jueves por la noche. Pero pronto qued\u00f3 claro que algunos equipos de programaci\u00f3n cruciales hab\u00edan sido completamente desbaratados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como muestra de la escasez de programadores, Musk envi\u00f3 el viernes correos electr\u00f3nicos a todos los empleados en los que convocaba a \u201ccualquiera que escriba software\u201d a su puesto de mando en la d\u00e9cima planta de Twitter a las 14:00 horas, pidiendo que volaran a San Francisco si no eran locales, dijo el empleado que renunci\u00f3 el jueves pero que segu\u00eda recibiendo correos electr\u00f3nicos de la empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras hacerse del control de Twitter hace menos de tres semanas, Musk ech\u00f3 a la mitad de los 7.500 empleados a tiempo completo de la empresa y a un n\u00famero incalculable de trabajadores independientes responsables de la moderaci\u00f3n de contenidos y de otras tareas cruciales. Luego lleg\u00f3 el ultim\u00e1tum de esta semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tres ingenieros que se marcharon esta semana describieron para The Associated Press por qu\u00e9 esperan que los m\u00e1s de 230 millones de usuarios de Twitter se sientan bastante inc\u00f3modos ahora que m\u00e1s de dos tercios de los ingenieros de los servicios centrales de Twitter se han ido. Aunque no prev\u00e9n un colapso a corto plazo, Twitter podr\u00eda volverse muy \u00e1spero en los bordes, especialmente si Musk hace cambios importantes sin muchas pruebas fuera de la plataforma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los signos de desgaste eran evidentes antes de la salida masiva del jueves. La gente report\u00f3 ver m\u00e1s spam y estafas en sus feeds y en sus mensajes directos. Los ingenieros informaron de tuits ca\u00eddos. La gente recibi\u00f3 extra\u00f1os mensajes de error.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero nada cr\u00edtico se ha descompuesto. A\u00fan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay una quiniela para cu\u00e1ndo ocurrir\u00e1 eso\u201d, dijo uno de los ingenieros, quienes hablaron bajo condici\u00f3n de anonimato por temor a las represalias de Musk que podr\u00edan afectar sus carreras y finanzas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro dijo que si Twitter ha estado apagando servidores y \u201cde repente entra un gran volumen, podr\u00eda empezar a colapsar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl Mundial es el mayor evento para Twitter. Es lo primero que aprendes cuando te incorporas a Twitter\u201d, indic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con los despidos previos de empleados de curadur\u00eda, las p\u00e1ginas de tendencias de Twitter ya sufr\u00edan. Los problemas t\u00e9cnicos comenzaron el martes cuando Musk anunci\u00f3 en Twitter que hab\u00eda comenzado a cerrar \u201cmicroservicios\u201d que consideraba \u201cbloatware\u201d, o software de relleno, innecesario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00a1En realidad se necesita menos del 20% para que Twitter funcione!\u201d, tuite\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso gener\u00f3 oposici\u00f3n de los ingenieros que le dijeron a Musk que no ten\u00eda idea de lo que dec\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos microservicios son la forma en que la mayor\u00eda de los grandes servicios web modernos organizan su c\u00f3digo para permitir que ingenieros de software trabajen de manera r\u00e1pida y eficiente\u201d, explic\u00f3 Gergely Orosz, autor del blog Pragmatic Engineer (Ingeniero pragm\u00e1tico) y exprogramador en Uber. Hay muchos servicios de estos, y cada uno administra una funcionalidad diferente. En lugar de probar la eliminaci\u00f3n de microservicios en un entorno simulado de la vida real, al parecer el equipo de Musk ha estado actualizando Twitter en vivo en las computadoras de todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y de hecho, un microservicio fall\u00f3 brevemente: aquel que las personas usan para verificar su identidad en Twitter a trav\u00e9s de mensajes SMS cuando se registran. Se llama la autenticaci\u00f3n de dos pasos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAlcanzaste tu l\u00edmite de c\u00f3digos SMS. Vuelve a intentar en 24 horas\u201d, aconsej\u00f3 Twitter cuando un reportero intent\u00f3 descargar su historial de publicaciones. Por suerte, funcionaba la verificaci\u00f3n alterna por correo electr\u00f3nico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los ingenieros que recientemente dej\u00f3 Twitter y que trabajaba en servicios centrales, le dijo a la AP que los equipos de ingenier\u00eda pasaron de unas 15 personas antes de la llegada de Musk \u2014sin incluir a los l\u00edderes de los equipos, que fueron todos despedidos\u2014 a tres o cuatro antes de las renuncias del jueves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de eso se fue m\u00e1s conocimiento institucional que no puede reemplazarse de la noche a la ma\u00f1ana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodo podr\u00eda fallar\u201d, dijo el programador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para algunos servicios, se necesitan seis meses para capacitar a alguien para trabajar una rotaci\u00f3n de guardia, dijeron los ingenieros. Dichas rotaciones requieren que los programadores est\u00e9n disponibles a todas horas. Pero si la persona de guardia no est\u00e1 familiarizada con el c\u00f3digo base, las fallas pueden tener una reacci\u00f3n en cadena mientras revisan fren\u00e9ticamente los manuales de referencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDe haberme quedado estar\u00eda constantemente de guardia con poco apoyo por un periodo indeterminado en varios sistemas complejos adicionales en los que no tengo experiencia\u201d, tuite\u00f3 Peter Clowes, un ingeniero que acept\u00f3 la indemnizaci\u00f3n por despido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPara operar sistemas incluso relativamente aburridos se necesitan personas que sepan a d\u00f3nde ir cuando algo falla\u201d, indic\u00f3 Blaine Cook, ingeniero fundador de Twitter, quien se fue en 2008. Es peligroso reducir dr\u00e1sticamente la fuerza laboral de programaci\u00f3n a un equipo m\u00ednimo sin primero blindar el c\u00f3digo, agreg\u00f3. \u201cEs como decir: \u2018Estos bomberos no hacen nada. As\u00ed que los despediremos a todos\u2019\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A los ingenieros tambi\u00e9n les preocupa que Musk cierre las herramientas para la moderaci\u00f3n de contenido y para la eliminaci\u00f3n de material il\u00edcito que las personas suben a Twitter, o que no haya suficientes trabajadores para operarlas adecuadamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra preocupaci\u00f3n son los hackers. Cuando han infiltrado el sistema en el pasado, reducir el da\u00f1o depende de su r\u00e1pida detecci\u00f3n y expulsi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No est\u00e1 claro c\u00f3mo la limpieza interna de Musk en Twitter ha afectado a su equipo de ciberseguridad, que en agosto sufri\u00f3 un gran golpe en sus relaciones p\u00fablicas cuando el muy respetado jefe de seguridad despedido por la empresa este a\u00f1o, Peiter Zatko, present\u00f3 una denuncia que afirma que la plataforma era un caos de ciberseguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cGran parte de la infraestructura de seguridad de una organizaci\u00f3n grande como Twitter est\u00e1 en las cabezas de las personas\u201d, dijo Graham, el experto en ciberseguridad. \u201cY cuando se van, sabes, todo se va con ellos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El explosivo estilo gerencial de Elon Musk en Twitter ha mermado las filas de los ingenieros de software que mantienen en funcionamiento la plataforma, a tal grado que expertos del sector y los programadores que han sido despedidos o han renunciado esta semana creen que Twitter podr\u00eda irse estropeando y colapsar pronto. Musk puso fin a una discusi\u00f3n muy p\u00fablica con casi dos docenas de programadores fundamentales para la estabilidad de la plataforma al ordenar su despido esta semana. Cientos de ingenieros y otros trabajadores renunciaron despu\u00e9s de que Musk les exigiera que se comprometieran a trabajar de forma \u201cextremadamente dura\u201d o que renunciaran con una indemnizaci\u00f3n por despido. Las nuevas salidas significan que la plataforma est\u00e1 perdiendo trabajadores justo cuando se prepara para la Copa del Mundo en Qatar, que se inaugura el domingo. Es uno de los eventos m\u00e1s concurridos de Twitter, cuando oleadas de tuits estresan fuertemente sus sistemas. \u201cS\u00ed parece que va a reventar Twitter\u201d, coment\u00f3 Robert Graham, un veterano empresario de la ciberseguridad. \u201cNo veo c\u00f3mo no se apagar\u00e1n las luces en cualquier momento\u201d, aunque muchas de las recientes salidas de Twitter auguraban una muerte m\u00e1s gradual. Cientos de empleados se\u00f1alaron que se marchaban antes de la fecha l\u00edmite del jueves, y publicaron mensajes de despedida, un emoji de saludo y otros s\u00edmbolos familiares en el tabl\u00f3n de mensajes interno de la compa\u00f1\u00eda en Slack, seg\u00fan los empleados que a\u00fan tienen acceso. Decenas de ellos tambi\u00e9n han anunciado su partida p\u00fablicamente en Twitter. Esta semana, algunos se enfadaron tanto por la imprudencia percibida de Musk que tomaron Twitter para insultarlo. \u201cB\u00e9same el trasero, Elon\u201d, dijo una ingeniera, a\u00f1adiendo marcas de l\u00e1piz labial. Hab\u00eda sido despedida. La direcci\u00f3n de Twitter envi\u00f3 un correo electr\u00f3nico sin firmar despu\u00e9s de la fecha l\u00edmite del jueves en el que inform\u00f3 que sus oficinas estar\u00edan cerradas y que el acceso con tarjeta de identificaci\u00f3n de los empleados estar\u00eda deshabilitado hasta el lunes. No se dio ninguna raz\u00f3n, seg\u00fan dos empleados que recibieron el correo electr\u00f3nico, uno que acept\u00f3 la indemnizaci\u00f3n y otro que sigue en n\u00f3mina. Ambos hablaron bajo condici\u00f3n de anonimato por temor a represalias. Con un escuadr\u00f3n de programadores de Tesla a su lado mientras desvalijaba un espacio de trabajo que sol\u00eda ser agradable, Musk no parec\u00eda alarmado. \u201cLos mejores se quedan, as\u00ed que no estoy superpreocupado\u201d, tuite\u00f3 el tambi\u00e9n director general de Tesla y SpaceX el jueves por la noche. Pero pronto qued\u00f3 claro que algunos equipos de programaci\u00f3n cruciales hab\u00edan sido completamente desbaratados. Como muestra de la escasez de programadores, Musk envi\u00f3 el viernes correos electr\u00f3nicos a todos los empleados en los que convocaba a \u201ccualquiera que escriba software\u201d a su puesto de mando en la d\u00e9cima planta de Twitter a las 14:00 horas, pidiendo que volaran a San Francisco si no eran locales, dijo el empleado que renunci\u00f3 el jueves pero que segu\u00eda recibiendo correos electr\u00f3nicos de la empresa. Tras hacerse del control de Twitter hace menos de tres semanas, Musk ech\u00f3 a la mitad de los 7.500 empleados a tiempo completo de la empresa y a un n\u00famero incalculable de trabajadores independientes responsables de la moderaci\u00f3n de contenidos y de otras tareas cruciales. Luego lleg\u00f3 el ultim\u00e1tum de esta semana. Tres ingenieros que se marcharon esta semana describieron para The Associated Press por qu\u00e9 esperan que los m\u00e1s de 230 millones de usuarios de Twitter se sientan bastante inc\u00f3modos ahora que m\u00e1s de dos tercios de los ingenieros de los servicios centrales de Twitter se han ido. Aunque no prev\u00e9n un colapso a corto plazo, Twitter podr\u00eda volverse muy \u00e1spero en los bordes, especialmente si Musk hace cambios importantes sin muchas pruebas fuera de la plataforma. Los signos de desgaste eran evidentes antes de la salida masiva del jueves. La gente report\u00f3 ver m\u00e1s spam y estafas en sus feeds y en sus mensajes directos. Los ingenieros informaron de tuits ca\u00eddos. La gente recibi\u00f3 extra\u00f1os mensajes de error. Pero nada cr\u00edtico se ha descompuesto. A\u00fan. \u201cHay una quiniela para cu\u00e1ndo ocurrir\u00e1 eso\u201d, dijo uno de los ingenieros, quienes hablaron bajo condici\u00f3n de anonimato por temor a las represalias de Musk que podr\u00edan afectar sus carreras y finanzas. Otro dijo que si Twitter ha estado apagando servidores y \u201cde repente entra un gran volumen, podr\u00eda empezar a colapsar\u201d. \u201cEl Mundial es el mayor evento para Twitter. Es lo primero que aprendes cuando te incorporas a Twitter\u201d, indic\u00f3. Con los despidos previos de empleados de curadur\u00eda, las p\u00e1ginas de tendencias de Twitter ya sufr\u00edan. Los problemas t\u00e9cnicos comenzaron el martes cuando Musk anunci\u00f3 en Twitter que hab\u00eda comenzado a cerrar \u201cmicroservicios\u201d que consideraba \u201cbloatware\u201d, o software de relleno, innecesario. \u201c\u00a1En realidad se necesita menos del 20% para que Twitter funcione!\u201d, tuite\u00f3. Eso gener\u00f3 oposici\u00f3n de los ingenieros que le dijeron a Musk que no ten\u00eda idea de lo que dec\u00eda. \u201cLos microservicios son la forma en que la mayor\u00eda de los grandes servicios web modernos organizan su c\u00f3digo para permitir que ingenieros de software trabajen de manera r\u00e1pida y eficiente\u201d, explic\u00f3 Gergely Orosz, autor del blog Pragmatic Engineer (Ingeniero pragm\u00e1tico) y exprogramador en Uber. Hay muchos servicios de estos, y cada uno administra una funcionalidad diferente. En lugar de probar la eliminaci\u00f3n de microservicios en un entorno simulado de la vida real, al parecer el equipo de Musk ha estado actualizando Twitter en vivo en las computadoras de todos. Y de hecho, un microservicio fall\u00f3 brevemente: aquel que las personas usan para verificar su identidad en Twitter a trav\u00e9s de mensajes SMS cuando se registran. Se llama la autenticaci\u00f3n de dos pasos. \u201cAlcanzaste tu l\u00edmite de c\u00f3digos SMS. Vuelve a intentar en 24 horas\u201d, aconsej\u00f3 Twitter cuando un reportero intent\u00f3 descargar su historial de publicaciones. Por suerte, funcionaba la verificaci\u00f3n alterna por correo electr\u00f3nico. Uno de los ingenieros que recientemente dej\u00f3 Twitter y que trabajaba en servicios centrales, le dijo a la AP que los equipos de ingenier\u00eda pasaron de unas 15 personas antes de la llegada de Musk \u2014sin incluir a los l\u00edderes de los [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":86915,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-86914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86914"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86914\/revisions"}],"predecessor-version":[{"id":86916,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86914\/revisions\/86916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86915"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}