{"id":86984,"date":"2022-11-23T17:55:07","date_gmt":"2022-11-23T21:55:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=86984"},"modified":"2022-11-23T17:58:00","modified_gmt":"2022-11-23T21:58:00","slug":"teleferico-y-ministerio-de-agricultura-firman-acuerdo-para-fomentar-la-agricultura-en-comunidades-de-la-provincia-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/teleferico-y-ministerio-de-agricultura-firman-acuerdo-para-fomentar-la-agricultura-en-comunidades-de-la-provincia-puerto-plata\/","title":{"rendered":"Telef\u00e9rico y Ministerio de Agricultura firman acuerdo para fomentar la agricultura en comunidades de la Provincia Puerto Plata"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura2.jpeg\" alt=\"\" class=\"wp-image-86986\" width=\"483\" height=\"390\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura2.jpeg 1023w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura2-300x243.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura2-768x622.jpeg 768w\" sizes=\"auto, (max-width: 483px) 100vw, 483px\" \/><figcaption><strong>Juan Miguel Mart\u00ednez<\/strong> (Por Agricultura),   <strong>Claritza Rochtte<\/strong> (Gobernadora POP) y  <strong>Atahualpa Paulino<\/strong> (Administrador Telef\u00e9rico)<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">San Felipe Puerto Plata.- Por iniciativa de la gobernadora <strong>Claritza Rochtte<\/strong> la administraci\u00f3n del Telef\u00e9rico de Puerto Plata y el Ministerio de Agricultura suscribieron un acuerdo interinstitucional mediante el cual se busca fortalecer la agricultura, donde se desarrollar\u00e1n t\u00e9cnicas en la siembra de diversos tipos de productos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambas carteras implementar\u00e1n iniciativas y ampliar\u00e1n las coberturas de los servicios que ofrecen las instituciones, con m\u00e1s apoyo, asesor\u00eda t\u00e9cnica e insumos para fomentar la producci\u00f3n y comercializaci\u00f3n de alimentos b\u00e1sicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el convenio, <strong>Juan Miguel Mart\u00ednez<\/strong>, representante del Ministerio de Agricultura, en esta provincia, dijo que la agricultura es la base de la alimentaci\u00f3n en cualquier parte del mundo y que este tipo de programa viene a fortalecer el sector. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Atahualpa Paulino<\/strong>, administrador del Telef\u00e9rico, indic\u00f3 que este acuerdo constituye una oportunidad para que a trav\u00e9s de la agricultura y los huertos las personas puedan superar sus condiciones y tengan asegurada su alimentaci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 Paulino que este proyecto complementar\u00e1 la oferta tur\u00edstica del Telef\u00e9rico, ya que los turistas podr\u00e1n conocer sobre las diferentes plantas end\u00e9micas del monumento natural Isabel de torres<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura3-1024x768.jpeg\" alt=\"\" data-id=\"86987\" data-full-url=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura3.jpeg\" data-link=\"http:\/\/sosuaonline.net\/inicio\/?attachment_id=86987\" class=\"wp-image-86987\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura3-1024x768.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura3-300x225.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura3-768x576.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura3.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1023\" height=\"828\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura2.jpeg\" alt=\"\" data-id=\"86986\" data-full-url=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura2.jpeg\" data-link=\"http:\/\/sosuaonline.net\/inicio\/?attachment_id=86986\" class=\"wp-image-86986\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura2.jpeg 1023w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura2-300x243.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura2-768x622.jpeg 768w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura1-1024x768.jpeg\" alt=\"\" data-id=\"86985\" data-full-url=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura1.jpeg\" data-link=\"http:\/\/sosuaonline.net\/inicio\/?attachment_id=86985\" class=\"wp-image-86985\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura1-1024x768.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura1-300x225.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura1-768x576.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/teleferico-y-agricultura1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Puntos del Acuerdo:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agricultura como el Telef\u00e9rico se comprometen a apoyar la agricultura con semillas, insumos, equipos y materiales necesarios para fomentar la producci\u00f3n. Adem\u00e1s, impartir talleres y seminarios para mejorar el sector agr\u00edcola, desarrollar huertos comunitarios, apoyo a la comercializaci\u00f3n, construcci\u00f3n y reparaci\u00f3n de caminos vecinales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Felipe Puerto Plata.- Por iniciativa de la gobernadora Claritza Rochtte la administraci\u00f3n del Telef\u00e9rico de Puerto Plata y el Ministerio de Agricultura suscribieron un acuerdo interinstitucional mediante el cual se busca fortalecer la agricultura, donde se desarrollar\u00e1n t\u00e9cnicas en la siembra de diversos tipos de productos. Ambas carteras implementar\u00e1n iniciativas y ampliar\u00e1n las coberturas de los servicios que ofrecen las instituciones, con m\u00e1s apoyo, asesor\u00eda t\u00e9cnica e insumos para fomentar la producci\u00f3n y comercializaci\u00f3n de alimentos b\u00e1sicos. Durante el convenio, Juan Miguel Mart\u00ednez, representante del Ministerio de Agricultura, en esta provincia, dijo que la agricultura es la base de la alimentaci\u00f3n en cualquier parte del mundo y que este tipo de programa viene a fortalecer el sector. Atahualpa Paulino, administrador del Telef\u00e9rico, indic\u00f3 que este acuerdo constituye una oportunidad para que a trav\u00e9s de la agricultura y los huertos las personas puedan superar sus condiciones y tengan asegurada su alimentaci\u00f3n. Agreg\u00f3 Paulino que este proyecto complementar\u00e1 la oferta tur\u00edstica del Telef\u00e9rico, ya que los turistas podr\u00e1n conocer sobre las diferentes plantas end\u00e9micas del monumento natural Isabel de torres Puntos del Acuerdo: Agricultura como el Telef\u00e9rico se comprometen a apoyar la agricultura con semillas, insumos, equipos y materiales necesarios para fomentar la producci\u00f3n. Adem\u00e1s, impartir talleres y seminarios para mejorar el sector agr\u00edcola, desarrollar huertos comunitarios, apoyo a la comercializaci\u00f3n, construcci\u00f3n y reparaci\u00f3n de caminos vecinales.<\/p>\n","protected":false},"author":12,"featured_media":86987,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,460],"tags":[],"class_list":["post-86984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo","category-turismo-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=86984"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86984\/revisions"}],"predecessor-version":[{"id":86988,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/86984\/revisions\/86988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/86987"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=86984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=86984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=86984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}