{"id":87058,"date":"2022-11-29T06:59:08","date_gmt":"2022-11-29T10:59:08","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87058"},"modified":"2022-11-29T06:59:10","modified_gmt":"2022-11-29T10:59:10","slug":"policia-iniciara-el-viernes-patrullaje-por-cuadrantes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/policia-iniciara-el-viernes-patrullaje-por-cuadrantes\/","title":{"rendered":"Polic\u00eda iniciar\u00e1 el viernes \u201cpatrullaje por cuadrantes\u201d"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/policia-iniciara-el-viernes-patrullaje-por-cuadrantes.jpeg\" alt=\"\" class=\"wp-image-87059\" width=\"231\" height=\"119\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/policia-iniciara-el-viernes-patrullaje-por-cuadrantes.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/policia-iniciara-el-viernes-patrullaje-por-cuadrantes-300x155.jpeg 300w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para contrarrestar los actos delictivos y disminuir la inseguridad ciudadana que azota la capital dominicana, la Polic\u00eda Nacional presentar\u00e1 el viernes venidero una nueva estrategia denominada \u201cpatrullaje por cuadrantes\u201d, que ser\u00e1 aplicada en el pol\u00edgono central.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este plan fue presentado ayer por el general de brigada, Juan Brown P\u00e9rez, durante un almuerzo&nbsp; presidido por el presidente Luis Abinader, junto a directores de medios de comunicaci\u00f3n, el director de la Polic\u00eda Nacional, Eduardo Alberto Then, el ministro de Interior y Polic\u00eda, Jes\u00fas V\u00e1squez, y otros altos mandos y ministros de primera l\u00ednea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El general Brown detall\u00f3, al presentar la nueva estrategia, que esta consistir\u00e1 en una vigilancia m\u00faltiple de agentes que incluir\u00e1 504 miembros distribuidos en tres turnos, es decir, que un total de 168 agentes estar\u00e1n distribuidos en \u00e1reas determinadas en&nbsp; diferentes horarios que establecer\u00e1 la entidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este patrullaje especial rodear\u00e1 las 84 cuadras de los sectores que comprenden el pol\u00edgono central de esta capital, cuya delimitaci\u00f3n abarca al Norte de la avenida Jhon F. Kennedy, al Sur de la avenida 27 de Febrero, al Este de la avenida Ortega y Gasset y al Oeste de la avenida Winston Churchill.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contar\u00e1n con un total de 33 camionetas y 84 motocicletas para desplazarse en las \u00e1reas correspondientes con la finalidad de contrarrestar la seguridad de los residentes, indic\u00f3 el general de brigada Brown.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que manipularan un total de 19 drones para mantener la vigilancia sobre la superficie con disponibilidad de 42 pilotos, utilizar\u00e1n c\u00e1maras instauradas en los uniformes para una auto vigilancia as\u00ed como tambi\u00e9n, manipularan instrumentos propio del orden, tales como la macana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este equipo de agentes ser\u00e1 dirigido por 17 supervisores comprendido por dos departamentos policiales que tendr\u00e1n la capacidad, seg\u00fan explic\u00f3 Brown, de bloquear las v\u00edas de acceso al pol\u00edgono en casos de emergencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tropas combinadas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente Luis Abinader dijo durante el encuentro que d\u00edas despu\u00e9s, se lanzar\u00e1 otro operativo para garantizar la seguridad ciudad en el territorio nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este ser\u00e1 anunciado tentativamente, el pr\u00f3ximo lunes y integrar\u00e1 las \u201ctropas combinadas\u201d de las Fuerzas Armadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Homicidios<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n resalt\u00f3 que este a\u00f1o, de mayo a noviembre, las cifras correspondientes a los \u00edndices de criminalidad han disminuido a diferencia de otros a\u00f1os, donde se evidenci\u00f3 un incremento&nbsp; significativo de estos casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que la aplicaci\u00f3n de la tecnolog\u00eda que ha introducido la Polic\u00eda Nacional en esta gesti\u00f3n, les ha permitido simplificar datos, descubrir los lugares donde con incidencia de delitos y algunas de sus causas por las que se produces este tipo de infracciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En referencia a la eficiencia de la recopilaci\u00f3n de esos datos, el mandatario detall\u00f3 que la Polic\u00eda Nacional tiene un \u201cmapa de calor\u201d donde visualizan las zonas m\u00e1s vulnerables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mayor criminalidad<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente, identificaron que el sector Alma Rosa ubicado en el municipio Santo Domingo Este, es el lugar \u201cn\u00famero uno en robos\u201d, arrojando una cifra de 142 desde mayo a noviembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En a\u00f1os anteriores, esta zona ocupaba los \u00faltimos lugares cuando realizaban las medicaciones concernientes a la criminalidad, especific\u00f3 el mandatario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n el general de brigada, Juan Brown P\u00e9rez, especific\u00f3 que durante los recientes actos de entretenimiento multitudinario se registr\u00f3 un incremento de denuncias de robo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cit\u00f3 que en los dos d\u00edas de conciertos del artista puertorrique\u00f1o, Bad Bunny, denunciaron 86 delitos asociados a robo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que esta cifra disminuy\u00f3 significativamente durante el reciente concierto de Daddy Yankee luego de que la Polic\u00eda Nacional estudiara el caso y de igual forma&nbsp; implementara un plan de acci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con relaci\u00f3n a este tema, Luis Abinader destac\u00f3 que la mayor\u00eda de estos casos son \u201creincidentes\u201d y que en el 86 por ciento hay consumo de sustancias il\u00edcitas de por medio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo Procesal Penal<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer mandatario prometi\u00f3 que antes del 27 de febrero se realizar\u00e1n algunas modificaciones al C\u00f3digo Procesal Penal debido a que la actual pieza es muy \u201cgarantista\u201d, y por esto no existen mayores consecuencias a los delitos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se necesitan m\u00e1s agentes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que la entidad necesita&nbsp; de entre 7 a 9 mil nuevos agentes y que tiene el objetivo de entrenar a al menos 3,000 polic\u00edas, con la creaci\u00f3n de m\u00e1s academias de entrenamiento junto a departamentos de homicidios y de desapariciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para contrarrestar los actos delictivos y disminuir la inseguridad ciudadana que azota la capital dominicana, la Polic\u00eda Nacional presentar\u00e1 el viernes venidero una nueva estrategia denominada \u201cpatrullaje por cuadrantes\u201d, que ser\u00e1 aplicada en el pol\u00edgono central. Este plan fue presentado ayer por el general de brigada, Juan Brown P\u00e9rez, durante un almuerzo&nbsp; presidido por el presidente Luis Abinader, junto a directores de medios de comunicaci\u00f3n, el director de la Polic\u00eda Nacional, Eduardo Alberto Then, el ministro de Interior y Polic\u00eda, Jes\u00fas V\u00e1squez, y otros altos mandos y ministros de primera l\u00ednea. El general Brown detall\u00f3, al presentar la nueva estrategia, que esta consistir\u00e1 en una vigilancia m\u00faltiple de agentes que incluir\u00e1 504 miembros distribuidos en tres turnos, es decir, que un total de 168 agentes estar\u00e1n distribuidos en \u00e1reas determinadas en&nbsp; diferentes horarios que establecer\u00e1 la entidad. Este patrullaje especial rodear\u00e1 las 84 cuadras de los sectores que comprenden el pol\u00edgono central de esta capital, cuya delimitaci\u00f3n abarca al Norte de la avenida Jhon F. Kennedy, al Sur de la avenida 27 de Febrero, al Este de la avenida Ortega y Gasset y al Oeste de la avenida Winston Churchill. Contar\u00e1n con un total de 33 camionetas y 84 motocicletas para desplazarse en las \u00e1reas correspondientes con la finalidad de contrarrestar la seguridad de los residentes, indic\u00f3 el general de brigada Brown. Dijo que manipularan un total de 19 drones para mantener la vigilancia sobre la superficie con disponibilidad de 42 pilotos, utilizar\u00e1n c\u00e1maras instauradas en los uniformes para una auto vigilancia as\u00ed como tambi\u00e9n, manipularan instrumentos propio del orden, tales como la macana. Este equipo de agentes ser\u00e1 dirigido por 17 supervisores comprendido por dos departamentos policiales que tendr\u00e1n la capacidad, seg\u00fan explic\u00f3 Brown, de bloquear las v\u00edas de acceso al pol\u00edgono en casos de emergencias. Tropas combinadas El presidente Luis Abinader dijo durante el encuentro que d\u00edas despu\u00e9s, se lanzar\u00e1 otro operativo para garantizar la seguridad ciudad en el territorio nacional. Este ser\u00e1 anunciado tentativamente, el pr\u00f3ximo lunes y integrar\u00e1 las \u201ctropas combinadas\u201d de las Fuerzas Armadas. Homicidios Tambi\u00e9n resalt\u00f3 que este a\u00f1o, de mayo a noviembre, las cifras correspondientes a los \u00edndices de criminalidad han disminuido a diferencia de otros a\u00f1os, donde se evidenci\u00f3 un incremento&nbsp; significativo de estos casos. Indic\u00f3 que la aplicaci\u00f3n de la tecnolog\u00eda que ha introducido la Polic\u00eda Nacional en esta gesti\u00f3n, les ha permitido simplificar datos, descubrir los lugares donde con incidencia de delitos y algunas de sus causas por las que se produces este tipo de infracciones. En referencia a la eficiencia de la recopilaci\u00f3n de esos datos, el mandatario detall\u00f3 que la Polic\u00eda Nacional tiene un \u201cmapa de calor\u201d donde visualizan las zonas m\u00e1s vulnerables. Mayor criminalidad Recientemente, identificaron que el sector Alma Rosa ubicado en el municipio Santo Domingo Este, es el lugar \u201cn\u00famero uno en robos\u201d, arrojando una cifra de 142 desde mayo a noviembre. En a\u00f1os anteriores, esta zona ocupaba los \u00faltimos lugares cuando realizaban las medicaciones concernientes a la criminalidad, especific\u00f3 el mandatario. Tambi\u00e9n el general de brigada, Juan Brown P\u00e9rez, especific\u00f3 que durante los recientes actos de entretenimiento multitudinario se registr\u00f3 un incremento de denuncias de robo. Cit\u00f3 que en los dos d\u00edas de conciertos del artista puertorrique\u00f1o, Bad Bunny, denunciaron 86 delitos asociados a robo. Indic\u00f3 que esta cifra disminuy\u00f3 significativamente durante el reciente concierto de Daddy Yankee luego de que la Polic\u00eda Nacional estudiara el caso y de igual forma&nbsp; implementara un plan de acci\u00f3n. Con relaci\u00f3n a este tema, Luis Abinader destac\u00f3 que la mayor\u00eda de estos casos son \u201creincidentes\u201d y que en el 86 por ciento hay consumo de sustancias il\u00edcitas de por medio. C\u00f3digo Procesal Penal El primer mandatario prometi\u00f3 que antes del 27 de febrero se realizar\u00e1n algunas modificaciones al C\u00f3digo Procesal Penal debido a que la actual pieza es muy \u201cgarantista\u201d, y por esto no existen mayores consecuencias a los delitos. Se necesitan m\u00e1s agentes Dijo que la entidad necesita&nbsp; de entre 7 a 9 mil nuevos agentes y que tiene el objetivo de entrenar a al menos 3,000 polic\u00edas, con la creaci\u00f3n de m\u00e1s academias de entrenamiento junto a departamentos de homicidios y de desapariciones.<\/p>\n","protected":false},"author":9,"featured_media":87059,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-87058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87058"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87058\/revisions"}],"predecessor-version":[{"id":87060,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87058\/revisions\/87060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87059"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}