{"id":87088,"date":"2022-11-30T11:37:35","date_gmt":"2022-11-30T15:37:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87088"},"modified":"2022-11-30T11:37:43","modified_gmt":"2022-11-30T15:37:43","slug":"detienen-mujer-que-se-grabo-golpeando-salvajemente-a-hija-de-tres-anos-en-gaspar-hernandez","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/detienen-mujer-que-se-grabo-golpeando-salvajemente-a-hija-de-tres-anos-en-gaspar-hernandez\/","title":{"rendered":"Detienen mujer que se grab\u00f3 golpeando salvajemente a hija de tres a\u00f1os en Gaspar Hern\u00e1ndez"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"234\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/imagecontent984810720180417113419-a299b7ce-focus-0-0-375-240.jpg\" alt=\"\" class=\"wp-image-87089\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/imagecontent984810720180417113419-a299b7ce-focus-0-0-375-240.jpg 366w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/imagecontent984810720180417113419-a299b7ce-focus-0-0-375-240-300x192.jpg 300w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Un video que circula en las redes sociales muestra los momentos en que una mujer golpea brutalmente en reiteradas ocasiones a su&nbsp;hija de aproximadamente dos a\u00f1os de edad,&nbsp;en un hecho ocurrido en el municipio&nbsp;Gaspar Hern\u00e1ndez, provincia Espaillat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el audiovisual se puede ver c\u00f3mo la mujer golpea a la ni\u00f1a en el rostro y la cabeza y vocifera\u00a0\u201ceso es lo que t\u00fa quieres que la maltrate\u201d\u00a0aparentemente refiri\u00e9ndose al padre de la menor.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"164\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/descarga-1-1.jpg\" alt=\"\" class=\"wp-image-87090\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/descarga-1-1.jpg 306w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/11\/descarga-1-1-300x161.jpg 300w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;madre&nbsp;no se compadeci\u00f3 de los incesantes llantos de&nbsp;la indefensa beb\u00e9&nbsp;y procedi\u00f3 a halarla por el pelo para tumbarla y luego patearla varias veces por la espalda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otra parte del video se escucha a la mujer decir:\u00a0\u201cque sufra\u201d, mientras contin\u00faa con los golpes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, los usuarios de las redes sociales han solicitado al&nbsp;Consejo Nacional para la Ni\u00f1ez y la Adolescencia (Conani) y a la Polic\u00eda Nacional&nbsp;acudir en auxilio de la ni\u00f1a y que las autoridades judiciales apliquen las medidas correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por respeto a la dignidad de la menor&nbsp;Diario Libre&nbsp;se reserva el derecho de no publicar el audiovisual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un video que circula en las redes sociales muestra los momentos en que una mujer golpea brutalmente en reiteradas ocasiones a su&nbsp;hija de aproximadamente dos a\u00f1os de edad,&nbsp;en un hecho ocurrido en el municipio&nbsp;Gaspar Hern\u00e1ndez, provincia Espaillat. En el audiovisual se puede ver c\u00f3mo la mujer golpea a la ni\u00f1a en el rostro y la cabeza y vocifera\u00a0\u201ceso es lo que t\u00fa quieres que la maltrate\u201d\u00a0aparentemente refiri\u00e9ndose al padre de la menor. La&nbsp;madre&nbsp;no se compadeci\u00f3 de los incesantes llantos de&nbsp;la indefensa beb\u00e9&nbsp;y procedi\u00f3 a halarla por el pelo para tumbarla y luego patearla varias veces por la espalda. En otra parte del video se escucha a la mujer decir:\u00a0\u201cque sufra\u201d, mientras contin\u00faa con los golpes Al respecto, los usuarios de las redes sociales han solicitado al&nbsp;Consejo Nacional para la Ni\u00f1ez y la Adolescencia (Conani) y a la Polic\u00eda Nacional&nbsp;acudir en auxilio de la ni\u00f1a y que las autoridades judiciales apliquen las medidas correspondientes. Por respeto a la dignidad de la menor&nbsp;Diario Libre&nbsp;se reserva el derecho de no publicar el audiovisual.<\/p>\n","protected":false},"author":9,"featured_media":87090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-87088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87088"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87088\/revisions"}],"predecessor-version":[{"id":87091,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87088\/revisions\/87091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87090"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}