{"id":87126,"date":"2022-12-01T14:00:13","date_gmt":"2022-12-01T18:00:13","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87126"},"modified":"2022-12-01T14:00:14","modified_gmt":"2022-12-01T18:00:14","slug":"congreso-aun-no-se-pone-de-acuerdo-sobre-el-presupuesto-del-proximo-ano","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/congreso-aun-no-se-pone-de-acuerdo-sobre-el-presupuesto-del-proximo-ano\/","title":{"rendered":"Congreso a\u00fan no se pone de acuerdo sobre el presupuesto del pr\u00f3ximo a\u00f1o"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212011342131.jpeg\" alt=\"\" class=\"wp-image-87127\" width=\"247\" height=\"127\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212011342131.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212011342131-300x155.jpeg 300w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A un mes de finalizar el a\u00f1o 2022, el Congreso Nacional&nbsp;<strong>a\u00fan mantiene los debates sobre el proyecto de ley de Presupuesto General del Estado<\/strong>&nbsp;para el a\u00f1o 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de la premura que lleva la iniciativa, los legisladores solo se han reunido ocho veces, sin que se tenga a\u00fan definido cu\u00e1ndo se pueda aprobar un informe.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Junto a eso, en varias de esas reuniones de la comisi\u00f3n bicameral que estudia el proyecto han enviado excusas o simplemente se han ausentado un gran cantidad de legisladores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Solo en la pen\u00faltima reuni\u00f3n, realizada el pasado 24 de noviembre,<\/strong>&nbsp;no estuvieron presentes 14 legisladores de 30 que tiene la comisi\u00f3n, por lo que la reuni\u00f3n cont\u00f3 con una presencia reducida casi a la mitad de sus miembros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este jueves la comisi\u00f3n se reunir\u00e1 y, seg\u00fan comentarios de algunos legisladores, se espera llegar a un consenso para que el viernes, en una sesi\u00f3n extraordinaria, la C\u00e1mara de Diputados conozca el proyecto de ley de Presupuesto General del Estado para el a\u00f1o 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A un mes de finalizar el a\u00f1o 2022, el Congreso Nacional&nbsp;a\u00fan mantiene los debates sobre el proyecto de ley de Presupuesto General del Estado&nbsp;para el a\u00f1o 2023. A pesar de la premura que lleva la iniciativa, los legisladores solo se han reunido ocho veces, sin que se tenga a\u00fan definido cu\u00e1ndo se pueda aprobar un informe.&nbsp; Junto a eso, en varias de esas reuniones de la comisi\u00f3n bicameral que estudia el proyecto han enviado excusas o simplemente se han ausentado un gran cantidad de legisladores. Solo en la pen\u00faltima reuni\u00f3n, realizada el pasado 24 de noviembre,&nbsp;no estuvieron presentes 14 legisladores de 30 que tiene la comisi\u00f3n, por lo que la reuni\u00f3n cont\u00f3 con una presencia reducida casi a la mitad de sus miembros. Este jueves la comisi\u00f3n se reunir\u00e1 y, seg\u00fan comentarios de algunos legisladores, se espera llegar a un consenso para que el viernes, en una sesi\u00f3n extraordinaria, la C\u00e1mara de Diputados conozca el proyecto de ley de Presupuesto General del Estado para el a\u00f1o 2023.<\/p>\n","protected":false},"author":9,"featured_media":87127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-87126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87126"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87126\/revisions"}],"predecessor-version":[{"id":87128,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87126\/revisions\/87128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87127"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}