{"id":87160,"date":"2022-12-03T08:31:56","date_gmt":"2022-12-03T12:31:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87160"},"modified":"2022-12-03T08:31:57","modified_gmt":"2022-12-03T12:31:57","slug":"la-corrupcion-en-la-policia-fue-denunciada-por-raul-alejandro-giron","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-corrupcion-en-la-policia-fue-denunciada-por-raul-alejandro-giron\/","title":{"rendered":"La corrupci\u00f3n en la Polic\u00eda fue denunciada por Ra\u00fal Alejandro Gir\u00f3n"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/la-corrupcion-en-la-policia-fue-denunciada-por-raul-alejandro-giron.jpeg\" alt=\"\" class=\"wp-image-87161\" width=\"283\" height=\"146\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/la-corrupcion-en-la-policia-fue-denunciada-por-raul-alejandro-giron.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/la-corrupcion-en-la-policia-fue-denunciada-por-raul-alejandro-giron-300x155.jpeg 300w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En mayo de 2021 el mayor del Ej\u00e9rcito,&nbsp;<strong>Ra\u00fal Alejandro Gir\u00f3n Jim\u00e9nez<\/strong>&nbsp;denunci\u00f3 supuestas ventas de \u201cespecialismos\u201d que se efectuaban en la Polic\u00eda Nacional, as\u00ed como la venta de rangos y pensiones de los agentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con Gir\u00f3n Jim\u00e9nez, el esquema fraudulento consist\u00eda en que los agentes ped\u00edan mejores puestos o rangos, que significaban salarios m\u00e1s altos, y a cambio ten\u00edan que&nbsp;<strong>entregarle un adelanto de tres meses del nuevo monto que iban a recibir.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mayor, que habl\u00f3 en la audiencia de coerci\u00f3n del caso Coral, acus\u00f3 al tambi\u00e9n&nbsp;<strong>militar Rafael N\u00fa\u00f1ez de Aza<\/strong>&nbsp;de idearse el esquema fraudulento de venta de \u201cespecialismos en la Polic\u00eda Nacional\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl director financiero al cual hago menci\u00f3n y el se\u00f1or Rafael N\u00fa\u00f1ez de Aza, encontraron la forma de multiplicar el dinero, hacen lo siguiente, dicen, nosotros tenemos un personal que no est\u00e1 laborando, que est\u00e1 cobrando, que devuelva ese dinero y ellos se quedan con una parte del dinero\u2026 Y si nosotros empezamos a venderle los especilismos a los polic\u00edas, porque eso se hace exclusivamente con los miembros de la Polic\u00eda Nacional, entonces se idean lo siguiente, si usted quer\u00eda un especialismo de 50 mil pesos, usted pagaba tres meses de adelanto de ese espcielismo\u201d, dijo en la audiencia Ra\u00fal Alejandro Gir\u00f3n Jim\u00e9nez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cP<strong>onga 300 gente mensuales, y no eran 300 eran m\u00e1s,<\/strong>&nbsp;a 150 mil pesos para que usted vea por d\u00f3nde se va la cosa\u201d, contin\u00fao dici\u00e9ndole a la jueza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otras de las revelaciones por parte de Gir\u00f3n fue el esquema de pensiones que se manejaba en la Polic\u00eda Nacional, donde a los miembros de esta instituci\u00f3n, sin importar el rango, se les pod\u00eda otorgar una pensi\u00f3n igual o superior a la suma de dinero que debe recibir el presidente de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Declar\u00f3 haber hecho una solicitud de transferencia hacia la entidad del orden con&nbsp;<strong>el fin de obtener una de estas pensiones.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo me pod\u00eda buscar f\u00e1cilmente, con el esquema que hay, una pensi\u00f3n de 300,000, 350,000 y hasta 400,000 mil pesos, y Abinader y yo nos vamos pensionados con lo mismo, siendo \u00e9l presidente y yo un simple guardia\u201d, indic\u00f3 el imputado en aquella ocasi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El escenario de su denuncia se present\u00f3 el 7 de mayo de 2021 cuando Ra\u00fal Gir\u00f3n Jim\u00e9nez, ex encargado de n\u00f3mina del&nbsp;<strong>Cuerpo Especializado de Seguridad Presidencial (Cusep)<\/strong>&nbsp;y uno de los principales implicados en el caso Coral, habl\u00f3 en la audiencia que conoc\u00eda la medida de coerci\u00f3n contra el grupo de imputados, encabezado por el mayor general Ad\u00e1n C\u00e1ceres Silvestre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La denuncia de Vila del Castillo<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esta denuncia recuerda la realizada esta semana por el comisionado ejecutivo encargado de reformar la\u00a0<strong>Polic\u00eda Nacional, Jos\u00e9 Vila del Castillo<\/strong>,\u00a0quien manifest\u00f3 el \u201cconstante trabajo que han tenido\u201d, a fin de ordenar la supuesta estructura inmoral que arropaba esa instituci\u00f3n, que denomin\u00f3 como \u201cel elefante blanco y la lacra de la corrupci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vila confes\u00f3 haber encontrado y desmontado en la gesti\u00f3n del mayor general Eduardo Alberto Then una estructura que cobraba por nombrar en los puestos policiales,&nbsp;<strong>decidir los traslados, los ascensos, cobrar las pensiones,<\/strong>&nbsp;renovar los uniformes y las armas nuevas, as\u00ed como otras irregularidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo digo as\u00ed de claro, una corrupci\u00f3n hist\u00f3rica, sistem\u00e1tica, llevada de un director a otro, impulsada desde la cabeza, obligando al \u00faltimo raso a pertenecer a ella\u201d, indic\u00f3 Vila al participar como expositor en el seminario internacional sobre Seguridad Ciudadana, en la biblioteca Pedro Mir, de la UASD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTodos los que no pertenec\u00edan al sistema fueron apartados, perseguidos o enviados a peque\u00f1as oficinas\u00bb, a\u00f1adi\u00f3 el comisionado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En mayo de 2021 el mayor del Ej\u00e9rcito,&nbsp;Ra\u00fal Alejandro Gir\u00f3n Jim\u00e9nez&nbsp;denunci\u00f3 supuestas ventas de \u201cespecialismos\u201d que se efectuaban en la Polic\u00eda Nacional, as\u00ed como la venta de rangos y pensiones de los agentes. De acuerdo con Gir\u00f3n Jim\u00e9nez, el esquema fraudulento consist\u00eda en que los agentes ped\u00edan mejores puestos o rangos, que significaban salarios m\u00e1s altos, y a cambio ten\u00edan que&nbsp;entregarle un adelanto de tres meses del nuevo monto que iban a recibir. El mayor, que habl\u00f3 en la audiencia de coerci\u00f3n del caso Coral, acus\u00f3 al tambi\u00e9n&nbsp;militar Rafael N\u00fa\u00f1ez de Aza&nbsp;de idearse el esquema fraudulento de venta de \u201cespecialismos en la Polic\u00eda Nacional\u201d. \u201cEl director financiero al cual hago menci\u00f3n y el se\u00f1or Rafael N\u00fa\u00f1ez de Aza, encontraron la forma de multiplicar el dinero, hacen lo siguiente, dicen, nosotros tenemos un personal que no est\u00e1 laborando, que est\u00e1 cobrando, que devuelva ese dinero y ellos se quedan con una parte del dinero\u2026 Y si nosotros empezamos a venderle los especilismos a los polic\u00edas, porque eso se hace exclusivamente con los miembros de la Polic\u00eda Nacional, entonces se idean lo siguiente, si usted quer\u00eda un especialismo de 50 mil pesos, usted pagaba tres meses de adelanto de ese espcielismo\u201d, dijo en la audiencia Ra\u00fal Alejandro Gir\u00f3n Jim\u00e9nez. \u201cPonga 300 gente mensuales, y no eran 300 eran m\u00e1s,&nbsp;a 150 mil pesos para que usted vea por d\u00f3nde se va la cosa\u201d, contin\u00fao dici\u00e9ndole a la jueza. Otras de las revelaciones por parte de Gir\u00f3n fue el esquema de pensiones que se manejaba en la Polic\u00eda Nacional, donde a los miembros de esta instituci\u00f3n, sin importar el rango, se les pod\u00eda otorgar una pensi\u00f3n igual o superior a la suma de dinero que debe recibir el presidente de la Rep\u00fablica. Declar\u00f3 haber hecho una solicitud de transferencia hacia la entidad del orden con&nbsp;el fin de obtener una de estas pensiones. \u201cYo me pod\u00eda buscar f\u00e1cilmente, con el esquema que hay, una pensi\u00f3n de 300,000, 350,000 y hasta 400,000 mil pesos, y Abinader y yo nos vamos pensionados con lo mismo, siendo \u00e9l presidente y yo un simple guardia\u201d, indic\u00f3 el imputado en aquella ocasi\u00f3n. El escenario de su denuncia se present\u00f3 el 7 de mayo de 2021 cuando Ra\u00fal Gir\u00f3n Jim\u00e9nez, ex encargado de n\u00f3mina del&nbsp;Cuerpo Especializado de Seguridad Presidencial (Cusep)&nbsp;y uno de los principales implicados en el caso Coral, habl\u00f3 en la audiencia que conoc\u00eda la medida de coerci\u00f3n contra el grupo de imputados, encabezado por el mayor general Ad\u00e1n C\u00e1ceres Silvestre. La denuncia de Vila del Castillo Esta denuncia recuerda la realizada esta semana por el comisionado ejecutivo encargado de reformar la\u00a0Polic\u00eda Nacional, Jos\u00e9 Vila del Castillo,\u00a0quien manifest\u00f3 el \u201cconstante trabajo que han tenido\u201d, a fin de ordenar la supuesta estructura inmoral que arropaba esa instituci\u00f3n, que denomin\u00f3 como \u201cel elefante blanco y la lacra de la corrupci\u00f3n\u201d. Vila confes\u00f3 haber encontrado y desmontado en la gesti\u00f3n del mayor general Eduardo Alberto Then una estructura que cobraba por nombrar en los puestos policiales,&nbsp;decidir los traslados, los ascensos, cobrar las pensiones,&nbsp;renovar los uniformes y las armas nuevas, as\u00ed como otras irregularidades. \u201cLo digo as\u00ed de claro, una corrupci\u00f3n hist\u00f3rica, sistem\u00e1tica, llevada de un director a otro, impulsada desde la cabeza, obligando al \u00faltimo raso a pertenecer a ella\u201d, indic\u00f3 Vila al participar como expositor en el seminario internacional sobre Seguridad Ciudadana, en la biblioteca Pedro Mir, de la UASD. \u00abTodos los que no pertenec\u00edan al sistema fueron apartados, perseguidos o enviados a peque\u00f1as oficinas\u00bb, a\u00f1adi\u00f3 el comisionado.<\/p>\n","protected":false},"author":9,"featured_media":87161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-87160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87160"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87160\/revisions"}],"predecessor-version":[{"id":87162,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87160\/revisions\/87162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87161"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}