{"id":87289,"date":"2022-12-12T12:39:51","date_gmt":"2022-12-12T16:39:51","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87289"},"modified":"2022-12-12T12:45:38","modified_gmt":"2022-12-12T16:45:38","slug":"3ra-gran-gala-de-navidad-2022-enamora-a-los-presentes-en-el-anfiteatro-de-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/3ra-gran-gala-de-navidad-2022-enamora-a-los-presentes-en-el-anfiteatro-de-puerto-plata\/","title":{"rendered":"3ra. Gran Gala de Navidad 2022 enamora a los presentes en el Anfiteatro de Puerto Plata"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM-1024x684.jpeg\" alt=\"\" class=\"wp-image-87290\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM-1024x684.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM-768x513.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Miles de personas se dieron cita para disfrutar del concierto dirigido por el maestro <strong>Jos\u00e9 Antonio Molina<\/strong> y la Orquesta Sinf\u00f3nica Nacional<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">San Felipe de Puerto Plata.- La Novia del Atl\u00e1ntico celebr\u00f3 la noche de este domingo la Gran Gala de la Navidad, un evento que por tercera ocasi\u00f3n lleva a los puertoplate\u00f1os<strong> Jos\u00e9 Ignacio Paliza<\/strong> y su esposa <strong>Isabel Brugal de Paliza<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s de cinco mil personas se dieron cita al Anfiteatro de Puerto Plata para disfrutar del concierto dirigido por el maestro<strong> Jos\u00e9 Antonio Molina y la Orquesta Sinf\u00f3nica Nacional,<\/strong> con las voces de artistas como <strong>Maridalia Hern\u00e1ndez, Manny Cruz, Alex Bueno, Jackeline Estevez <\/strong>y otros. <\/p>\n\n\n\n<figure class=\"wp-block-video aligncenter\"><video height=\"234\" style=\"aspect-ratio: 426 \/ 234;\" width=\"426\" controls src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/1670861340476.mp4\"><\/video><figcaption>3ra. Edicci\u00f3n de La Gran Gala de Navidad 2022 <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAgradezco a la familia puertoplate\u00f1a quienes abarrotaron anoche el anfiteatro Puerto Plata, para disfrutar de la tercera edici\u00f3n de la <strong>Gran Gala de Navidad 2022<\/strong>. Quiero resaltar el trabajo realizado por mi esposa Isabel quien encabez\u00f3 la organizaci\u00f3n. #FelizNavidad\u201d, manifest\u00f3 Paliza a trav\u00e9s de su cuenta de Twitter. <\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM-1024x684.jpeg\" alt=\"\" data-id=\"87290\" data-full-url=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM.jpeg\" data-link=\"http:\/\/sosuaonline.net\/inicio\/?attachment_id=87290\" class=\"wp-image-87290\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM-1024x684.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM-768x513.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.49-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.48-PM-1024x682.jpeg\" alt=\"\" data-id=\"87291\" data-full-url=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.48-PM.jpeg\" data-link=\"http:\/\/sosuaonline.net\/inicio\/?attachment_id=87291\" class=\"wp-image-87291\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.48-PM-1024x682.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.48-PM-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.48-PM-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.48-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.47-PM-1024x684.jpeg\" alt=\"\" data-id=\"87292\" data-full-url=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.47-PM.jpeg\" data-link=\"http:\/\/sosuaonline.net\/inicio\/?attachment_id=87292\" class=\"wp-image-87292\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.47-PM-1024x684.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.47-PM-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.47-PM-768x513.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.47-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.46-PM-1024x682.jpeg\" alt=\"\" data-id=\"87293\" data-full-url=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.46-PM.jpeg\" data-link=\"http:\/\/sosuaonline.net\/inicio\/?attachment_id=87293\" class=\"wp-image-87293\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.46-PM-1024x682.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.46-PM-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.46-PM-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.46-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.45-PM-1024x575.jpeg\" alt=\"\" data-id=\"87294\" data-full-url=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.45-PM.jpeg\" data-link=\"http:\/\/sosuaonline.net\/inicio\/?attachment_id=87294\" class=\"wp-image-87294\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.45-PM-1024x575.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.45-PM-300x168.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.45-PM-768x431.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.45-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.44-PM-1024x684.jpeg\" alt=\"\" data-id=\"87295\" data-full-url=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.44-PM.jpeg\" data-link=\"http:\/\/sosuaonline.net\/inicio\/?attachment_id=87295\" class=\"wp-image-87295\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.44-PM-1024x684.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.44-PM-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.44-PM-768x513.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-12-at-12.01.44-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 \u201cMi reconocimiento al maestro <strong>Jos\u00e9 Antonio Molina<\/strong> y todos los miembros de la Orquesta Sinf\u00f3nica Nacional, a Pinky Pintor por la excelente producci\u00f3n, y a los artistas invitados\u201d, agreg\u00f3 <strong>Paliza<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La velada frente al Oc\u00e9ano Atl\u00e1ntico se prest\u00f3 para que los presentes escucharan y bailaran los temas como, Ca\u00f1a Braba, Por Amor, Feliz Navidad, Lleg\u00f3 Juanita, Pap\u00e1 Boc\u00f3, Navidad Sin Mi Madre, Dilema de Juan Lockward, Cuando Te Beso, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acto se desarroll\u00f3 bajo estrictas medidas de seguridad para el disfrute sano y tranquilo de toda la familia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miles de personas se dieron cita para disfrutar del concierto dirigido por el maestro Jos\u00e9 Antonio Molina y la Orquesta Sinf\u00f3nica Nacional San Felipe de Puerto Plata.- La Novia del Atl\u00e1ntico celebr\u00f3 la noche de este domingo la Gran Gala de la Navidad, un evento que por tercera ocasi\u00f3n lleva a los puertoplate\u00f1os Jos\u00e9 Ignacio Paliza y su esposa Isabel Brugal de Paliza. M\u00e1s de cinco mil personas se dieron cita al Anfiteatro de Puerto Plata para disfrutar del concierto dirigido por el maestro Jos\u00e9 Antonio Molina y la Orquesta Sinf\u00f3nica Nacional, con las voces de artistas como Maridalia Hern\u00e1ndez, Manny Cruz, Alex Bueno, Jackeline Estevez y otros. \u201cAgradezco a la familia puertoplate\u00f1a quienes abarrotaron anoche el anfiteatro Puerto Plata, para disfrutar de la tercera edici\u00f3n de la Gran Gala de Navidad 2022. Quiero resaltar el trabajo realizado por mi esposa Isabel quien encabez\u00f3 la organizaci\u00f3n. #FelizNavidad\u201d, manifest\u00f3 Paliza a trav\u00e9s de su cuenta de Twitter. Agreg\u00f3 \u201cMi reconocimiento al maestro Jos\u00e9 Antonio Molina y todos los miembros de la Orquesta Sinf\u00f3nica Nacional, a Pinky Pintor por la excelente producci\u00f3n, y a los artistas invitados\u201d, agreg\u00f3 Paliza. La velada frente al Oc\u00e9ano Atl\u00e1ntico se prest\u00f3 para que los presentes escucharan y bailaran los temas como, Ca\u00f1a Braba, Por Amor, Feliz Navidad, Lleg\u00f3 Juanita, Pap\u00e1 Boc\u00f3, Navidad Sin Mi Madre, Dilema de Juan Lockward, Cuando Te Beso, entre otros. El acto se desarroll\u00f3 bajo estrictas medidas de seguridad para el disfrute sano y tranquilo de toda la familia.<\/p>\n","protected":false},"author":12,"featured_media":87290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88,460],"tags":[],"class_list":["post-87289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-turismo-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87289"}],"version-history":[{"count":4,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87289\/revisions"}],"predecessor-version":[{"id":87300,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87289\/revisions\/87300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87290"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}