{"id":87304,"date":"2022-12-12T19:24:11","date_gmt":"2022-12-12T23:24:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87304"},"modified":"2022-12-12T19:24:20","modified_gmt":"2022-12-12T23:24:20","slug":"vacaciones-escolares-iniciaran-el-21-de-diciembre-tras-consenso-entre-minerd-y-adp","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/vacaciones-escolares-iniciaran-el-21-de-diciembre-tras-consenso-entre-minerd-y-adp\/","title":{"rendered":"Vacaciones escolares iniciar\u00e1n el 21 de diciembre, tras consenso entre Minerd y ADP"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212121949131.jpeg\" alt=\"\" class=\"wp-image-87305\" width=\"274\" height=\"141\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212121949131.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212121949131-300x155.jpeg 300w\" sizes=\"auto, (max-width: 274px) 100vw, 274px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Las vacaciones por motivo a las festividades navide\u00f1as<strong>\u00a0iniciar\u00e1n el mi\u00e9rcoles 21 de diciembre<\/strong>, luego de que se reajustara la fecha el\u00a0<strong>calendario escolar<\/strong>\u00a0durante un acuerdo entre sectores educativos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo dio a conocer a reporteros de List\u00edn Diario el ministro de Educaci\u00f3n, \u00c1ngel Hern\u00e1ndez, quien inform\u00f3 que presidi\u00f3 una reuni\u00f3n este lunes con el Consejo Nacional de Educaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHoy en la reuni\u00f3n del Consejo Nacional de Educaci\u00f3n se acord\u00f3 aprobar que las vacaciones se inicien el mi\u00e9rcoles 21 con la aprobaci\u00f3n y compromiso de cumplir del presidente de la Asociaci\u00f3n Dominicana de Profesores (ADP), Eduardo Hidalgo\u201d, dijo el ministro al ser cuestionado sobre el tema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precisamente hoy el presidente de la ADP indic\u00f3 en un documento que el gremio no \u201cadelant\u00f3\u201d las vacaciones navide\u00f1as<strong>&nbsp;\u201csino que est\u00e1 planificando la finalizaci\u00f3n de los procesos en las fechas en que tradicionalmente se ha hecho,<\/strong>&nbsp;entre el 16 al 20 de diciembre\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, el Minerd hab\u00eda reiterado su posici\u00f3n de que las mismas iniciar\u00edan a partir del 24, D\u00eda de Nochebuena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero esto ya fue modificado este lunes luego de que la ADP solicitara un&nbsp;<strong>conversatorio con el Minerd<\/strong>&nbsp;y el consejo educativo sobre la \u201cconvivencia de las vacaciones\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respecto al tema, antes de hacer el consenso, Hern\u00e1ndez catalog\u00f3 la posici\u00f3n de la ADP como una \u201cpostura ambigua, sin compromiso con lo principal: el aprendizaje de los ni\u00f1os\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los alumnos regresaran a las aulas nuevamente&nbsp;<strong>el d\u00eda 10 de enero del a\u00f1o 2023<\/strong>.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las vacaciones por motivo a las festividades navide\u00f1as\u00a0iniciar\u00e1n el mi\u00e9rcoles 21 de diciembre, luego de que se reajustara la fecha el\u00a0calendario escolar\u00a0durante un acuerdo entre sectores educativos. As\u00ed lo dio a conocer a reporteros de List\u00edn Diario el ministro de Educaci\u00f3n, \u00c1ngel Hern\u00e1ndez, quien inform\u00f3 que presidi\u00f3 una reuni\u00f3n este lunes con el Consejo Nacional de Educaci\u00f3n. \u201cHoy en la reuni\u00f3n del Consejo Nacional de Educaci\u00f3n se acord\u00f3 aprobar que las vacaciones se inicien el mi\u00e9rcoles 21 con la aprobaci\u00f3n y compromiso de cumplir del presidente de la Asociaci\u00f3n Dominicana de Profesores (ADP), Eduardo Hidalgo\u201d, dijo el ministro al ser cuestionado sobre el tema. Precisamente hoy el presidente de la ADP indic\u00f3 en un documento que el gremio no \u201cadelant\u00f3\u201d las vacaciones navide\u00f1as&nbsp;\u201csino que est\u00e1 planificando la finalizaci\u00f3n de los procesos en las fechas en que tradicionalmente se ha hecho,&nbsp;entre el 16 al 20 de diciembre\u00bb. Sin embargo, el Minerd hab\u00eda reiterado su posici\u00f3n de que las mismas iniciar\u00edan a partir del 24, D\u00eda de Nochebuena. Pero esto ya fue modificado este lunes luego de que la ADP solicitara un&nbsp;conversatorio con el Minerd&nbsp;y el consejo educativo sobre la \u201cconvivencia de las vacaciones\u201d. Respecto al tema, antes de hacer el consenso, Hern\u00e1ndez catalog\u00f3 la posici\u00f3n de la ADP como una \u201cpostura ambigua, sin compromiso con lo principal: el aprendizaje de los ni\u00f1os\u201d. Los alumnos regresaran a las aulas nuevamente&nbsp;el d\u00eda 10 de enero del a\u00f1o 2023.&nbsp;<\/p>\n","protected":false},"author":9,"featured_media":87305,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-87304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87304"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87304\/revisions"}],"predecessor-version":[{"id":87306,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87304\/revisions\/87306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87305"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}