{"id":87350,"date":"2022-12-13T14:06:26","date_gmt":"2022-12-13T18:06:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87350"},"modified":"2022-12-13T14:06:28","modified_gmt":"2022-12-13T18:06:28","slug":"dejan-en-libertad-a-dos-hombres-acusados-de-matar-a-joven-taxista-en-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dejan-en-libertad-a-dos-hombres-acusados-de-matar-a-joven-taxista-en-puerto-plata\/","title":{"rendered":"Dejan en libertad a dos hombres acusados de matar a joven taxista en Puerto Plata"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212131327571.jpeg\" alt=\"\" class=\"wp-image-87351\" width=\"280\" height=\"143\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212131327571.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212131327571-300x154.jpeg 300w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El juez de la oficina de Atenci\u00f3n Permanente del Distrito Judicial de Puerto Plata, Pascual Francisco Abreu, vari\u00f3 la medida de coerci\u00f3n de 12 meses de prisi\u00f3n preventiva a\u00a0<strong>Elisaul Alexander Mercado e Isaac Gabriel Jim\u00e9nez Guti\u00e9rrez,<\/strong>\u00a0acusados de\u00a0<strong>la muerte a golpes\u00a0<\/strong>al taxista\u00a0<strong>Alberto Grull\u00f3n Uceta<\/strong>\u00a0con el fin de despojarlo de su veh\u00edculo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los familiares del joven de 21 a\u00f1os,&nbsp;<strong>asesinado el 12 de noviembre de 2021<\/strong>&nbsp;en Villa Isabela, provincia Puerto Plata, expresaron su desacuerdo con la decisi\u00f3n del tribunal, la cual otorga libertad a los dos imputados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El juez vario la medida a los dos encartados de un a\u00f1o de prisi\u00f3n preventiva e impuso el pago de una&nbsp;<strong>garant\u00eda econ\u00f3mica de 2 millones de pesos<\/strong>, cifra que deber\u00e1 ser pagada a trav\u00e9s de una empresa aseguradora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los dos hombres le quitaron la vida al taxista luego de solicitarle un servicio para qu\u00e9 los trasladara desde el elevado del Cienfuegos, en Santiago, a la playa La Ensenada, Puerto Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marlyn Ram\u00edrez de Le\u00f3n, esposa del hombre asesinado,&nbsp;<strong>dijo no estar de acuerdo la variaci\u00f3n<\/strong>, en virtud de que los dos implicados en la muerte de su esposo, no solo representan un peligro para su familia, sino tambi\u00e9n para la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, asegur\u00f3 que apelar\u00e1n la decisi\u00f3n del juez para que ambos imputados sean devueltos a prisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Muerte del taxista<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El informe policial indica que el taxista Alberto Grull\u00f3n fue asesinado por dos hombres residentes en el barrio Libertad de la provincia de Santiago,&nbsp;<strong>con el fin de despojarlo de su veh\u00edculo&nbsp;<\/strong>en el municipio La Isabela, provincia Puerto Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los malhechores le propinaron golpes con piedras en la cabeza y dejaron el cuerpo abandonado en Villa Isabela. El joven hab\u00eda sido reportado como desaparecido por sus familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan arroj\u00f3 la investigaci\u00f3n en torno al caso, Grull\u00f3n Uceta falleci\u00f3 a consecuencia de&nbsp;<strong>trauma contuso en la cabeza y m\u00faltiples heridas cortantes.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los imputados fueron apresados en el municipio de Cabarete, provincia Puerto Plata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El juez de la oficina de Atenci\u00f3n Permanente del Distrito Judicial de Puerto Plata, Pascual Francisco Abreu, vari\u00f3 la medida de coerci\u00f3n de 12 meses de prisi\u00f3n preventiva a\u00a0Elisaul Alexander Mercado e Isaac Gabriel Jim\u00e9nez Guti\u00e9rrez,\u00a0acusados de\u00a0la muerte a golpes\u00a0al taxista\u00a0Alberto Grull\u00f3n Uceta\u00a0con el fin de despojarlo de su veh\u00edculo. Los familiares del joven de 21 a\u00f1os,&nbsp;asesinado el 12 de noviembre de 2021&nbsp;en Villa Isabela, provincia Puerto Plata, expresaron su desacuerdo con la decisi\u00f3n del tribunal, la cual otorga libertad a los dos imputados. El juez vario la medida a los dos encartados de un a\u00f1o de prisi\u00f3n preventiva e impuso el pago de una&nbsp;garant\u00eda econ\u00f3mica de 2 millones de pesos, cifra que deber\u00e1 ser pagada a trav\u00e9s de una empresa aseguradora. Los dos hombres le quitaron la vida al taxista luego de solicitarle un servicio para qu\u00e9 los trasladara desde el elevado del Cienfuegos, en Santiago, a la playa La Ensenada, Puerto Plata. Marlyn Ram\u00edrez de Le\u00f3n, esposa del hombre asesinado,&nbsp;dijo no estar de acuerdo la variaci\u00f3n, en virtud de que los dos implicados en la muerte de su esposo, no solo representan un peligro para su familia, sino tambi\u00e9n para la sociedad. Asimismo, asegur\u00f3 que apelar\u00e1n la decisi\u00f3n del juez para que ambos imputados sean devueltos a prisi\u00f3n. Muerte del taxista El informe policial indica que el taxista Alberto Grull\u00f3n fue asesinado por dos hombres residentes en el barrio Libertad de la provincia de Santiago,&nbsp;con el fin de despojarlo de su veh\u00edculo&nbsp;en el municipio La Isabela, provincia Puerto Plata. Los malhechores le propinaron golpes con piedras en la cabeza y dejaron el cuerpo abandonado en Villa Isabela. El joven hab\u00eda sido reportado como desaparecido por sus familiares. Seg\u00fan arroj\u00f3 la investigaci\u00f3n en torno al caso, Grull\u00f3n Uceta falleci\u00f3 a consecuencia de&nbsp;trauma contuso en la cabeza y m\u00faltiples heridas cortantes. Los imputados fueron apresados en el municipio de Cabarete, provincia Puerto Plata.<\/p>\n","protected":false},"author":9,"featured_media":87351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-87350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87350"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87350\/revisions"}],"predecessor-version":[{"id":87352,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87350\/revisions\/87352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87351"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}