{"id":87383,"date":"2022-12-19T14:31:30","date_gmt":"2022-12-19T18:31:30","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87383"},"modified":"2022-12-19T14:31:35","modified_gmt":"2022-12-19T18:31:35","slug":"indicadores-coronavirus-casi-se-duplican-en-ultimos-18-dias","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/indicadores-coronavirus-casi-se-duplican-en-ultimos-18-dias\/","title":{"rendered":"Indicadores coronavirus casi se duplican en \u00faltimos 18 d\u00edas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/salu.jpg\" alt=\"\" class=\"wp-image-87384\" width=\"250\" height=\"171\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/salu.jpg 673w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/salu-300x205.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/salu-75x52.jpg 75w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los principales indicadores del comportamiento del Covid-19, entre ellos los casos activos, las hospitalizaciones y la positividad acumulada de cuatro semanas se han casi duplicado en el pa\u00eds en los \u00faltimos 18 d\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el primero de diciembre a la fecha el sistema ha notificado 5,738 nuevos contagios captados mediante pruebas de laboratorio; la positividad acumulada de cuatro semanas pas\u00f3 de 5.27% a 12.98% y los casos activos de 1,838 en dicha fecha a 2,647 notificados ayer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La positividad diaria pas\u00f3 de 22.30% reportada el pasado primero de diciembre a 25.59% notificada ayer, porcentaje en que ha estado oscilando esta \u00faltima semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las hospitalizaciones tambi\u00e9n incrementaron, reportando a inicio de mes 48 hospitalizados y ayer se notificaron 67 pacientes tanto en camas regulares como de cuidados intensivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nuevos casos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ayer fueron reportados 271 nuevos casos captados en 2,060 pruebas de laboratorio procesadas en las \u00faltimas 24 horas, de acuerdo a los datos del bolet\u00edn epidemiol\u00f3gico n\u00famero 1004 emitido ayer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La positividad diaria se coloc\u00f3 en 25.59 por ciento y la acumulada de cuatro semanas en 12.98%.&nbsp; De los nuevos reportes, 144 casos fueron notificados en el Distrito Nacional, demarcaci\u00f3n que desde que inici\u00f3 la pandemia a la fecha ha reportado al sistema 175,380 casos positivos del virus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo report\u00f3 31 nuevos casos, para un acumulado desde marzo del 2020 a la fecha de 133,879;&nbsp; la provincia Duarte report\u00f3 11 casos nuevos para un acumulado de 15,246 contagios y La Altagracia 10 caso, demarcaci\u00f3n que tiene un acumulado de 20,361 reportes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santiago, que por lo general es una de las provincias que mantiene mayor reporte de casos, en el informe de ayer solo notific\u00f3 ocho nuevos contagios, manteniendo unos 73,267 registros positivos acumulados a la fecha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los principales indicadores del comportamiento del Covid-19, entre ellos los casos activos, las hospitalizaciones y la positividad acumulada de cuatro semanas se han casi duplicado en el pa\u00eds en los \u00faltimos 18 d\u00edas. Desde el primero de diciembre a la fecha el sistema ha notificado 5,738 nuevos contagios captados mediante pruebas de laboratorio; la positividad acumulada de cuatro semanas pas\u00f3 de 5.27% a 12.98% y los casos activos de 1,838 en dicha fecha a 2,647 notificados ayer. La positividad diaria pas\u00f3 de 22.30% reportada el pasado primero de diciembre a 25.59% notificada ayer, porcentaje en que ha estado oscilando esta \u00faltima semana. Las hospitalizaciones tambi\u00e9n incrementaron, reportando a inicio de mes 48 hospitalizados y ayer se notificaron 67 pacientes tanto en camas regulares como de cuidados intensivos. Nuevos casos Ayer fueron reportados 271 nuevos casos captados en 2,060 pruebas de laboratorio procesadas en las \u00faltimas 24 horas, de acuerdo a los datos del bolet\u00edn epidemiol\u00f3gico n\u00famero 1004 emitido ayer. La positividad diaria se coloc\u00f3 en 25.59 por ciento y la acumulada de cuatro semanas en 12.98%.&nbsp; De los nuevos reportes, 144 casos fueron notificados en el Distrito Nacional, demarcaci\u00f3n que desde que inici\u00f3 la pandemia a la fecha ha reportado al sistema 175,380 casos positivos del virus. Santo Domingo report\u00f3 31 nuevos casos, para un acumulado desde marzo del 2020 a la fecha de 133,879;&nbsp; la provincia Duarte report\u00f3 11 casos nuevos para un acumulado de 15,246 contagios y La Altagracia 10 caso, demarcaci\u00f3n que tiene un acumulado de 20,361 reportes. Santiago, que por lo general es una de las provincias que mantiene mayor reporte de casos, en el informe de ayer solo notific\u00f3 ocho nuevos contagios, manteniendo unos 73,267 registros positivos acumulados a la fecha.<\/p>\n","protected":false},"author":9,"featured_media":87384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-87383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87383"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87383\/revisions"}],"predecessor-version":[{"id":87385,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87383\/revisions\/87385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87384"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}