{"id":87410,"date":"2022-12-22T07:59:53","date_gmt":"2022-12-22T11:59:53","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87410"},"modified":"2022-12-22T07:59:54","modified_gmt":"2022-12-22T11:59:54","slug":"no-hay-restriccion-de-expendio-de-bebidas-alcoholicas-el-24-y-31-de-diciembre","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/no-hay-restriccion-de-expendio-de-bebidas-alcoholicas-el-24-y-31-de-diciembre\/","title":{"rendered":"No hay restricci\u00f3n de expendio de bebidas alcoh\u00f3licas el 24 y 31 de diciembre"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"170\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/no-hay-restriccion-de-expendio-de-bebidas-alcoholicas-el-24-y-31-de-diciembre.jpeg\" alt=\"\" class=\"wp-image-87411\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/no-hay-restriccion-de-expendio-de-bebidas-alcoholicas-el-24-y-31-de-diciembre.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/no-hay-restriccion-de-expendio-de-bebidas-alcoholicas-el-24-y-31-de-diciembre-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio de Interior y Polic\u00eda extendi\u00f3 desde este mi\u00e9rcoles y hasta el 8 de enero el horario de expendio de bebidas alcoh\u00f3licas en todo el territorio nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nuevo horario autoriza la venta y consumo de bebidas alcoh\u00f3licas de&nbsp;<strong>domingo a jueves hasta las 3:00 a.m.<\/strong>&nbsp;y&nbsp;<strong>viernes y s\u00e1bado hasta las 4:00 de la ma\u00f1ana<\/strong>. El 24 y 31 de diciembre no hay restricciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La resoluci\u00f3n 009-2022 consigna que la flexibilizaci\u00f3n con motivo de la celebraci\u00f3n de las fiestas<\/strong>&nbsp;de Navidad y de fin de a\u00f1o tambi\u00e9n contiene un llamado a la mesura y una exhortaci\u00f3n a departir en familia y comunidad en armon\u00eda, recordando que el \u201cesp\u00edritu de estas fechas es la uni\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La medida advierte que&nbsp;<strong>su violaci\u00f3n dar\u00eda lugar al cierre temporal o definitivo<\/strong>&nbsp;del establecimiento y a la cancelaci\u00f3n de la licencia o permiso para operar, sin perjuicio de otras sanciones legales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de una nota de prensa, Interior y Polic\u00eda, ndica que la Direcci\u00f3n Nacional de Control de Expendio de Bebidas Alcoh\u00f3licas (COBA), con apoyo de la Polic\u00eda Nacional velar\u00e1 por el cumplimiento de la disposici\u00f3n y promover\u00e1 las acciones pertinentes de acuerdo con las leyes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cEl Ministerio de Interior conf\u00eda en la sensatez y la madurez de la poblaci\u00f3n<\/strong>,&nbsp;de la que espera disfrute con comedimiento de estas festividades y tenga a la familia como n\u00facleo en sus festejos para recibir el 2023 con j\u00fabilo y tomar las previsiones necesarias para que su entorno sea m\u00e1s seguro\u201d, establecen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Interior y Polic\u00eda extendi\u00f3 desde este mi\u00e9rcoles y hasta el 8 de enero el horario de expendio de bebidas alcoh\u00f3licas en todo el territorio nacional. El nuevo horario autoriza la venta y consumo de bebidas alcoh\u00f3licas de&nbsp;domingo a jueves hasta las 3:00 a.m.&nbsp;y&nbsp;viernes y s\u00e1bado hasta las 4:00 de la ma\u00f1ana. El 24 y 31 de diciembre no hay restricciones. La resoluci\u00f3n 009-2022 consigna que la flexibilizaci\u00f3n con motivo de la celebraci\u00f3n de las fiestas&nbsp;de Navidad y de fin de a\u00f1o tambi\u00e9n contiene un llamado a la mesura y una exhortaci\u00f3n a departir en familia y comunidad en armon\u00eda, recordando que el \u201cesp\u00edritu de estas fechas es la uni\u00f3n\u201d. La medida advierte que&nbsp;su violaci\u00f3n dar\u00eda lugar al cierre temporal o definitivo&nbsp;del establecimiento y a la cancelaci\u00f3n de la licencia o permiso para operar, sin perjuicio de otras sanciones legales. A trav\u00e9s de una nota de prensa, Interior y Polic\u00eda, ndica que la Direcci\u00f3n Nacional de Control de Expendio de Bebidas Alcoh\u00f3licas (COBA), con apoyo de la Polic\u00eda Nacional velar\u00e1 por el cumplimiento de la disposici\u00f3n y promover\u00e1 las acciones pertinentes de acuerdo con las leyes. \u201cEl Ministerio de Interior conf\u00eda en la sensatez y la madurez de la poblaci\u00f3n,&nbsp;de la que espera disfrute con comedimiento de estas festividades y tenga a la familia como n\u00facleo en sus festejos para recibir el 2023 con j\u00fabilo y tomar las previsiones necesarias para que su entorno sea m\u00e1s seguro\u201d, establecen<\/p>\n","protected":false},"author":9,"featured_media":87411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-87410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87410"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87410\/revisions"}],"predecessor-version":[{"id":87412,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87410\/revisions\/87412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87411"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}