{"id":87425,"date":"2022-12-23T08:34:13","date_gmt":"2022-12-23T12:34:13","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87425"},"modified":"2022-12-23T08:34:14","modified_gmt":"2022-12-23T12:34:14","slug":"trafico-aereo-entre-rd-y-estados-unidos-fluye-normal-a-pesar-de-tormenta","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/trafico-aereo-entre-rd-y-estados-unidos-fluye-normal-a-pesar-de-tormenta\/","title":{"rendered":"Tr\u00e1fico a\u00e9reo entre RD y Estados Unidos fluye normal a pesar de tormenta"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212230210091.jpeg\" alt=\"\" class=\"wp-image-87426\" width=\"254\" height=\"131\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212230210091.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2022\/12\/202212230210091-300x155.jpeg 300w\" sizes=\"auto, (max-width: 254px) 100vw, 254px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El tr\u00e1fico a\u00e9reo entre Rep\u00fablica Dominicana y Estados Unidos se mantuvo normal en el transcurso de este jueves, a pesar de la fuerte tormenta invernal que esta azotado ese pa\u00eds y que ha provocado la cancelaci\u00f3n de al menos 1,800&nbsp; vuelos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aeropuertos Dominicanos  inform\u00f3 que hasta el momento no se ha registrado ninguna cancelaci\u00f3n de vuelos desde y hacia ciudades de Estados Unidos desde el Aeropuerto Internacional de Las Am\u00e9ricas (AILA), Jos\u00e9 Francisco Pe\u00f1a G\u00f3mez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan explic\u00f3 la empresa concesionaria, de seis de los principales aeropuertos dominicanos, los vuelos hacia territorio norteamericano se mantienen saliendo y llegando con normalidad, a pesar de la situaci\u00f3n climatol\u00f3gica que se registra en esa naci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con los informe, m\u00e1s de 1,800 vuelos han sido cancelados en todo Estados Unidos este jueves debido a una gran tormenta invernal, con una triple amenaza de fuertes nevadas, vientos huracanados y fr\u00edo intenso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este jueves los vuelos procedentes de ciudades como Nueva York, Boston, Massachusetts, Miami, Florida, Filadelfia, New Jersey, Atlanta, Fort&nbsp; Lauderdale, Orlando, Florida y otras ciudades estadounidenses llegaban y sal\u00edan repletos de pasajeros tanto nacionales como extranjeros.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con datos extraoficiales ya han ingresado al pa\u00eds, desde ciudades norteamericanas con motivo de las navidades, m\u00e1s de 350 mil pasajeros en su mayor\u00eda dominicanos radicados en los Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aerodom tiene proyecci\u00f3n de que este a\u00f1o durante el periodo navide\u00f1o m\u00e1s de 500,000 mil pasajeros se movilizar\u00e1n por el aeropuerto Internacional de Las Am\u00e9ricas, durante este mes de diciembre y parte de enero del 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con los detalles ofrecidos por la empresa aeroportuaria, todav\u00eda no se ha recibido ning\u00fan reporte de vuelos oficial de parte de las l\u00edneas a\u00e9reas que operan vuelos regulares desde territorio estadounidenses hacia la Rep\u00fablica Dominicana por el aeropuerto internacional de Las Am\u00e9ricas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En algunas partes del territorio norteamericano azotados por un peligroso frente fr\u00edo del \u00c1rtico, ya se registran tormentas blancas que impiden la visibilidad y vuelven peligrosas las condiciones en las carreteras<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El tr\u00e1fico a\u00e9reo entre Rep\u00fablica Dominicana y Estados Unidos se mantuvo normal en el transcurso de este jueves, a pesar de la fuerte tormenta invernal que esta azotado ese pa\u00eds y que ha provocado la cancelaci\u00f3n de al menos 1,800&nbsp; vuelos. Aeropuertos Dominicanos inform\u00f3 que hasta el momento no se ha registrado ninguna cancelaci\u00f3n de vuelos desde y hacia ciudades de Estados Unidos desde el Aeropuerto Internacional de Las Am\u00e9ricas (AILA), Jos\u00e9 Francisco Pe\u00f1a G\u00f3mez. Seg\u00fan explic\u00f3 la empresa concesionaria, de seis de los principales aeropuertos dominicanos, los vuelos hacia territorio norteamericano se mantienen saliendo y llegando con normalidad, a pesar de la situaci\u00f3n climatol\u00f3gica que se registra en esa naci\u00f3n. De acuerdo con los informe, m\u00e1s de 1,800 vuelos han sido cancelados en todo Estados Unidos este jueves debido a una gran tormenta invernal, con una triple amenaza de fuertes nevadas, vientos huracanados y fr\u00edo intenso. Este jueves los vuelos procedentes de ciudades como Nueva York, Boston, Massachusetts, Miami, Florida, Filadelfia, New Jersey, Atlanta, Fort&nbsp; Lauderdale, Orlando, Florida y otras ciudades estadounidenses llegaban y sal\u00edan repletos de pasajeros tanto nacionales como extranjeros.&nbsp;&nbsp; De acuerdo con datos extraoficiales ya han ingresado al pa\u00eds, desde ciudades norteamericanas con motivo de las navidades, m\u00e1s de 350 mil pasajeros en su mayor\u00eda dominicanos radicados en los Estados Unidos. Aerodom tiene proyecci\u00f3n de que este a\u00f1o durante el periodo navide\u00f1o m\u00e1s de 500,000 mil pasajeros se movilizar\u00e1n por el aeropuerto Internacional de Las Am\u00e9ricas, durante este mes de diciembre y parte de enero del 2023. De acuerdo con los detalles ofrecidos por la empresa aeroportuaria, todav\u00eda no se ha recibido ning\u00fan reporte de vuelos oficial de parte de las l\u00edneas a\u00e9reas que operan vuelos regulares desde territorio estadounidenses hacia la Rep\u00fablica Dominicana por el aeropuerto internacional de Las Am\u00e9ricas En algunas partes del territorio norteamericano azotados por un peligroso frente fr\u00edo del \u00c1rtico, ya se registran tormentas blancas que impiden la visibilidad y vuelven peligrosas las condiciones en las carreteras<\/p>\n","protected":false},"author":9,"featured_media":87426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-87425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87425"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87425\/revisions"}],"predecessor-version":[{"id":87427,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87425\/revisions\/87427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87426"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}