{"id":87973,"date":"2023-02-09T07:20:02","date_gmt":"2023-02-09T11:20:02","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=87973"},"modified":"2023-02-09T07:20:12","modified_gmt":"2023-02-09T11:20:12","slug":"suman-15-los-muertos-en-intercambios-de-disparos-en-lo-que-va-de-ano","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/suman-15-los-muertos-en-intercambios-de-disparos-en-lo-que-va-de-ano\/","title":{"rendered":"Suman 15 los muertos en \u201cintercambios de disparos\u201d en lo que va de a\u00f1o"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/policia-60f3939c-focus-0-0-895-573.jpg\" alt=\"\" class=\"wp-image-87974\" width=\"234\" height=\"132\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/policia-60f3939c-focus-0-0-895-573.jpg 608w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/policia-60f3939c-focus-0-0-895-573-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/policia-60f3939c-focus-0-0-895-573-600x338.jpg 600w\" sizes=\"auto, (max-width: 234px) 100vw, 234px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En un mes y siete d\u00edas, Rep\u00fablica Dominicana registra al menos&nbsp;<strong>15 muertes a mano de agentes de la Polic\u00eda Nacional<\/strong>&nbsp;en los llamados \u00ab<strong>intercambios de disparos<\/strong>\u00ab, seg\u00fan los registros publicados por la propia instituci\u00f3n del orden en su p\u00e1gina oficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lo que va del mes de febrero, (ocho d\u00edas) han ca\u00eddo abatidos unos cinco presuntos delincuentes, quienes, seg\u00fan la instituci\u00f3n del orden, ten\u00edan prontuarios por distintos hechos delictivos en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Iniciada la semana, dos j\u00f3venes, ambos de 18 a\u00f1os, resultaron muertos a mano de la&nbsp;<strong>Polic\u00eda Nacional<\/strong>&nbsp;en el sector&nbsp;<strong>Cach\u00f3n de la Rubia<\/strong>, Santo Domingo Este, tras supuestamente enfrentar a los oficiales del orden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los individuos fueron identificados como&nbsp;<strong>Anderson Amparo Zapata<\/strong>, alias Cach\u00f3n, y&nbsp;<strong>Londry Amparo de la Cruz<\/strong>, mejor conocido como \u00abPopol\u00f3n\u00bb. Los familiares de estos j\u00f3venes reconocieron que se dedicaban a delinquir, sin embargo, condenaron la acci\u00f3n tomada por los oficiales tras manifestar que los fallecidos merec\u00edan una oportunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La madre de Londry Amparo estaba consciente de que su hijo atracaba en algunos sectores del pa\u00eds y defini\u00f3 las acciones del joven como \u201calgo de muchachos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasadso s\u00e1bado, un supuesto enfrentamiento con agentes de la uniformada, dos presuntos delincuentes murieron tras ser perseguidos por oficiales de la&nbsp;<strong>Direcci\u00f3n Central de Investigaci\u00f3n (Dicrim)<\/strong>&nbsp;por \u00abasaltar\u00bb a una joyer\u00eda en el sector Invivienda, Santo Domingo Este. Uno de los delincuentes supuestamente se quit\u00f3 la vida al verse acorralado, seg\u00fan un informe de la&nbsp;<strong>Polic\u00eda Nacional<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los fallecidos fueron identificados como&nbsp;<strong>Marcos Alfredo Maldonado Lafontaine<\/strong>, alias \u00abMaikol El Wa\u00bb, de 27 a\u00f1os, y el segundo solo fue reconocido como&nbsp;<strong>\u201cEl Gordo\u201d,<\/strong>&nbsp;a quienes de les ocup\u00f3 armadas de fuego, conforme a la Polic\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el robo de la joyer\u00eda, la\u00a0<strong>Polic\u00eda Nacional<\/strong>\u00a0apres\u00f3 a Juan Manuel V\u00e1squez Ventura, de 24 a\u00f1os, y a Juan Alberto de Le\u00f3n Ger\u00f3nimo, de 29 a\u00f1os. La instituci\u00f3n inform\u00f3 que recuper\u00f3 todas las prendas robadas, las cuales ascend\u00edan a m\u00e1s de siete mil gramos de oro, seg\u00fan uno de los propietarios del negocio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado 03 de febrero un presunto delincuente result\u00f3 muerto y otros tres detenidos, a quienes le daban seguimiento por el asesinato del sargento de la&nbsp;<strong>Polic\u00eda Nacional<\/strong>, Yeysen Gustavo Montero Florentino en la comunidad Maim\u00f3n, provincia Monse\u00f1or Nouel. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de<strong>&nbsp;Cristian Espinosa, alias \u201cChocolate Macron\u201d<\/strong>, quien se enfrent\u00f3, seg\u00fan la Polic\u00eda, a los agentes del orden tras negarse a ser apresado. Adem\u00e1s de la muerte del sargento, se le vincula con el deceso de un oficial de la Armada, R\u00f3mulo de los Santos Vargas Guti\u00e9rrez, el 12 de septiembre del a\u00f1o pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n es vinculado al doble homicidio de Efren Osiris Manzueta Romero y Jefrey Encarnaci\u00f3n Mer\u00e1n, hecho ocurrido el pasado 26 de diciembre del 2022.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>En enero cayeron 10<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el mes de enero al menos 10 personas resultaron muertas en medio de supuestos&nbsp;<strong>intercambios de disparos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mi\u00e9rcoles 11 de enero tres j\u00f3venes resultaron muertos tras supuestamente enfrentarse a los agentes policiales mientras se negaban a ser apresados en momentos en que transitaban por la calle Jos\u00e9 Dolores Cer\u00f3n esquina 17, ensanche Luper\u00f3n, Distrito Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de&nbsp;<strong>Adri\u00e1n Jos\u00e9 Mercedes Dur\u00e1n<\/strong>, alias \u00abel Mello\u00bb, de 21 a\u00f1os;&nbsp;<strong>Brailyn Mart\u00ednez (Brayan)<\/strong>, de 25, y&nbsp;<strong>un tercero no identificado<\/strong>, quienes supuestamente emprendieron a tiros contra los agentes que le daban seguimiento por distintos hechos delictivos en Santo Domingo y en el Distrito Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En igual circunstancia cay\u00f3 abatido el 10 de enero&nbsp;<strong>Wilfri Alexander Rosario Bonilla<\/strong>, alias \u00abBubuta\u00bb, quien \u00abera activamente buscado\u00bb por la entidad mediante \u00f3rdenes judiciales, por supuestamente herir de bala a un agente y haber cometido dos homicidios y otros il\u00edcitos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el informe policial, \u00abBubuta\u00bb cometi\u00f3 estos hechos junto a los nombrados \u00ab\u00d1ify y Sesenta\u00bb\u00a0(pr\u00f3fugos) en la provincia Santiago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agentes de la uniformada tambi\u00e9n ultimaron a un hombre en el sector Los Ginebra, provincia Puerto Plata, quien supuestamente habr\u00eda enfrentado a tiros a oficiales de la&nbsp;<strong>Polic\u00eda Nacional<\/strong>&nbsp;desde el interior de una casa, donde estaba atrincherado para evitar ser arrestado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hombre\u00a0solo fue identificado como \u00ab<strong>Anderson\u00bb<\/strong>, buscado por las autoridades de la provincia Santiago por varios cr\u00edmenes y atracos cometidos a mano armada, seg\u00fan el reporte de la entidad. El hecho ocurri\u00f3 el 5 de enero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mismo d\u00eda los oficiales tambi\u00e9n ultimaron al presunto delincuente&nbsp;<strong>Wilmer Hern\u00e1ndez<\/strong>, alias \u00abCalvito\u00bb, en la calle Los Humildes del sector Los Guaricanos, Santo Domingo Norte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCalvito\u00bb, de 28 a\u00f1os, estaba siendo se\u00f1alado por la Polic\u00eda como pr\u00f3fugo por haber cometido hechos delictivos y de criminalidad, entre ellos homicidios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Otros dos muertos&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al&nbsp;d\u00eda siguiente la instituci\u00f3n del orden ultim\u00f3 durante un \u201cintercambio de disparos\u201d a dos&nbsp;presuntos delincuentes&nbsp;en el sector El Capacito, del municipio San Francisco de Macor\u00eds, provincia Duarte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de&nbsp;<strong>Wilman Gonz\u00e1lez Paulino (a) \u00abW\u00bb<\/strong>, de 42 a\u00f1os, y&nbsp;<strong>Jos\u00e9 Antonio Vargas Marte (a) \u00abel Maco\u00bb<\/strong>, de 38, quienes fueron se\u00f1alados como \u201cpeligrosos&nbsp;delincuentes\u201d que se dedicaban al sicariato, extorsi\u00f3n, distribuci\u00f3n y venta de drogas, entre otros il\u00edcitos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo, cay\u00f3 abatido por agentes de la Polic\u00eda&nbsp;<strong>Anderson Ramos Canela<\/strong>, alias \u00abCoca\u00bb, quien supuestamente era activamente buscado por ultimar a un cabo policial, adscrito a la&nbsp;Direcci\u00f3n General de Seguridad de Tr\u00e1nsito y Transporte Terrestre (Digesett).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCoca\u00bb supuestamente se enfrent\u00f3 a los policiales mientras intentaban apresarlo en el barrio Los Coquitos, en el sector Las Caobas, Santo Domingo Oeste, el 4 de enero. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que el 1 de enero, polic\u00edas ultimaron al joven&nbsp;<strong>Wander Medina P\u00e9rez<\/strong>, alias \u00abel Menor\u00bb, en medio de un alegado intercambio de disparos en el sector Balaguer del distrito municipal Villa Central, provincia Barahona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El informe policial indica que Medina P\u00e9rez era buscado por la comisi\u00f3n de varios hechos delictivos y al verse acorralado por los agentes, enfrent\u00f3 a tiros a la patrulla de investigaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un mes y siete d\u00edas, Rep\u00fablica Dominicana registra al menos&nbsp;15 muertes a mano de agentes de la Polic\u00eda Nacional&nbsp;en los llamados \u00abintercambios de disparos\u00ab, seg\u00fan los registros publicados por la propia instituci\u00f3n del orden en su p\u00e1gina oficial. En lo que va del mes de febrero, (ocho d\u00edas) han ca\u00eddo abatidos unos cinco presuntos delincuentes, quienes, seg\u00fan la instituci\u00f3n del orden, ten\u00edan prontuarios por distintos hechos delictivos en el pa\u00eds. Iniciada la semana, dos j\u00f3venes, ambos de 18 a\u00f1os, resultaron muertos a mano de la&nbsp;Polic\u00eda Nacional&nbsp;en el sector&nbsp;Cach\u00f3n de la Rubia, Santo Domingo Este, tras supuestamente enfrentar a los oficiales del orden. Los individuos fueron identificados como&nbsp;Anderson Amparo Zapata, alias Cach\u00f3n, y&nbsp;Londry Amparo de la Cruz, mejor conocido como \u00abPopol\u00f3n\u00bb. Los familiares de estos j\u00f3venes reconocieron que se dedicaban a delinquir, sin embargo, condenaron la acci\u00f3n tomada por los oficiales tras manifestar que los fallecidos merec\u00edan una oportunidad. La madre de Londry Amparo estaba consciente de que su hijo atracaba en algunos sectores del pa\u00eds y defini\u00f3 las acciones del joven como \u201calgo de muchachos\u201d. El pasadso s\u00e1bado, un supuesto enfrentamiento con agentes de la uniformada, dos presuntos delincuentes murieron tras ser perseguidos por oficiales de la&nbsp;Direcci\u00f3n Central de Investigaci\u00f3n (Dicrim)&nbsp;por \u00abasaltar\u00bb a una joyer\u00eda en el sector Invivienda, Santo Domingo Este. Uno de los delincuentes supuestamente se quit\u00f3 la vida al verse acorralado, seg\u00fan un informe de la&nbsp;Polic\u00eda Nacional. Los fallecidos fueron identificados como&nbsp;Marcos Alfredo Maldonado Lafontaine, alias \u00abMaikol El Wa\u00bb, de 27 a\u00f1os, y el segundo solo fue reconocido como&nbsp;\u201cEl Gordo\u201d,&nbsp;a quienes de les ocup\u00f3 armadas de fuego, conforme a la Polic\u00eda. Por el robo de la joyer\u00eda, la\u00a0Polic\u00eda Nacional\u00a0apres\u00f3 a Juan Manuel V\u00e1squez Ventura, de 24 a\u00f1os, y a Juan Alberto de Le\u00f3n Ger\u00f3nimo, de 29 a\u00f1os. La instituci\u00f3n inform\u00f3 que recuper\u00f3 todas las prendas robadas, las cuales ascend\u00edan a m\u00e1s de siete mil gramos de oro, seg\u00fan uno de los propietarios del negocio. El pasado 03 de febrero un presunto delincuente result\u00f3 muerto y otros tres detenidos, a quienes le daban seguimiento por el asesinato del sargento de la&nbsp;Polic\u00eda Nacional, Yeysen Gustavo Montero Florentino en la comunidad Maim\u00f3n, provincia Monse\u00f1or Nouel. &nbsp; Se trata de&nbsp;Cristian Espinosa, alias \u201cChocolate Macron\u201d, quien se enfrent\u00f3, seg\u00fan la Polic\u00eda, a los agentes del orden tras negarse a ser apresado. Adem\u00e1s de la muerte del sargento, se le vincula con el deceso de un oficial de la Armada, R\u00f3mulo de los Santos Vargas Guti\u00e9rrez, el 12 de septiembre del a\u00f1o pasado. Tambi\u00e9n es vinculado al doble homicidio de Efren Osiris Manzueta Romero y Jefrey Encarnaci\u00f3n Mer\u00e1n, hecho ocurrido el pasado 26 de diciembre del 2022. En enero cayeron 10 En el mes de enero al menos 10 personas resultaron muertas en medio de supuestos&nbsp;intercambios de disparos. El mi\u00e9rcoles 11 de enero tres j\u00f3venes resultaron muertos tras supuestamente enfrentarse a los agentes policiales mientras se negaban a ser apresados en momentos en que transitaban por la calle Jos\u00e9 Dolores Cer\u00f3n esquina 17, ensanche Luper\u00f3n, Distrito Nacional. Se trata de&nbsp;Adri\u00e1n Jos\u00e9 Mercedes Dur\u00e1n, alias \u00abel Mello\u00bb, de 21 a\u00f1os;&nbsp;Brailyn Mart\u00ednez (Brayan), de 25, y&nbsp;un tercero no identificado, quienes supuestamente emprendieron a tiros contra los agentes que le daban seguimiento por distintos hechos delictivos en Santo Domingo y en el Distrito Nacional. En igual circunstancia cay\u00f3 abatido el 10 de enero&nbsp;Wilfri Alexander Rosario Bonilla, alias \u00abBubuta\u00bb, quien \u00abera activamente buscado\u00bb por la entidad mediante \u00f3rdenes judiciales, por supuestamente herir de bala a un agente y haber cometido dos homicidios y otros il\u00edcitos. Seg\u00fan el informe policial, \u00abBubuta\u00bb cometi\u00f3 estos hechos junto a los nombrados \u00ab\u00d1ify y Sesenta\u00bb\u00a0(pr\u00f3fugos) en la provincia Santiago. Agentes de la uniformada tambi\u00e9n ultimaron a un hombre en el sector Los Ginebra, provincia Puerto Plata, quien supuestamente habr\u00eda enfrentado a tiros a oficiales de la&nbsp;Polic\u00eda Nacional&nbsp;desde el interior de una casa, donde estaba atrincherado para evitar ser arrestado. El hombre\u00a0solo fue identificado como \u00abAnderson\u00bb, buscado por las autoridades de la provincia Santiago por varios cr\u00edmenes y atracos cometidos a mano armada, seg\u00fan el reporte de la entidad. El hecho ocurri\u00f3 el 5 de enero. El mismo d\u00eda los oficiales tambi\u00e9n ultimaron al presunto delincuente&nbsp;Wilmer Hern\u00e1ndez, alias \u00abCalvito\u00bb, en la calle Los Humildes del sector Los Guaricanos, Santo Domingo Norte. \u00abCalvito\u00bb, de 28 a\u00f1os, estaba siendo se\u00f1alado por la Polic\u00eda como pr\u00f3fugo por haber cometido hechos delictivos y de criminalidad, entre ellos homicidios. Otros dos muertos&nbsp; Al&nbsp;d\u00eda siguiente la instituci\u00f3n del orden ultim\u00f3 durante un \u201cintercambio de disparos\u201d a dos&nbsp;presuntos delincuentes&nbsp;en el sector El Capacito, del municipio San Francisco de Macor\u00eds, provincia Duarte. Se trata de&nbsp;Wilman Gonz\u00e1lez Paulino (a) \u00abW\u00bb, de 42 a\u00f1os, y&nbsp;Jos\u00e9 Antonio Vargas Marte (a) \u00abel Maco\u00bb, de 38, quienes fueron se\u00f1alados como \u201cpeligrosos&nbsp;delincuentes\u201d que se dedicaban al sicariato, extorsi\u00f3n, distribuci\u00f3n y venta de drogas, entre otros il\u00edcitos. As\u00ed mismo, cay\u00f3 abatido por agentes de la Polic\u00eda&nbsp;Anderson Ramos Canela, alias \u00abCoca\u00bb, quien supuestamente era activamente buscado por ultimar a un cabo policial, adscrito a la&nbsp;Direcci\u00f3n General de Seguridad de Tr\u00e1nsito y Transporte Terrestre (Digesett). \u00abCoca\u00bb supuestamente se enfrent\u00f3 a los policiales mientras intentaban apresarlo en el barrio Los Coquitos, en el sector Las Caobas, Santo Domingo Oeste, el 4 de enero. &nbsp; Mientras que el 1 de enero, polic\u00edas ultimaron al joven&nbsp;Wander Medina P\u00e9rez, alias \u00abel Menor\u00bb, en medio de un alegado intercambio de disparos en el sector Balaguer del distrito municipal Villa Central, provincia Barahona. El informe policial indica que Medina P\u00e9rez era buscado por la comisi\u00f3n de varios hechos delictivos y al verse acorralado por los agentes, enfrent\u00f3 a tiros a la patrulla de investigaciones.<\/p>\n","protected":false},"author":9,"featured_media":87974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-87973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=87973"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87973\/revisions"}],"predecessor-version":[{"id":87975,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/87973\/revisions\/87975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/87974"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=87973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=87973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=87973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}