{"id":88056,"date":"2023-02-14T08:40:32","date_gmt":"2023-02-14T12:40:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=88056"},"modified":"2023-02-14T08:40:33","modified_gmt":"2023-02-14T12:40:33","slug":"aguilas-adquieren-a-gilberto-celestino-desde-los-toros-por-victor-robles","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aguilas-adquieren-a-gilberto-celestino-desde-los-toros-por-victor-robles\/","title":{"rendered":"\u00c1guilas adquieren a Gilberto Celestino desde los Toros por V\u00edctor Robles"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/dep-4.jpg\" alt=\"\" class=\"wp-image-88057\" width=\"254\" height=\"158\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/dep-4.jpg 409w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/dep-4-300x186.jpg 300w\" sizes=\"auto, (max-width: 254px) 100vw, 254px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Las \u00c1guilas Cibae\u00f1as adquirieron al jardinero central de grandes ligas Gilberto Celestino en cambio con los Toros del Este, que recibieron al tambi\u00e9n centrocampista de las mayores V\u00edctor Robles, anunci\u00f3 aqu\u00ed \u00c1ngel Ovalles, gerente de Operaciones de los aguiluchos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Celestino, quien milita en Grandes Ligas con los Mellizos de Minnesota, fue definido por Ovalles como un jardinero central defensivamente s\u00f3lido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAdem\u00e1s puede generar ofensiva del lado derecho del plato, hace contacto, se embasa y es un jugador consistente que debe ser s\u00f3lido en esta liga\u201d, asegur\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gerente aguilucho dio la bienvenida al nuevo jugador del equipo, al tiempo de agradecer a V\u00edctor su entrega a la causa aguilucha y dese\u00f3 suerte en su carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gilberto Celestino viene de jugar 122 partidos en Grandes Ligas con los Mellizos en 2022, donde bate\u00f3 .238, impuls\u00f3 25. Recibi\u00f3 32 transferencias y 77 ponches. Las estad\u00edsticas de barra cerraron en .313 \/.302 \/.613<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Celestino es nativo de Santo Domingo, tiene 24 a\u00f1os, mide 6\u00b4-0\u201d, su equipo original en la Liga Dominicana son los Gigantes del Cibao, con quienes jug\u00f3 s\u00f3lo 4 partidos, pegando un hit en siete turnos. En la temporada 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue enviado a los Toros del Este para la temporada 2021-2022 en el cambio que involucr\u00f3 adem\u00e1s al torpedero Oneil Cruz y el lanzador Adonis Rosa por el patrullero Jordany Valdesp\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con los Toros Gilberto Celestino jug\u00f3 11 juegos. Seis en la campa\u00f1a 2021-2022 y cinco el a\u00f1o pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su actuaci\u00f3n en LIDOM se resume en 15 juegos, 41 turnos, 8 hits, promedio de bateo de .195, dos dobles, 3 carreras impulsadas, 4 anotadas, 14 boletos y 8 ponches. Su OBP es de .389, SLG .244, OPS. 633.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las \u00c1guilas Cibae\u00f1as adquirieron al jardinero central de grandes ligas Gilberto Celestino en cambio con los Toros del Este, que recibieron al tambi\u00e9n centrocampista de las mayores V\u00edctor Robles, anunci\u00f3 aqu\u00ed \u00c1ngel Ovalles, gerente de Operaciones de los aguiluchos. Celestino, quien milita en Grandes Ligas con los Mellizos de Minnesota, fue definido por Ovalles como un jardinero central defensivamente s\u00f3lido. \u201cAdem\u00e1s puede generar ofensiva del lado derecho del plato, hace contacto, se embasa y es un jugador consistente que debe ser s\u00f3lido en esta liga\u201d, asegur\u00f3. El gerente aguilucho dio la bienvenida al nuevo jugador del equipo, al tiempo de agradecer a V\u00edctor su entrega a la causa aguilucha y dese\u00f3 suerte en su carrera. Gilberto Celestino viene de jugar 122 partidos en Grandes Ligas con los Mellizos en 2022, donde bate\u00f3 .238, impuls\u00f3 25. Recibi\u00f3 32 transferencias y 77 ponches. Las estad\u00edsticas de barra cerraron en .313 \/.302 \/.613 Celestino es nativo de Santo Domingo, tiene 24 a\u00f1os, mide 6\u00b4-0\u201d, su equipo original en la Liga Dominicana son los Gigantes del Cibao, con quienes jug\u00f3 s\u00f3lo 4 partidos, pegando un hit en siete turnos. En la temporada 2021. Fue enviado a los Toros del Este para la temporada 2021-2022 en el cambio que involucr\u00f3 adem\u00e1s al torpedero Oneil Cruz y el lanzador Adonis Rosa por el patrullero Jordany Valdesp\u00edn. Con los Toros Gilberto Celestino jug\u00f3 11 juegos. Seis en la campa\u00f1a 2021-2022 y cinco el a\u00f1o pasado. Su actuaci\u00f3n en LIDOM se resume en 15 juegos, 41 turnos, 8 hits, promedio de bateo de .195, dos dobles, 3 carreras impulsadas, 4 anotadas, 14 boletos y 8 ponches. Su OBP es de .389, SLG .244, OPS. 633.<\/p>\n","protected":false},"author":9,"featured_media":88057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-88056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/88056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=88056"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/88056\/revisions"}],"predecessor-version":[{"id":88058,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/88056\/revisions\/88058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/88057"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=88056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=88056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=88056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}