{"id":88116,"date":"2023-02-20T13:00:19","date_gmt":"2023-02-20T17:00:19","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=88116"},"modified":"2023-02-20T13:00:20","modified_gmt":"2023-02-20T17:00:20","slug":"militares-en-red-de-trafico-haitianos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/militares-en-red-de-trafico-haitianos\/","title":{"rendered":"Militares en red de tr\u00e1fico haitianos"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/militares-en-red-de-trafico-haitianos.jpeg\" alt=\"\" class=\"wp-image-88117\" width=\"243\" height=\"126\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/militares-en-red-de-trafico-haitianos.jpeg 329w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/militares-en-red-de-trafico-haitianos-300x155.jpeg 300w\" sizes=\"auto, (max-width: 243px) 100vw, 243px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La Procuradur\u00eda Especializada Contra el Tr\u00e1fico Il\u00edcito de Migran\u00adtes y Trata de Personas (PETT), conjuntamente con la Fiscal\u00eda de Monte Cristi, inform\u00f3 que en la madrugada de ayer lanz\u00f3 la Operaci\u00f3n Frontera, con la que desarticul\u00f3 una\u00a0<strong>red de criminalidad organizada dedicada al tr\u00e1fico de inmigrantes haitianos en la que participaban militares y civiles.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la operaci\u00f3n fueron arrestados<strong>&nbsp;Eddy Rafael Cordero Villanueva y Osiris Rafael Est\u00e9vez Fortuna<\/strong>, quienes han sido identificados como cabecillas de esta red.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros arrestados son&nbsp;<strong>Elbio Jos\u00e9 Castillo Mart\u00ednez, Hilario Antonio G\u00f3mez Paul, Santo Valerio Contreras, Anelby Susa\u00f1a Guzm\u00e1n, Jes\u00fas Mar\u00eda Cerda Acosta, Anelsy Escarlex Cordero N\u00fa\u00f1ez y Mar\u00eda Rafaela Batista de Cordero.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la operaci\u00f3n tambi\u00e9n fueron detenidos los miembros el segundo teniente&nbsp;<strong>Jos\u00e9 Dolores Hern\u00e1ndez Merejildo y Julio C\u00e9sar Pujols Montero<\/strong>; los sargentos&nbsp;<strong>Rafael Contreras y Rafael Zabala Pe\u00f1a&nbsp;<\/strong>y el cabo<strong>&nbsp;Sandro Liranzo Javier.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe pudo desmantelar esta organizaci\u00f3n criminal que operaba en la frontera norte, especialmente en la provincia de Monte Cristi, desde donde lograron trasladar a cientos de inmigrantes haitianos e introducirlos a territorio dominicano debido a que su cabecilla reside en la zona y contaba con la complicidad de los miembros arrestados del Ej\u00e9rcito que en el desempe\u00f1o de sus funciones se encontraban habilitados para resguardar y proteger la frontera de nuestro pa\u00eds,&nbsp; quienes permitieron&nbsp; el tr\u00e1fico il\u00edcito de cientos de nacionales haitianos hacia&nbsp; territorio de la Rep\u00fablica Dominicana\u201d, la titular PETT, Yoanna Bejar\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>APUNTES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>16 allanamientos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 16 allanamientos realizados se encontraron 24 inmigrantes entre ellos, hombres mujeres embarazadas, ni\u00f1os y adolescentes quienes permanec\u00edan en los centros de acopio clandestinos utilizados por la estructura criminal para ser trasportados por las diferentes rutas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Procuradur\u00eda Especializada Contra el Tr\u00e1fico Il\u00edcito de Migran\u00adtes y Trata de Personas (PETT), conjuntamente con la Fiscal\u00eda de Monte Cristi, inform\u00f3 que en la madrugada de ayer lanz\u00f3 la Operaci\u00f3n Frontera, con la que desarticul\u00f3 una\u00a0red de criminalidad organizada dedicada al tr\u00e1fico de inmigrantes haitianos en la que participaban militares y civiles.\u00a0 En la operaci\u00f3n fueron arrestados&nbsp;Eddy Rafael Cordero Villanueva y Osiris Rafael Est\u00e9vez Fortuna, quienes han sido identificados como cabecillas de esta red. Otros arrestados son&nbsp;Elbio Jos\u00e9 Castillo Mart\u00ednez, Hilario Antonio G\u00f3mez Paul, Santo Valerio Contreras, Anelby Susa\u00f1a Guzm\u00e1n, Jes\u00fas Mar\u00eda Cerda Acosta, Anelsy Escarlex Cordero N\u00fa\u00f1ez y Mar\u00eda Rafaela Batista de Cordero. En la operaci\u00f3n tambi\u00e9n fueron detenidos los miembros el segundo teniente&nbsp;Jos\u00e9 Dolores Hern\u00e1ndez Merejildo y Julio C\u00e9sar Pujols Montero; los sargentos&nbsp;Rafael Contreras y Rafael Zabala Pe\u00f1a&nbsp;y el cabo&nbsp;Sandro Liranzo Javier. \u201cSe pudo desmantelar esta organizaci\u00f3n criminal que operaba en la frontera norte, especialmente en la provincia de Monte Cristi, desde donde lograron trasladar a cientos de inmigrantes haitianos e introducirlos a territorio dominicano debido a que su cabecilla reside en la zona y contaba con la complicidad de los miembros arrestados del Ej\u00e9rcito que en el desempe\u00f1o de sus funciones se encontraban habilitados para resguardar y proteger la frontera de nuestro pa\u00eds,&nbsp; quienes permitieron&nbsp; el tr\u00e1fico il\u00edcito de cientos de nacionales haitianos hacia&nbsp; territorio de la Rep\u00fablica Dominicana\u201d, la titular PETT, Yoanna Bejar\u00e1n. APUNTES 16 allanamientos En 16 allanamientos realizados se encontraron 24 inmigrantes entre ellos, hombres mujeres embarazadas, ni\u00f1os y adolescentes quienes permanec\u00edan en los centros de acopio clandestinos utilizados por la estructura criminal para ser trasportados por las diferentes rutas.<\/p>\n","protected":false},"author":9,"featured_media":88117,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-88116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/88116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=88116"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/88116\/revisions"}],"predecessor-version":[{"id":88118,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/88116\/revisions\/88118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/88117"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=88116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=88116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=88116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}