{"id":88425,"date":"2023-02-28T15:30:20","date_gmt":"2023-02-28T19:30:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=88425"},"modified":"2023-02-28T15:31:28","modified_gmt":"2023-02-28T19:31:28","slug":"la-autopsia-de-esmeralda-no-fue-hecha-por-el-inacif","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-autopsia-de-esmeralda-no-fue-hecha-por-el-inacif\/","title":{"rendered":"La autopsia de Esmeralda no fue hecha por el Inacif"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/inac.jpg\" alt=\"\" class=\"wp-image-88426\" width=\"261\" height=\"134\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/inac.jpg 331w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/02\/inac-300x154.jpg 300w\" sizes=\"auto, (max-width: 261px) 100vw, 261px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio de autopsia de la joven\u00a0<strong>Esmeralda Richiez<\/strong>, de 16 a\u00f1os, oriunda de Hig\u00fcey y que ha captado la atenci\u00f3n del pa\u00eds, no fue realizada en el Instituto Nacional de Ciencias Forenses (Inacif), sino en\u00a0<strong>el Instituto Nacional de Patolog\u00eda Forense Doctor Sergio Sarita Valdez<\/strong>, ya que no se report\u00f3 como muerte violenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo explicaron los doctores C\u00e1ndido Jim\u00e9nez y Jairo Medrano, presidente y asesor legal de la Sociedad Dominicana de Medicina Forense, quienes se\u00f1alaron, adem\u00e1s, que en un informe preliminar,\u00a0<strong>como el que se dio a conocer inicialmente en torno a ese caso<\/strong>, pueden cometerse errores, ya que el m\u00e9dico solo va describiendo lo que va encontrando en el cad\u00e1ver, por lo que siempre hay que esperar el informe definitivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Recuerdan que las muertes violenta<\/strong><a rel=\"noreferrer noopener\" href=\"https:\/\/listindiario.com\/la-republica\/2023\/02\/16\/763157\/esmeralda-richiez-sufrio-un-shock-hipovolemico-segun-analisis-del-inacif-publicado-por-pgr\" target=\"_blank\"><strong>s<\/strong><\/a>\u00a0o m\u00e9dico- legal son las que les corresponden al Inacif, como es el caso de accidentes de tr\u00e1nsito, armas blancas, envenenamientos, intoxicaciones, suicidio, entre otros, y que las dem\u00e1s muertes, corresponden al Instituto Nacional de Patolog\u00eda Forense Doctor Sergio Sarita Valdez, entre ellas, las maternas, las de vigilancia epidemiol\u00f3gica, cuando ocurren en privados de libertad, las neonatales e infantiles y las s\u00fabitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cEsta autopsia no la hizo el Inacif,\u00a0<\/strong>que solo procedi\u00f3 a hacer el levantamiento del cuerpo y la evaluaci\u00f3n personal del imputado,<a rel=\"noreferrer noopener\" href=\"https:\/\/listindiario.com\/la-republica\/2023\/02\/18\/763347\/muerte-de-esmeralda-contada-paso-a-paso\" target=\"_blank\"><strong>\u00a0<\/strong><\/a><strong>pero la necropsia la hizo el Instituto de Patolog\u00eda<\/strong>, porque no calificaba como muerte violenta, ya que inicialmente no se involucr\u00f3 arma de fuego o blanca, ahorcadura, sino que seg\u00fan versiones, se presum\u00eda aborto y eso corresponde al Instituto de Patolog\u00eda Forense\u201d, explic\u00f3 Medrano.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Preliminares<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los especialistas recordaron que en todo procedimiento de necropsia existe el resultado preliminar y el informe definitivo, donde pueden surgir nuevas evidencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explicaron que existen los resultados preliminares, porque el forense va escribiendo de acuerdo a lo que va encontrando en el cad\u00e1ver, pero que en los resultados definitivos pueden surgir otros datos.&nbsp;<strong>\u201cEn el caso de la jovencita Esmeralda, la poblaci\u00f3n debe entender que los primeros datos que surgieron fueron fruto de un informe preliminar, no final\u201d<\/strong>, dijo Medrano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que en un preliminar se pueden cometer ciertos errores, por lo que la poblaci\u00f3n no entiende y empieza a sacar conclusiones de que hay alteraciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dirigente de la Sociedad Dominicana de Medicina Forense dijo que todos los forenses del pa\u00eds son egresados de la misma escuela y tienen la misma calidad de formaci\u00f3n, as\u00ed que no se puede descalificar los informes emitidos por sus compa\u00f1eros, \u201cporque sabemos de la calidad y la rigurosidad en su ejercicio\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El estudio de autopsia de la joven\u00a0Esmeralda Richiez, de 16 a\u00f1os, oriunda de Hig\u00fcey y que ha captado la atenci\u00f3n del pa\u00eds, no fue realizada en el Instituto Nacional de Ciencias Forenses (Inacif), sino en\u00a0el Instituto Nacional de Patolog\u00eda Forense Doctor Sergio Sarita Valdez, ya que no se report\u00f3 como muerte violenta. As\u00ed lo explicaron los doctores C\u00e1ndido Jim\u00e9nez y Jairo Medrano, presidente y asesor legal de la Sociedad Dominicana de Medicina Forense, quienes se\u00f1alaron, adem\u00e1s, que en un informe preliminar,\u00a0como el que se dio a conocer inicialmente en torno a ese caso, pueden cometerse errores, ya que el m\u00e9dico solo va describiendo lo que va encontrando en el cad\u00e1ver, por lo que siempre hay que esperar el informe definitivo. Recuerdan que las muertes violentas\u00a0o m\u00e9dico- legal son las que les corresponden al Inacif, como es el caso de accidentes de tr\u00e1nsito, armas blancas, envenenamientos, intoxicaciones, suicidio, entre otros, y que las dem\u00e1s muertes, corresponden al Instituto Nacional de Patolog\u00eda Forense Doctor Sergio Sarita Valdez, entre ellas, las maternas, las de vigilancia epidemiol\u00f3gica, cuando ocurren en privados de libertad, las neonatales e infantiles y las s\u00fabitas. \u201cEsta autopsia no la hizo el Inacif,\u00a0que solo procedi\u00f3 a hacer el levantamiento del cuerpo y la evaluaci\u00f3n personal del imputado,\u00a0pero la necropsia la hizo el Instituto de Patolog\u00eda, porque no calificaba como muerte violenta, ya que inicialmente no se involucr\u00f3 arma de fuego o blanca, ahorcadura, sino que seg\u00fan versiones, se presum\u00eda aborto y eso corresponde al Instituto de Patolog\u00eda Forense\u201d, explic\u00f3 Medrano. Preliminares Los especialistas recordaron que en todo procedimiento de necropsia existe el resultado preliminar y el informe definitivo, donde pueden surgir nuevas evidencias. Explicaron que existen los resultados preliminares, porque el forense va escribiendo de acuerdo a lo que va encontrando en el cad\u00e1ver, pero que en los resultados definitivos pueden surgir otros datos.&nbsp;\u201cEn el caso de la jovencita Esmeralda, la poblaci\u00f3n debe entender que los primeros datos que surgieron fueron fruto de un informe preliminar, no final\u201d, dijo Medrano. Indic\u00f3 que en un preliminar se pueden cometer ciertos errores, por lo que la poblaci\u00f3n no entiende y empieza a sacar conclusiones de que hay alteraciones. El dirigente de la Sociedad Dominicana de Medicina Forense dijo que todos los forenses del pa\u00eds son egresados de la misma escuela y tienen la misma calidad de formaci\u00f3n, as\u00ed que no se puede descalificar los informes emitidos por sus compa\u00f1eros, \u201cporque sabemos de la calidad y la rigurosidad en su ejercicio\u201d.<\/p>\n","protected":false},"author":9,"featured_media":88426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-88425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/88425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=88425"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/88425\/revisions"}],"predecessor-version":[{"id":88427,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/88425\/revisions\/88427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/88426"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=88425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=88425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=88425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}