{"id":89364,"date":"2023-03-13T19:43:33","date_gmt":"2023-03-13T23:43:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=89364"},"modified":"2023-03-13T19:47:21","modified_gmt":"2023-03-13T23:47:21","slug":"comunidades-en-santiago-se-movilizan-para-protestar-por-falta-de-agua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/comunidades-en-santiago-se-movilizan-para-protestar-por-falta-de-agua\/","title":{"rendered":"Comunidades en Santiago se movilizan para protestar por falta de agua"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"170\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/03\/comunidades-en-santiago-se-movilizan-para-protestar-por-falta-de-agua-potable.jpeg\" alt=\"\" class=\"wp-image-89365\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/03\/comunidades-en-santiago-se-movilizan-para-protestar-por-falta-de-agua-potable.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/03\/comunidades-en-santiago-se-movilizan-para-protestar-por-falta-de-agua-potable-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de la prolongada sequ\u00eda que azota a Santiago y otros puntos del pa\u00eds, este lunes varias comunidades de las provincias de La Vega, Espaillat y Santiago, se concentraron frente a la oficina principal de la Corporaci\u00f3n de Acueducto y Alcantarillado de Santiago (Coraasan), para exigir la conexi\u00f3n a la tuber\u00eda central y poder recibir el preciado l\u00edquido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comunitarios de los sectores La Torre, El Caimito, Manga Larga, La Vereda, Rancho Viejo y La Penda, tras m\u00e1s de siete a\u00f1os que no reciben agua, se apostaron frente a Coraasan de Santiago para pedir el inicio de los trabajos de construcci\u00f3n de un tanque de almacenamiento de agua y la conectividad de la tuber\u00eda para poder recibir el l\u00edquido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Franklin Grull\u00f3n, secretario de proyecto de la Asociaci\u00f3n de Juntas de vecinos, indic\u00f3 de que los comunitarios tienen los terrenos donde se pretende construir el tanque, por lo que esperan que las autoridades inicien con la obra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que tienen que pagar por encima de los 2,000 pesos, para poder comprar un cami\u00f3n agua por lo que no est\u00e1n en la construcci\u00f3n de seguir pagando para llenar sus cisternas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Coraasan<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que el director de Coraasan, Andr\u00e9s Burgos, dijo que ya los trabajos de instalaci\u00f3n de una nueva l\u00ednea de tuber\u00eda que conecta la red de distribuci\u00f3n al sistema principal, fueron iniciados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Burgos, dijo que el presidente Luis Abinader, dispuso el inicio de los trabajos que hab\u00edan sido demandados a trav\u00e9s del Comit\u00e9 Pro-Agua a pasadas autoridades, sin obtener ninguna respuesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEsta localidad est\u00e1 en el centro de 23 comunidades y era la \u00fanica a la que no le llegaba el agua, pero gracias a Dios y a Coraasan ya tenemos\u00bb, sostuvo Euclides Rosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director de la entidad dijo que Coraasan, puso en marcha un conjunto de medidas para mitigar el impacto de la sequ\u00eda en la poblaci\u00f3n: aumento de la flotilla de camiones cisterna para ampliar las zonas de distribuci\u00f3n de agua potable y la intensificaci\u00f3n de los trabajos de correcci\u00f3n de aver\u00edas para minimizar las p\u00e9rdidas de agua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio de la prolongada sequ\u00eda que azota a Santiago y otros puntos del pa\u00eds, este lunes varias comunidades de las provincias de La Vega, Espaillat y Santiago, se concentraron frente a la oficina principal de la Corporaci\u00f3n de Acueducto y Alcantarillado de Santiago (Coraasan), para exigir la conexi\u00f3n a la tuber\u00eda central y poder recibir el preciado l\u00edquido. Comunitarios de los sectores La Torre, El Caimito, Manga Larga, La Vereda, Rancho Viejo y La Penda, tras m\u00e1s de siete a\u00f1os que no reciben agua, se apostaron frente a Coraasan de Santiago para pedir el inicio de los trabajos de construcci\u00f3n de un tanque de almacenamiento de agua y la conectividad de la tuber\u00eda para poder recibir el l\u00edquido. Franklin Grull\u00f3n, secretario de proyecto de la Asociaci\u00f3n de Juntas de vecinos, indic\u00f3 de que los comunitarios tienen los terrenos donde se pretende construir el tanque, por lo que esperan que las autoridades inicien con la obra. Dijo que tienen que pagar por encima de los 2,000 pesos, para poder comprar un cami\u00f3n agua por lo que no est\u00e1n en la construcci\u00f3n de seguir pagando para llenar sus cisternas. Coraasan Mientras que el director de Coraasan, Andr\u00e9s Burgos, dijo que ya los trabajos de instalaci\u00f3n de una nueva l\u00ednea de tuber\u00eda que conecta la red de distribuci\u00f3n al sistema principal, fueron iniciados. Burgos, dijo que el presidente Luis Abinader, dispuso el inicio de los trabajos que hab\u00edan sido demandados a trav\u00e9s del Comit\u00e9 Pro-Agua a pasadas autoridades, sin obtener ninguna respuesta. \u00abEsta localidad est\u00e1 en el centro de 23 comunidades y era la \u00fanica a la que no le llegaba el agua, pero gracias a Dios y a Coraasan ya tenemos\u00bb, sostuvo Euclides Rosa. El director de la entidad dijo que Coraasan, puso en marcha un conjunto de medidas para mitigar el impacto de la sequ\u00eda en la poblaci\u00f3n: aumento de la flotilla de camiones cisterna para ampliar las zonas de distribuci\u00f3n de agua potable y la intensificaci\u00f3n de los trabajos de correcci\u00f3n de aver\u00edas para minimizar las p\u00e9rdidas de agua.<\/p>\n","protected":false},"author":9,"featured_media":89365,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-89364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/89364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=89364"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/89364\/revisions"}],"predecessor-version":[{"id":89366,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/89364\/revisions\/89366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/89365"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=89364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=89364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=89364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}