{"id":89890,"date":"2023-04-17T12:55:59","date_gmt":"2023-04-17T16:55:59","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=89890"},"modified":"2023-04-17T12:56:02","modified_gmt":"2023-04-17T16:56:02","slug":"solicitud-de-jean-alain-para-que-le-quiten-el-arresto-domiciliario-y-grillete-electronico-sera-conocida-el-miercoles","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/solicitud-de-jean-alain-para-que-le-quiten-el-arresto-domiciliario-y-grillete-electronico-sera-conocida-el-miercoles\/","title":{"rendered":"Solicitud de Jean Alain para que le quiten el arresto domiciliario y grillete electr\u00f3nico ser\u00e1 conocida el mi\u00e9rcoles"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"333\" height=\"171\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/04\/yanalan.jpg\" alt=\"\" class=\"wp-image-89891\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/04\/yanalan.jpg 333w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/04\/yanalan-300x154.jpg 300w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\n\nEl exprocurador general de la Rep\u00fablica, Jean Alain Rodr\u00edguez, principal implicado en el caso Medusa, acudi\u00f3 hoy ante el juez del Tercer Juzgado de la Instrucci\u00f3n del Distrito Nacional, en busca de la variaci\u00f3n del arresto domiciliario y del retiro del brazalete electr\u00f3nico.&nbsp;Sin embargo, el juez Amauris Mart\u00ednez, aplaz\u00f3 la audiencia de revisi\u00f3n de medida de coerci\u00f3n para este mi\u00e9rcoles a las 2:00 de la tarde a petici\u00f3n de Wilson Camacho, titular de la Procuradur\u00eda Especializada de Persecuci\u00f3n de la Corrupci\u00f3n Administrativa (Pepca).&nbsp;A la salida del tribunal, el doctor Carlos Balc\u00e1cer, quien forma parte del consejo de defensa del exprocurador, dijo que el tribunal tom\u00f3 la decisi\u00f3n de aplazar la audiencia acogiendo un pedimento del Ministerio P\u00fablico, quien alega que no tienen los nuevos presupuestos presentados por el imputado, con lo cual busca su variaci\u00f3n de la medida de coerci\u00f3n.&nbsp;Sostuvo que su pedimento es que le quiten el arresto domiciliario a su cliente o, por el contrario, que le retiren el grillete electr\u00f3nico, alegando que esto les ocasiona laceraciones en una de las piernas.&nbsp;Expres\u00f3 que el \u00fanico testimonio que mantiene en prisi\u00f3n con arresto domiciliario a Jean Alain domiciliario, fue las declaraciones que dio Rainiery Medina, quien fue condenada a cinco a\u00f1os de prisi\u00f3n suspendida con relaci\u00f3n a otro proceso diferente al caso Medusa.&nbsp;A la salida del tribunal, el exprocurador, fue cuestionado de que si se hab\u00eda convertido a una religi\u00f3n, respondi\u00f3 que no, que siempre ha cre\u00eddo en Dios.\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El exprocurador general de la Rep\u00fablica, Jean Alain Rodr\u00edguez, principal implicado en el caso Medusa, acudi\u00f3 hoy ante el juez del Tercer Juzgado de la Instrucci\u00f3n del Distrito Nacional, en busca de la variaci\u00f3n del arresto domiciliario y del retiro del brazalete electr\u00f3nico.&nbsp;Sin embargo, el juez Amauris Mart\u00ednez, aplaz\u00f3 la audiencia de revisi\u00f3n de medida de coerci\u00f3n para este mi\u00e9rcoles a las 2:00 de la tarde a petici\u00f3n de Wilson Camacho, titular de la Procuradur\u00eda Especializada de Persecuci\u00f3n de la Corrupci\u00f3n Administrativa (Pepca).&nbsp;A la salida del tribunal, el doctor Carlos Balc\u00e1cer, quien forma parte del consejo de defensa del exprocurador, dijo que el tribunal tom\u00f3 la decisi\u00f3n de aplazar la audiencia acogiendo un pedimento del Ministerio P\u00fablico, quien alega que no tienen los nuevos presupuestos presentados por el imputado, con lo cual busca su variaci\u00f3n de la medida de coerci\u00f3n.&nbsp;Sostuvo que su pedimento es que le quiten el arresto domiciliario a su cliente o, por el contrario, que le retiren el grillete electr\u00f3nico, alegando que esto les ocasiona laceraciones en una de las piernas.&nbsp;Expres\u00f3 que el \u00fanico testimonio que mantiene en prisi\u00f3n con arresto domiciliario a Jean Alain domiciliario, fue las declaraciones que dio Rainiery Medina, quien fue condenada a cinco a\u00f1os de prisi\u00f3n suspendida con relaci\u00f3n a otro proceso diferente al caso Medusa.&nbsp;A la salida del tribunal, el exprocurador, fue cuestionado de que si se hab\u00eda convertido a una religi\u00f3n, respondi\u00f3 que no, que siempre ha cre\u00eddo en Dios.<\/p>\n","protected":false},"author":9,"featured_media":89891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-89890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/89890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=89890"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/89890\/revisions"}],"predecessor-version":[{"id":89892,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/89890\/revisions\/89892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/89891"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=89890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=89890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=89890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}