{"id":90089,"date":"2023-04-25T14:47:37","date_gmt":"2023-04-25T18:47:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=90089"},"modified":"2023-04-25T14:47:38","modified_gmt":"2023-04-25T18:47:38","slug":"la-materialista-es-la-cuarta-finalista-de-la-casa-de-los-famosos-3","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-materialista-es-la-cuarta-finalista-de-la-casa-de-los-famosos-3\/","title":{"rendered":"La Materialista es la cuarta finalista de \u00abLa casa de los famosos 3\u00bb"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/04\/dfgtrhy.jpg\" alt=\"\" class=\"wp-image-90090\" width=\"293\" height=\"163\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/04\/dfgtrhy.jpg 445w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2023\/04\/dfgtrhy-300x167.jpg 300w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La cantante urbana&nbsp;<strong>La Materialista&nbsp;<\/strong>qued\u00f3 como cuarta finalista del&nbsp;<strong>reality show<\/strong>&nbsp;de Telemundo&nbsp;<strong>\u00abLa casa de los Famosos 3\u00bb<\/strong>, cuya gran final es este lunes 24 de abril en vivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00abEstoy feliz por el apoyo del p\u00fablico, feliz por haberme permitido estar aqu\u00ed, un logro, una meta, un sue\u00f1o hecho realidad. Gracias Materialista Family\u00bb,<\/strong>&nbsp;expres\u00f3 la int\u00e9rprete de \u00abLas chapas que vibran\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su prometido, Eury Matos, quien permaneci\u00f3 una semana en el\u00a0<strong>reality show<\/strong>, le llev\u00f3 un ramo de flores y le entreg\u00f3 la medalla de finalista. Se besaron y se abrazaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yameyry Josefina Ynfante Honoret, nombre de pila de la cantante, fue una de las favoritas. \u00abYami fuiste la m\u00e1s genuina, me encant\u00f3 tu alegr\u00eda y tu autenticidad\u00bb, \u00abFelicidades @lamaterialista1 eres una mujer muy hermosa y con mucho talento\u00bb, \u00abPara todos nosotros fuiste la ganadora. Viva Quisqueya la bella\u00bb, fueron parte de los comentarios en la cuenta de Instagram de @telemundorealities.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De las 21 celebridades que fueron seleccionadas para hospedarse en la pol\u00e9mica casa, solo cinco lograron conseguir el pase a la gran final. Los dem\u00e1s son Jos\u00e9 Rodr\u00edguez, Paty Navidad, Madison Anderson y Pepe G\u00e1mez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos los participantes que forman parte de \u201cLa Casa de los Famosos\u201d tienen un sueldo de aproximadamente 100,000 d\u00f3lares por su permanencia en el&nbsp;<strong>reality show<\/strong>, seg\u00fan revel\u00f3 la cantante Stephanie Valenzuela, quien particip\u00f3 en la edici\u00f3n de 2022.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, tambi\u00e9n hay un premio para el ganador, m\u00e1s all\u00e1 de la exposici\u00f3n medi\u00e1tica. El vencedor, que es escogido por el p\u00fablico mediante votos, se llevar\u00e1 200,000 d\u00f3lares.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Solo en una ocasi\u00f3n&nbsp;<strong>La Materialista<\/strong>&nbsp;fue nominada para salir de la \u00abCasa de los Famosos 3\u00bb, pero el voto popular lo impidi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cantante urbana&nbsp;La Materialista&nbsp;qued\u00f3 como cuarta finalista del&nbsp;reality show&nbsp;de Telemundo&nbsp;\u00abLa casa de los Famosos 3\u00bb, cuya gran final es este lunes 24 de abril en vivo. \u00abEstoy feliz por el apoyo del p\u00fablico, feliz por haberme permitido estar aqu\u00ed, un logro, una meta, un sue\u00f1o hecho realidad. Gracias Materialista Family\u00bb,&nbsp;expres\u00f3 la int\u00e9rprete de \u00abLas chapas que vibran\u00bb. Su prometido, Eury Matos, quien permaneci\u00f3 una semana en el\u00a0reality show, le llev\u00f3 un ramo de flores y le entreg\u00f3 la medalla de finalista. Se besaron y se abrazaron. Yameyry Josefina Ynfante Honoret, nombre de pila de la cantante, fue una de las favoritas. \u00abYami fuiste la m\u00e1s genuina, me encant\u00f3 tu alegr\u00eda y tu autenticidad\u00bb, \u00abFelicidades @lamaterialista1 eres una mujer muy hermosa y con mucho talento\u00bb, \u00abPara todos nosotros fuiste la ganadora. Viva Quisqueya la bella\u00bb, fueron parte de los comentarios en la cuenta de Instagram de @telemundorealities. De las 21 celebridades que fueron seleccionadas para hospedarse en la pol\u00e9mica casa, solo cinco lograron conseguir el pase a la gran final. Los dem\u00e1s son Jos\u00e9 Rodr\u00edguez, Paty Navidad, Madison Anderson y Pepe G\u00e1mez. Todos los participantes que forman parte de \u201cLa Casa de los Famosos\u201d tienen un sueldo de aproximadamente 100,000 d\u00f3lares por su permanencia en el&nbsp;reality show, seg\u00fan revel\u00f3 la cantante Stephanie Valenzuela, quien particip\u00f3 en la edici\u00f3n de 2022.&nbsp; Sin embargo, tambi\u00e9n hay un premio para el ganador, m\u00e1s all\u00e1 de la exposici\u00f3n medi\u00e1tica. El vencedor, que es escogido por el p\u00fablico mediante votos, se llevar\u00e1 200,000 d\u00f3lares.&nbsp; Solo en una ocasi\u00f3n&nbsp;La Materialista&nbsp;fue nominada para salir de la \u00abCasa de los Famosos 3\u00bb, pero el voto popular lo impidi\u00f3.<\/p>\n","protected":false},"author":9,"featured_media":90090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-90089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=90089"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90089\/revisions"}],"predecessor-version":[{"id":90091,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/90089\/revisions\/90091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/90090"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=90089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=90089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=90089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}